{"id":111254,"date":"2026-06-23T12:14:33","date_gmt":"2026-06-23T15:14:33","guid":{"rendered":"https:\/\/med.estrategia.com\/portal\/?p=111254"},"modified":"2026-06-23T12:19:40","modified_gmt":"2026-06-23T15:19:40","slug":"casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026","status":"publish","type":"post","link":"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/","title":{"rendered":"Casa de Sa\u00fade Santa Marcelina divulga edital com 13 vagas para resid\u00eancia m\u00e9dica 2026.2"},"content":{"rendered":"<p>A <strong>Casa de Sa&uacute;de Santa Marcelina<\/strong> publicou nesta ter&ccedil;a-feira (23) o edital do processo seletivo para<strong> ingresso em seus programas de resid&ecirc;ncia m&eacute;dica no segundo semestre de 2026<\/strong>. Ao todo, <strong>s&atilde;o ofertadas 13 vagas<\/strong> distribu&iacute;das entre especialidades de acesso direto e pr&eacute;-requisito. <p>Organizado pela Consesp, o processo seletivo ser&aacute; realizado em <strong>duas etapas: prova objetiva virtual e avalia&ccedil;&atilde;o curricular<\/strong>. A taxa de inscri&ccedil;&atilde;o &eacute; de <strong>R$ 500,00<\/strong> e as inscri&ccedil;&otilde;es estar&atilde;o abertas entre os dias 8 e 19 de julho de 2026. Confira abaixo as principais datas e o edital completo!<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_79_2 counter-hierarchy ez-toc-counter ez-toc-transparent ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Navegue pelo conte\u00fado<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#Principais-datas-e-Edital-Casa-de-Saude-Santa-Marcelina-20262\" >Principais datas e Edital Casa de Sa&uacute;de Santa Marcelina 2026.2<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#Inscreva-se-em-nossa-newsletter\" >Inscreva-se em nossa newsletter!<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#Vagas-ofertadas\" >Vagas ofertadas<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#Acesso-direto\" >Acesso direto<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#Pre-requisito\" >Pr&eacute;-requisito<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#Como-sera-o-processo-seletivo\" >Como ser&aacute; o processo seletivo?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#Calendario-de-Residencia-Medica-20262027\" >Calend&aacute;rio de Resid&ecirc;ncia M&eacute;dica 2026\/2027<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-principais-datas-e-edital-casa-de-saude-santa-marcelina-2026-2\"><span class=\"ez-toc-section\" id=\"Principais-datas-e-Edital-Casa-de-Saude-Santa-Marcelina-20262\"><\/span>Principais datas e Edital Casa de Sa&uacute;de Santa Marcelina 2026.2<span class=\"ez-toc-section-end\"><\/span><\/h2><figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Per&iacute;odo de Inscri&ccedil;&otilde;es<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">08 a 19\/07\/2026<\/td><\/tr><tr><td><strong>Per&iacute;odo do Pr&eacute;-Teste<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">27 e 28\/07\/2026<\/td><\/tr><tr><td><strong>Prova Objetiva (Virtual)<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">29\/07\/2026<\/td><\/tr><tr><td><strong>Convoca&ccedil;&atilde;o para An&aacute;lise Curricular<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">07\/08\/2026<\/td><\/tr><tr><td><strong>Resultado Final<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">19\/08\/2026<\/td><\/tr><\/tbody><\/table><\/figure><div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/cdn.medblog.estrategiaeducacional.com.br\/wp-content\/uploads\/2026\/06\/4899_sopaulosantamarcelinarm.pdf\" target=\"_blank\">confira aqui o edital e cronograma completo!<\/a><\/div>\n<\/div><p class=\"wp-block-verse has-text-align-center\">&#9888;&#65039;&nbsp;<strong>Aten&ccedil;&atilde;o:<\/strong>&nbsp;&Eacute; de inteira responsabilidade do candidato acompanhar a publica&ccedil;&atilde;o de todos os atos referentes a esta sele&ccedil;&atilde;o na&nbsp;<a href=\"https:\/\/sis.consesp.com.br\/site\/index.php?pg=concursos\/info&amp;codigo=4899\" target=\"_blank\">p&aacute;gina oficial da institui&ccedil;&atilde;o<\/a>.<\/p><p>\n\n\n<div id=\"new-form\">\n\t<form id=\"forms_layout\">\n\t<input type=\"hidden\" id=\"chave_de\" name=\"chave_de\" value=\"01_EMED_LEADS_TOTAIS\" \/>\n\t\t<input type=\"hidden\" id=\"mid\" name=\"mid\" value=\"515009018\" \/>\n\t\t<input type=\"hidden\" id=\"Objetivo\" name=\"Objetivo\" value=\"Medicina\" \/>\n\t\t<input type=\"hidden\" id=\"Estado_de_Origem_do_IP\" name=\"Estado_de_Origem_do_IP\"  value=\"\" \/>\n\t\t<input type=\"hidden\" id=\"Cidade_de_Origem_do_IP\" name=\"Cidade_de_Origem_do_IP\" value=\"\" \/>\n\t\t<input type=\"hidden\" id=\"Modo_de_entrada\" name=\"Modo_de_entrada\" value=\"Portal\" \/>\n\t\t<input type=\"hidden\" id=\"Pagina_Origem\" name=\"Pagina_Origem\" value=\"\" \/>\n\n\t\t<div class=\"texto\">\n\t\t\t<h3 class=\"news\"><span class=\"ez-toc-section\" id=\"Inscreva-se-em-nossa-newsletter\"><\/span>Inscreva-se em nossa newsletter!<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\t\t\t<p>Receba not\u00edcias sobre resid\u00eancia m\u00e9dica, revalida\u00e7\u00e3o de diplomas e concursos m\u00e9dicos, al\u00e9m de materiais de estudo gratuitos e informa\u00e7\u00f5es relevantes do mundo da Medicina.<\/p>\n\t\t<\/div>\n\t\t<div class=\"campos\">\n\t\t\t<div class=\"first_name labels\">\n\t\t\t\t<input type=\"text\" class=\"input_labels\" id=\"first_name\" name=\"Nome_Completo\" placeholder=\"Nome\" required \/>\n\t\t\t<\/div>\n\t\t\t<div class=\"email labels\">\n\t\t\t\t<input type=\"email\" class=\"input_labels\" id=\"email\" name=\"Email\" placeholder=\"E-mail\" required \/>\n\t\t\t<\/div>\n\t\t\t<button type=\"submit\" class=\"button_layout\">\n\t\t\t\t<div id=\"lblBotao\">Inscreva-se<\/div>\n\t\t\t\t<span id=\"divSpiner\" class=\"loader\" role=\"status\" style=\"display: none;\"><\/span>\t\n\t\t\t<\/button>\n\t\t<\/div><!-- \/campos -->\n\t\t\n\t\t<label class=\"container_checkbox\">Voc\u00ea concorda com a nossa\n\t\t\t<a class=\"politics_privacy_ahref\" target=\"_blank\" href=\"https:\/\/gratis.estrategiaconcursos.com.br\/politica-de-privacidade\/\">Pol\u00edtica de Privacidade<\/a> e aceita receber informa\u00e7\u00f5es adicionais do Estrat\u00e9gia Educacional.\n\t\t\t<input id=\"checkbox_layout\" type=\"checkbox\" checked=\"checked\" required \/>\n\t\t\t<span class=\"checkbox\"><\/span>\n\t\t<\/label>\n\t\t<div id=\"msg\"><\/div>\n\t\t<div id=\"error\" class=\"error\">\n\t\t<\/div>\n\t<\/form>\n<\/div><!-- \/new-form -->\n\n\n\n<\/p><h2 class=\"wp-block-heading\" id=\"h-vagas-ofertadas\"><span class=\"ez-toc-section\" id=\"Vagas-ofertadas\"><\/span>Vagas ofertadas<span class=\"ez-toc-section-end\"><\/span><\/h2><h3 class=\"wp-block-heading\" id=\"h-acesso-direto\"><span class=\"ez-toc-section\" id=\"Acesso-direto\"><\/span>Acesso direto<span class=\"ez-toc-section-end\"><\/span><\/h3><figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Especialidade<\/th><th class=\"has-text-align-center\" data-align=\"center\">Vagas<\/th><\/tr><\/thead><tbody><tr><td>Medicina Intensiva<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><\/tbody><\/table><\/figure><h3 class=\"wp-block-heading\" id=\"h-pre-requisito\"><span class=\"ez-toc-section\" id=\"Pre-requisito\"><\/span>Pr&eacute;-requisito<span class=\"ez-toc-section-end\"><\/span><\/h3><figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Especialidade<\/th><th class=\"has-text-align-center\" data-align=\"center\">Vagas<\/th><\/tr><\/thead><tbody><tr><td>Cardiologia*<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>Endocrinologia e Metabologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Hematologia e Hemoterapia<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Nefrologia*<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><\/tr><tr><td>Mastologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">*1 vaga reservada para candidatos Negros<\/figcaption><\/figure><h2 class=\"wp-block-heading\" id=\"h-como-sera-o-processo-seletivo\"><span class=\"ez-toc-section\" id=\"Como-sera-o-processo-seletivo\"><\/span>Como ser&aacute; o processo seletivo?<span class=\"ez-toc-section-end\"><\/span><\/h2><p>A sele&ccedil;&atilde;o ser&aacute; composta por duas fases:<\/p><ul class=\"wp-block-list\">\n<li><strong>1&ordf; fase &ndash; Prova objetiva virtual<\/strong>: de car&aacute;ter eliminat&oacute;rio e classificat&oacute;rio, a avalia&ccedil;&atilde;o ser&aacute; aplicada em formato virtual no dia 29 de julho de 2026, com in&iacute;cio &agrave;s 9h (hor&aacute;rio de Bras&iacute;lia). A prova ter&aacute; dura&ccedil;&atilde;o de tr&ecirc;s horas e ser&aacute; realizada por meio de plataforma online com monitoramento remoto.<\/li>\n\n\n\n<li><strong>2&ordf; fase &ndash; Avalia&ccedil;&atilde;o curricular<\/strong>: os candidatos habilitados na primeira etapa ter&atilde;o seus curr&iacute;culos analisados pela Comiss&atilde;o de Resid&ecirc;ncia M&eacute;dica (COREME) da institui&ccedil;&atilde;o. A documenta&ccedil;&atilde;o dever&aacute; ser enviada pelos Correios, via Sedex com Aviso de Recebimento (AR), para o endere&ccedil;o indicado em edital at&eacute; o &uacute;ltimo dia para pagamento da taxa de inscri&ccedil;&atilde;o.<\/li>\n<\/ul><h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Calendario-de-Residencia-Medica-20262027\"><\/span>Calend&aacute;rio de Resid&ecirc;ncia M&eacute;dica 2026\/2027<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Para garantir que voc&ecirc; n&atilde;o perca nenhum prazo importante, o Estrat&eacute;gia MED mant&eacute;m um guia constantemente atualizado com todas as datas de provas, inscri&ccedil;&otilde;es e status dos principais processos seletivos de Resid&ecirc;ncia M&eacute;dica de todo o Brasil. Fique um passo &agrave; frente na sua prepara&ccedil;&atilde;o e organize seus estudos de forma inteligente!<\/p><p><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/calendario-de-residencia-medica-confira-as-datas-das-proximas-provas\/\" target=\"_blank\">Acesse aqui o Calend&aacute;rio de Resid&ecirc;ncia M&eacute;dica 2026\/2027<\/a>&nbsp;completo e confira as pr&oacute;ximas oportunidades.<\/p><p>\n\n\n\n<a id=\"cta\" class=\"cta-imagem\" href=\"https:\/\/med.estrategia.com\/cursos\/\" target=\"blank\">\n                <img decoding=\"async\" width=\"100%\" src=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2025\/08\/estrategia_geral.jpg\" alt=\"\" title=\"estrategia_geral\">\n        <\/a>\n<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"A Casa de Sa&uacute;de Santa Marcelina publicou nesta ter&ccedil;a-feira (23) o edital do processo seletivo para ingresso em&hellip;\n","protected":false},"author":39,"featured_media":111253,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wl_entities_gutenberg":"","footnotes":""},"categories":[300],"tags":[],"wl_entity_type":[199],"class_list":{"0":"post-111254","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias","8":"wl_entity_type-article"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Casa de Sa\u00fade Santa Marcelina divulga edital com 13 vagas para resid\u00eancia m\u00e9dica 2026.2<\/title>\n<meta name=\"description\" content=\"Casa de Sa\u00fade Santa Marcelina publica edital da resid\u00eancia m\u00e9dica 2026.2 com 13 vagas. Inscri\u00e7\u00f5es ocorrem entre 8 e 19 de julho, confira!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa de Sa\u00fade Santa Marcelina divulga edital com 13 vagas para resid\u00eancia m\u00e9dica 2026.2\" \/>\n<meta property=\"og:description\" content=\"Casa de Sa\u00fade Santa Marcelina publica edital da resid\u00eancia m\u00e9dica 2026.2 com 13 vagas. Inscri\u00e7\u00f5es ocorrem entre 8 e 19 de julho, confira!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia MED\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/estrategiamed1\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-23T15:14:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-23T15:19:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2026\/06\/CAPA-SANTA-MARCELINA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ana Carolina Damasceno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@estrategiamed_\" \/>\n<meta name=\"twitter:site\" content=\"@estrategiamed_\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Carolina Damasceno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/\",\"url\":\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/\",\"name\":\"Casa de Sa\u00fade Santa Marcelina divulga edital com 13 vagas para resid\u00eancia m\u00e9dica 2026.2\",\"isPartOf\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2026\/06\/CAPA-SANTA-MARCELINA.jpg\",\"datePublished\":\"2026-06-23T15:14:33+00:00\",\"dateModified\":\"2026-06-23T15:19:40+00:00\",\"author\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/2f553adbb8e25fe39d145c5b2927f58c\"},\"description\":\"Casa de Sa\u00fade Santa Marcelina publica edital da resid\u00eancia m\u00e9dica 2026.2 com 13 vagas. Inscri\u00e7\u00f5es ocorrem entre 8 e 19 de julho, confira!\",\"breadcrumb\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#primaryimage\",\"url\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2026\/06\/CAPA-SANTA-MARCELINA.jpg\",\"contentUrl\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2026\/06\/CAPA-SANTA-MARCELINA.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/med.estrategia.com\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/med.estrategia.com\/portal\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Casa de Sa\u00fade Santa Marcelina divulga edital com 13 vagas para resid\u00eancia m\u00e9dica 2026.2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#website\",\"url\":\"https:\/\/med.estrategia.com\/portal\/\",\"name\":\"Estrat\u00e9gia MED\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/med.estrategia.com\/portal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/2f553adbb8e25fe39d145c5b2927f58c\",\"name\":\"Ana Carolina Damasceno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2026\/07\/Sem-titulo-150x150.png\",\"contentUrl\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2026\/07\/Sem-titulo-150x150.png\",\"caption\":\"Ana Carolina Damasceno\"},\"description\":\"Coordenadora de Jornalismo EMED. Comunicadora por natureza e forma\u00e7\u00e3o, que ama e perde a no\u00e7\u00e3o do tempo com m\u00fasica e s\u00e9rie.\",\"url\":\"https:\/\/med.estrategia.com\/portal\/author\/ana-carolina-damasceno\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Casa de Sa\u00fade Santa Marcelina divulga edital com 13 vagas para resid\u00eancia m\u00e9dica 2026.2","description":"Casa de Sa\u00fade Santa Marcelina publica edital da resid\u00eancia m\u00e9dica 2026.2 com 13 vagas. Inscri\u00e7\u00f5es ocorrem entre 8 e 19 de julho, confira!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/","og_locale":"pt_BR","og_type":"article","og_title":"Casa de Sa\u00fade Santa Marcelina divulga edital com 13 vagas para resid\u00eancia m\u00e9dica 2026.2","og_description":"Casa de Sa\u00fade Santa Marcelina publica edital da resid\u00eancia m\u00e9dica 2026.2 com 13 vagas. Inscri\u00e7\u00f5es ocorrem entre 8 e 19 de julho, confira!","og_url":"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/","og_site_name":"Estrat\u00e9gia MED","article_publisher":"https:\/\/www.facebook.com\/estrategiamed1","article_published_time":"2026-06-23T15:14:33+00:00","article_modified_time":"2026-06-23T15:19:40+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2026\/06\/CAPA-SANTA-MARCELINA.jpg","type":"image\/jpeg"}],"author":"Ana Carolina Damasceno","twitter_card":"summary_large_image","twitter_creator":"@estrategiamed_","twitter_site":"@estrategiamed_","twitter_misc":{"Escrito por":"Ana Carolina Damasceno","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/","url":"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/","name":"Casa de Sa\u00fade Santa Marcelina divulga edital com 13 vagas para resid\u00eancia m\u00e9dica 2026.2","isPartOf":{"@id":"https:\/\/med.estrategia.com\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#primaryimage"},"image":{"@id":"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2026\/06\/CAPA-SANTA-MARCELINA.jpg","datePublished":"2026-06-23T15:14:33+00:00","dateModified":"2026-06-23T15:19:40+00:00","author":{"@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/2f553adbb8e25fe39d145c5b2927f58c"},"description":"Casa de Sa\u00fade Santa Marcelina publica edital da resid\u00eancia m\u00e9dica 2026.2 com 13 vagas. Inscri\u00e7\u00f5es ocorrem entre 8 e 19 de julho, confira!","breadcrumb":{"@id":"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#primaryimage","url":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2026\/06\/CAPA-SANTA-MARCELINA.jpg","contentUrl":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2026\/06\/CAPA-SANTA-MARCELINA.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/med.estrategia.com\/portal\/noticias\/casa-saude-santa-marcelina-edital-residencia-medica-2-semestre-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/med.estrategia.com\/portal\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/med.estrategia.com\/portal\/noticias\/"},{"@type":"ListItem","position":3,"name":"Casa de Sa\u00fade Santa Marcelina divulga edital com 13 vagas para resid\u00eancia m\u00e9dica 2026.2"}]},{"@type":"WebSite","@id":"https:\/\/med.estrategia.com\/portal\/#website","url":"https:\/\/med.estrategia.com\/portal\/","name":"Estrat\u00e9gia MED","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/med.estrategia.com\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/2f553adbb8e25fe39d145c5b2927f58c","name":"Ana Carolina Damasceno","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/image\/","url":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2026\/07\/Sem-titulo-150x150.png","contentUrl":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2026\/07\/Sem-titulo-150x150.png","caption":"Ana Carolina Damasceno"},"description":"Coordenadora de Jornalismo EMED. Comunicadora por natureza e forma\u00e7\u00e3o, que ama e perde a no\u00e7\u00e3o do tempo com m\u00fasica e s\u00e9rie.","url":"https:\/\/med.estrategia.com\/portal\/author\/ana-carolina-damasceno\/"}]}},"_wl_alt_label":[],"wl:entity_url":"\/post\/casa-de-saude-santa-marcelina-divulga-edital-com-13-vagas-para-residencia-medica-em-2026-111254","_links":{"self":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/111254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/comments?post=111254"}],"version-history":[{"count":2,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/111254\/revisions"}],"predecessor-version":[{"id":111258,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/111254\/revisions\/111258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/media\/111253"}],"wp:attachment":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/media?parent=111254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/categories?post=111254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/tags?post=111254"},{"taxonomy":"wl_entity_type","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/wl_entity_type?post=111254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}