{"id":2547,"date":"2020-11-15T17:56:33","date_gmt":"2020-11-15T20:56:33","guid":{"rendered":"https:\/\/med.estrategiaeducacional.com.br\/blog\/?p=2547"},"modified":"2023-07-24T17:24:52","modified_gmt":"2023-07-24T20:24:52","slug":"jornada-nacional-para-residencia-medica","status":"publish","type":"post","link":"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/","title":{"rendered":"1\u00aa Jornada Nacional para a Resid\u00eancia M\u00e9dica: confira como foi o evento!"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Se voc&ecirc; est&aacute; procurando informa&ccedil;&otilde;es, defini&ccedil;&otilde;es e dados sobre a <a class=\"wl-entity-page-link\" title=\"resid&ecirc;ncia\" href=\"https:\/\/med.estrategia.com\/portal\/entidade\/residencia-medica\/\" data-id=\"\/entity\/residencia-medica;http:\/\/dbpedia.org\/resource\/Residency_(medicine);http:\/\/en.dbpedia.org\/resource\/Residency_(medicine);http:\/\/nl.dbpedia.org\/resource\/Arts-assistent;http:\/\/de.dbpedia.org\/resource\/&Auml;rztliche_Weiterbildung;http:\/\/fr.dbpedia.org\/resource\/R&eacute;sidence_(m&eacute;decine);http:\/\/lt.dbpedia.org\/resource\/Rezident&#363;ra_(studijos);http:\/\/pt.dbpedia.org\/resource\/Resid&ecirc;ncia_m&eacute;dica;http:\/\/ru.dbpedia.org\/resource\/&#1050;&#1083;&#1080;&#1085;&#1080;&#1095;&#1077;&#1089;&#1082;&#1072;&#1103;_&#1086;&#1088;&#1076;&#1080;&#1085;&#1072;&#1090;&#1091;&#1088;&#1072;;http:\/\/uk.dbpedia.org\/resource\/&#1054;&#1088;&#1076;&#1080;&#1085;&#1072;&#1090;&#1091;&#1088;&#1072;_&#1082;&#1083;&#1110;&#1085;&#1110;&#1095;&#1085;&#1072;;https:\/\/data.wordlift.io\/wl106637\/entity\/residencia-medica\">Resid&ecirc;ncia M&eacute;dica<\/a>, o <a class=\"wl-entity-page-link\" href=\"https:\/\/med.estrategia.com\/portal\/entidade\/estrategia-med-2\/\" data-id=\"\/entity\/estrategia-med-2;https:\/\/data.wordlift.io\/wl106637\/entity\/estrategia_med\">Estrat&eacute;gia MED<\/a> &eacute; o lugar para esclarecer todas essas quest&otilde;es!&nbsp;A &ldquo;1&ordf; Jornada Nacional para Resid&ecirc;ncia M&eacute;dica&rdquo; foi uma s&eacute;rie de eventos <strong>entre os dias 16 e 23 de novembro<\/strong> e que contaram com nove temas e atividades diferentes e in&eacute;ditas para se aprofundar sobre o universo da Resid&ecirc;ncia M&eacute;dica.&nbsp;<p class=\"wp-block-paragraph\">Todos os eventos foram transmitidos pelo<a href=\"https:\/\/www.youtube.com\/channel\/UCyNuIBnEwzsgA05XK1P6Dmw\" target=\"_blank\" rel=\"noopener noreferrer\"> canal oficial do Estrat&eacute;gia MED<\/a> no YouTube, exceto a aplica&ccedil;&atilde;o do simulado, e podem ser acessados a qualquer momento por aqueles que n&atilde;o conseguiram acompanhar ao vivo.&nbsp;<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-transparent ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Navegue pelo conte\u00fado<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#Slides-da-1a-Jornada-Nacional-para-a-Residencia-Medica\" >Slides da 1&ordf; Jornada Nacional para a Resid&ecirc;ncia M&eacute;dica<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#Como-conciliar-o-5o-ano-e-o-Estudo-para-a-Residencia-Medica\" >Como conciliar o 5&ordm; ano e o Estudo para a Resid&ecirc;ncia M&eacute;dica?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#Como-conciliar-o-ultimo-ano-de-internato-e-o-Estudo-para-a-Residencia-Medica\" >Como conciliar o &uacute;ltimo ano de internato e o Estudo para a Resid&ecirc;ncia M&eacute;dica?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#Como-e-a-Prova-Pratica\" >Como &eacute; a Prova Pr&aacute;tica?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#Como-e-a-Analise-Curricular-e-a-Entrevista\" >Como &eacute; a An&aacute;lise Curricular e a Entrevista?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#Fatores-a-considerar-na-escolha-da-Especialidade\" >Fatores a considerar na escolha da Especialidade<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#Revisao-de-Vespera-para-SURCE\" >Revis&atilde;o de V&eacute;spera para SURCE<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#Revisao-de-Vespera-para-AMRIGS\" >Revis&atilde;o de V&eacute;spera para AMRIGS<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#Correcao-de-prova-Ao-Vivo-%E2%80%93-AMRIGS\" >Corre&ccedil;&atilde;o de prova Ao Vivo &ndash; AMRIGS<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#1o-Simulado-Geral-do-EMED\" >1&ordm; Simulado Geral do EMED<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-slides-da-1&ordf;-jornada-nacional-para-a-residencia-medica\"><span class=\"ez-toc-section\" id=\"Slides-da-1a-Jornada-Nacional-para-a-Residencia-Medica\"><\/span>Slides da 1&ordf; Jornada Nacional para a Resid&ecirc;ncia M&eacute;dica<span class=\"ez-toc-section-end\"><\/span><\/h2><p class=\"wp-block-paragraph\">Abaixo, voc&ecirc; pode baixar os slides das apresenta&ccedil;&otilde;es dos professores! <\/p><div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-7d812b4c wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-light-green-cyan-to-vivid-green-cyan-gradient-background has-background wp-element-button\" href=\"https:\/\/cdn.medblog.estrategiaeducacional.com.br\/wp-content\/uploads\/2020\/11\/AMRIGS-2.zip\" style=\"border-radius:38px\" target=\"_blank\">Tudo sobre a AMRIGS<\/a><\/div>\n<\/div><div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-7d812b4c wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-light-green-cyan-to-vivid-green-cyan-gradient-background has-background wp-element-button\" href=\"https:\/\/cdn.medblog.estrategiaeducacional.com.br\/wp-content\/uploads\/2020\/11\/SURCE-2.zip\" style=\"border-radius:44px\" target=\"_blank\">Tudo sobre a SURCE<\/a><\/div>\n<\/div><div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"h-como-conciliar-o-5&ordm;-ano-e-o-estudo-para-a-residencia-medica\"><span class=\"ez-toc-section\" id=\"Como-conciliar-o-5o-ano-e-o-Estudo-para-a-Residencia-Medica\"><\/span>Como conciliar o 5&ordm; ano e o Estudo para a Resid&ecirc;ncia M&eacute;dica?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<\/div><\/div><p class=\"wp-block-paragraph\">Assuntos abordados no dia 16 de novembro, &agrave;s 20h:<\/p><ul class=\"wp-block-list\">\n<li>Dicas de m&eacute;dicos que j&aacute; passaram pela resid&ecirc;ncia e alguns estudantes quintanistas que ainda est&atilde;o passando por este processo;<\/li>\n\n\n\n<li>Experi&ecirc;ncias e viv&ecirc;ncias, desde o per&iacute;odo da faculdade at&eacute; a <a href=\"https:\/\/med.estrategia.com\/portal\/category\/residencia-medica\/programa-de-residencia-medica\/\" target=\"_blank\">prova de resid&ecirc;ncia m&eacute;dica<\/a> e aprova&ccedil;&atilde;o; e<\/li>\n\n\n\n<li>Estrat&eacute;gias para superar as dificuldades passadas pelos estudantes quintanistas de medicina, precisando focar na gradua&ccedil;&atilde;o e nos estudos para o processo seletivo da Resid&ecirc;ncia M&eacute;dica.&nbsp;<\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-como-conciliar-o-ultimo-ano-de-internato-e-o-estudo-para-a-residencia-medica\"><span class=\"ez-toc-section\" id=\"Como-conciliar-o-ultimo-ano-de-internato-e-o-Estudo-para-a-Residencia-Medica\"><\/span>Como conciliar o &uacute;ltimo ano de internato e o Estudo para a Resid&ecirc;ncia M&eacute;dica?<span class=\"ez-toc-section-end\"><\/span><\/h2><p class=\"wp-block-paragraph\">Talvez esse seja um dos per&iacute;odos mais dif&iacute;ceis para os estudantes de <a class=\"wl-entity-page-link\" href=\"https:\/\/med.estrategia.com\/portal\/entidade\/medicina\/\" data-id=\"\/entity\/medicina;http:\/\/dbpedia.org\/resource\/Medicine;http:\/\/pt.dbpedia.org\/resource\/Medicina;http:\/\/hr.dbpedia.org\/resource\/Medicina;http:\/\/hu.dbpedia.org\/resource\/Orvostudom&aacute;ny;http:\/\/id.dbpedia.org\/resource\/Kedokteran;http:\/\/is.dbpedia.org\/resource\/L&aelig;knisfr&aelig;&eth;i;http:\/\/it.dbpedia.org\/resource\/Medicina;http:\/\/ro.dbpedia.org\/resource\/Medicin&#259;;http:\/\/ru.dbpedia.org\/resource\/&#1052;&#1077;&#1076;&#1080;&#1094;&#1080;&#1085;&#1072;;http:\/\/be.dbpedia.org\/resource\/&#1052;&#1077;&#1076;&#1099;&#1094;&#1099;&#1085;&#1072;;http:\/\/bg.dbpedia.org\/resource\/&#1052;&#1077;&#1076;&#1080;&#1094;&#1080;&#1085;&#1072;;http:\/\/sk.dbpedia.org\/resource\/Medic&iacute;na;http:\/\/sl.dbpedia.org\/resource\/Medicina;http:\/\/ca.dbpedia.org\/resource\/Medicina;http:\/\/sq.dbpedia.org\/resource\/Mjek&euml;sia;http:\/\/sr.dbpedia.org\/resource\/&#1052;&#1077;&#1076;&#1080;&#1094;&#1080;&#1085;&#1072;;http:\/\/sv.dbpedia.org\/resource\/Medicinsk_vetenskap;http:\/\/cs.dbpedia.org\/resource\/L&eacute;ka&#345;stv&iacute;;http:\/\/da.dbpedia.org\/resource\/L&aelig;gevidenskab;http:\/\/tr.dbpedia.org\/resource\/T&#305;p;http:\/\/de.dbpedia.org\/resource\/Medizin;http:\/\/lt.dbpedia.org\/resource\/Medicina;http:\/\/lv.dbpedia.org\/resource\/Medic&#299;na;http:\/\/uk.dbpedia.org\/resource\/&#1052;&#1077;&#1076;&#1080;&#1094;&#1080;&#1085;&#1072;;http:\/\/en.dbpedia.org\/resource\/Medicine;http:\/\/es.dbpedia.org\/resource\/Medicina;http:\/\/et.dbpedia.org\/resource\/Meditsiin;http:\/\/nl.dbpedia.org\/resource\/Geneeskunde;http:\/\/no.dbpedia.org\/resource\/Medisin;http:\/\/fi.dbpedia.org\/resource\/L&auml;&auml;ketiede;http:\/\/fr.dbpedia.org\/resource\/M&eacute;decine;http:\/\/pl.dbpedia.org\/resource\/Medycyna;https:\/\/data.wordlift.io\/wl106637\/entity\/medicina\">medicina<\/a>, com tantas demandas como internatos, provas finais, Trabalho de Conclus&atilde;o de Curso (TCC), al&eacute;m de muito estudo e preparo para os processos seletivos de Resid&ecirc;ncia M&eacute;dica.&nbsp;<\/p><p class=\"wp-block-paragraph\">Outra grande dificuldade do aluno, para aqueles que ainda n&atilde;o se decidiram, &eacute; a escolha de qual especialidade <a class=\"wl-entity-page-link\" title=\"doutora\" href=\"https:\/\/med.estrategia.com\/portal\/entidade\/medicos__trashed\/\" data-id=\"\/entity\/medicos__trashed;http:\/\/dbpedia.org\/resource\/Physician;http:\/\/pt.dbpedia.org\/resource\/M&eacute;dico;http:\/\/hr.dbpedia.org\/resource\/Lije&#269;nik;http:\/\/hu.dbpedia.org\/resource\/Orvos;http:\/\/id.dbpedia.org\/resource\/Dokter;http:\/\/is.dbpedia.org\/resource\/L&aelig;knir;http:\/\/it.dbpedia.org\/resource\/Medico;http:\/\/ro.dbpedia.org\/resource\/Medic;http:\/\/ru.dbpedia.org\/resource\/&#1042;&#1088;&#1072;&#1095;;http:\/\/be.dbpedia.org\/resource\/&#1059;&#1088;&#1072;&#1095;;http:\/\/bg.dbpedia.org\/resource\/&#1051;&#1077;&#1082;&#1072;&#1088;;http:\/\/sk.dbpedia.org\/resource\/Lek&aacute;r;http:\/\/sl.dbpedia.org\/resource\/Zdravnik;http:\/\/ca.dbpedia.org\/resource\/Metge;http:\/\/sr.dbpedia.org\/resource\/&#1033;&#1077;&#1082;&#1072;&#1088;;http:\/\/sv.dbpedia.org\/resource\/L&auml;kare;http:\/\/cs.dbpedia.org\/resource\/L&eacute;ka&#345;;http:\/\/da.dbpedia.org\/resource\/L&aelig;ge;http:\/\/tr.dbpedia.org\/resource\/Doktor_(t&#305;p);http:\/\/de.dbpedia.org\/resource\/Arzt;http:\/\/lt.dbpedia.org\/resource\/Gydytojas;http:\/\/lv.dbpedia.org\/resource\/&#256;rsts;http:\/\/uk.dbpedia.org\/resource\/&#1051;&#1110;&#1082;&#1072;&#1088;;http:\/\/en.dbpedia.org\/resource\/Physician;http:\/\/es.dbpedia.org\/resource\/M&eacute;dico;http:\/\/et.dbpedia.org\/resource\/Arst;http:\/\/nl.dbpedia.org\/resource\/Arts;http:\/\/no.dbpedia.org\/resource\/Lege;http:\/\/fi.dbpedia.org\/resource\/L&auml;&auml;k&auml;ri;http:\/\/fr.dbpedia.org\/resource\/M&eacute;decin;http:\/\/pl.dbpedia.org\/resource\/Lekarz;https:\/\/data.wordlift.io\/wl106637\/entity\/medicos\">m&eacute;dica<\/a> ir&atilde;o seguir, tendo pouca instru&ccedil;&atilde;o sobre cada uma delas e qual a melhor maneira de conhec&ecirc;-las melhor.<\/p><p class=\"wp-block-paragraph\">&Eacute; por isso que o <strong>Estrat&eacute;gia MED<\/strong> trouxe esse tema, tratado por m&eacute;dicos diferentes que j&aacute; passaram por essa mesma experi&ecirc;ncia, bem como por estudantes que est&atilde;o vivenciando essas dificuldades. <\/p><p class=\"wp-block-paragraph\">Assim o aluno pode tirar suas d&uacute;vidas e adquirir mais instru&ccedil;&otilde;es para passar por este processo. O segundo dia do evento aconteceu no dia <strong>17 de novembro, &agrave;s 20h!<\/strong>&nbsp;<\/p><h2 class=\"wp-block-heading\" id=\"h-como-e-a-prova-pratica\"><span class=\"ez-toc-section\" id=\"Como-e-a-Prova-Pratica\"><\/span>Como &eacute; a Prova Pr&aacute;tica?<span class=\"ez-toc-section-end\"><\/span><\/h2><p class=\"wp-block-paragraph\">Eis que chega o momento de falar do tema que mais preocupa os estudantes para Resid&ecirc;ncia. Pode-se dizer que a Prova Pr&aacute;tica &eacute; o terror de muitos candidatos!<\/p><p class=\"wp-block-paragraph\">A prova pr&aacute;tica, uma das fases dos processos seletivos de Resid&ecirc;ncia M&eacute;dica, &eacute; obrigat&oacute;ria apenas para algumas institui&ccedil;&otilde;es, tendo que ser analisado nos <a href=\"https:\/\/med.estrategia.com\/portal\/category\/residencia-medica\/provas-e-editais\/\" target=\"_blank\">editais <\/a>quais processos seletivos cobram esta etapa. <\/p><p class=\"wp-block-paragraph\">Esse tipo de avalia&ccedil;&atilde;o ainda gera muita d&uacute;vida entre os estudantes, principalmente por ser uma etapa pouco divulgada e com poucos detalhes. Portanto, este evento trouxe convidados que podem <strong>falar com propriedade sobre esse tema<\/strong>, j&aacute; que passaram por tal experi&ecirc;ncia. O evento aconteceu <strong>dia 18 de novembro, &agrave;s 20h, no canal do YouTube do Estrat&eacute;gia MED<\/strong>.<\/p><h2 class=\"wp-block-heading\" id=\"h-como-e-a-analise-curricular-e-a-entrevista\"><span class=\"ez-toc-section\" id=\"Como-e-a-Analise-Curricular-e-a-Entrevista\"><\/span>Como &eacute; a An&aacute;lise Curricular e a Entrevista?<span class=\"ez-toc-section-end\"><\/span><\/h2><p class=\"wp-block-paragraph\">Tanto a <a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/analise-curricular\/entrevista\/\" target=\"_blank\"><strong>an&aacute;lise curricu<\/strong>l<strong>ar<\/strong> quanto <strong>a entrevista<\/strong><\/a><strong> <\/strong>s&atilde;o, naqueles processos seletivos que a incluem, importantes etapas para o ingresso na Resid&ecirc;ncia M&eacute;dica. <\/p><p class=\"wp-block-paragraph\">Para os processos que requerem a an&aacute;lise do curr&iacute;culo, os alunos devem prestar muita aten&ccedil;&atilde;o nos editais disponibilizados por cada institui&ccedil;&atilde;o, afinal, cada um dos <strong>crit&eacute;rios de avalia&ccedil;&atilde;o<\/strong> dessa fase &eacute; extremamente espec&iacute;fico, de acordo com a especialidade e hospital de escolha.<\/p><p class=\"wp-block-paragraph\">Os crit&eacute;rios variam de acordo com a institui&ccedil;&atilde;o, tendo alguns pontos em comuns para a grande maioria, como:<\/p><ul class=\"wp-block-list\">\n<li>Participa&ccedil;&atilde;o estudantil;<\/li>\n\n\n\n<li>Projetos de extens&atilde;o;<\/li>\n\n\n\n<li>L&iacute;ngua estrangeira; e<\/li>\n\n\n\n<li>Publica&ccedil;&atilde;o de artigos cient&iacute;ficos.<\/li>\n<\/ul><p class=\"wp-block-paragraph\">Se quiser saber mais esses crit&eacute;rios, confira nossa mat&eacute;ria <a href=\"https:\/\/med.estrategia.com\/portal\/aluno-de-medicina\/residencia-medica\/\" target=\"_blank\">Tudo sobre Resid&ecirc;ncia M&eacute;dica.<\/a><\/p><p class=\"wp-block-paragraph\">Outra fase temida pelos alunos &eacute; o processo de <strong>entrevista<\/strong>, pois n&atilde;o sabem ao certo o que &eacute; cobrado, como se preparar e o que enfrentar&atilde;o. Mas fique tranquilo, que o Estrat&eacute;gia MED te contar tudo sobre o assunto! <\/p><p class=\"wp-block-paragraph\">Aqui, os alunos podem encontram <strong>perguntas t&eacute;cnicas<\/strong>, <strong>sobre seu pr&oacute;prio curr&iacute;culo,<\/strong> e at&eacute; mesmo <strong>perguntas pessoais.<\/strong> Dessa forma, os avaliadores conseguem ver a rea&ccedil;&atilde;o de cada candidato e como ele se comporta.<\/p><p class=\"wp-block-paragraph\">O evento feito pelo Estrat&eacute;gia MED trouxe tudo isso e muito mais! Tratamos todos os detalhes de grandes m&eacute;dicos que vivenciaram este processo para te dar dicas &uacute;nicas. O evento aconteceu dia <strong>19 de novembro, &agrave;s 20h, no nosso canal do YouTube<\/strong>!<\/p><h2 class=\"wp-block-heading\" id=\"h-fatores-a-considerar-na-escolha-da-especialidade\"><span class=\"ez-toc-section\" id=\"Fatores-a-considerar-na-escolha-da-Especialidade\"><\/span>Fatores a considerar na escolha da Especialidade<span class=\"ez-toc-section-end\"><\/span><\/h2><p class=\"wp-block-paragraph\">A medicina &eacute; uma profiss&atilde;o muito ampla e, por isso, tem m&uacute;ltiplas especialidades a serem escolhidas. A <strong>especialidade de escolha pode ser uma decis&atilde;o tomada por impulso<\/strong>. Por isso, &eacute; importante analisar com calma quais os crit&eacute;rios cobrados em cada resid&ecirc;ncia e de cada especialidade para tomar esta decis&atilde;o.&nbsp;<\/p><p class=\"wp-block-paragraph\">O Estrat&eacute;gia MED trouxe esse tema, em que foram explorados todos os fatores a considerar e que influenciam na escolha do futuro residente. Tudo isso aconteceu dia <strong>20 de novembro, &agrave;s 20h, no YouTube do Estrat&eacute;gia MED.<\/strong><\/p><h2 class=\"wp-block-heading\" id=\"h-revisao-de-vespera-para-surce\"><span class=\"ez-toc-section\" id=\"Revisao-de-Vespera-para-SURCE\"><\/span>Revis&atilde;o de V&eacute;spera para SURCE<span class=\"ez-toc-section-end\"><\/span><\/h2><p class=\"wp-block-paragraph\">A prova de resid&ecirc;ncia m&eacute;dica da <a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/programa-de-residencia-medica\/surce-residencia-medica\/\" target=\"_blank\">SURCE<\/a> &eacute; uma das mais famosas e concorridas do pa&iacute;s. Mas, antes de falar dela, precisamos saber o que &eacute; a SURCE.<\/p><p class=\"wp-block-paragraph\">Essa sigla significa <strong>Sele&ccedil;&atilde;o Unificada para Resid&ecirc;ncia M&eacute;dica no Estado do Cear&aacute;<\/strong>, que agrupa um total de 13 institui&ccedil;&otilde;es. Ela foi fundada em 2011, tendo como objetivo profissionalizar, tornar mais objetivo, igualit&aacute;rio e de menor custo, o processo seletivo para a resid&ecirc;ncia no Estado. <\/p><p class=\"wp-block-paragraph\">Os processos seletivos da SURCE s&atilde;o gerenciados pela<strong> <\/strong>Universidade Federal do Cear&aacute;, mas toda sua constru&ccedil;&atilde;o &eacute; coletiva, com apoio da Escola de Sa&uacute;de P&uacute;blica do Estado do Cear&aacute;, Secretaria de Sa&uacute;de do Munic&iacute;pio de Fortaleza, entre outras institui&ccedil;&otilde;es como hospitais e faculdades.&nbsp;<\/p><p class=\"wp-block-paragraph\">Confira abaixo alguns dados importantes da <strong>prova que aconteceu dia 22 de novembro:<\/strong><\/p><ul class=\"wp-block-list\">\n<li>N&uacute;mero de quest&otilde;es da prova objetiva: 100;<\/li>\n\n\n\n<li>Quest&otilde;es com quatro alternativas (A, B, C e D);<\/li>\n\n\n\n<li>Hor&aacute;rio da prova objetiva: in&iacute;cio &agrave;s 9h, hor&aacute;rio de Bras&iacute;lia;<\/li>\n\n\n\n<li>Dura&ccedil;&atilde;o da prova objetiva: at&eacute; 4h;<\/li>\n\n\n\n<li>Local de aplica&ccedil;&atilde;o da prova: somente em Fortaleza;<\/li>\n\n\n\n<li>Divulga&ccedil;&atilde;o do caderno de prova e do gabarito preliminar: 22\/11\/2020; e<\/li>\n\n\n\n<li>Prazo para recursos: dias 23 e 24\/11\/2020.<\/li>\n<\/ul><p class=\"wp-block-paragraph\">O evento oconteceu no dia <strong>21 de novembro, &agrave;s 10h,<\/strong> no YouTube, e o Estrat&eacute;gia MED aprofundou todos os conte&uacute;dos importantes que ca&iacute;ram na prova.<\/p><h2 class=\"wp-block-heading\" id=\"h-revisao-de-vespera-para-amrigs\"><span class=\"ez-toc-section\" id=\"Revisao-de-Vespera-para-AMRIGS\"><\/span>Revis&atilde;o de V&eacute;spera para AMRIGS<span class=\"ez-toc-section-end\"><\/span><\/h2><p class=\"wp-block-paragraph\">Embora popularmente conhecida como prova da <a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/programa-de-residencia-medica\/prova-amrigs-tudo-sobre\/\" target=\"_blank\">AMRIGS<\/a>, em verdade esse processo seletivo unifica a Associa&ccedil;&atilde;o Brasileira de Medicina &ndash; AMB, a Associa&ccedil;&atilde;o M&eacute;dica do Rio Grande do Sul &ndash; AMRIGS, a Associa&ccedil;&atilde;o Catarinense de Medicina &ndash; ACM e a Associa&ccedil;&atilde;o M&eacute;dica de Mato Grosso do Sul &ndash; AMMS. <\/p><p class=\"wp-block-paragraph\">Trata-se de um prova tradicional, <strong>realizada h&aacute; mais de 40 anos <\/strong>e que unificada o processo para ingresso em Programas de Resid&ecirc;ncia M&eacute;dica de unidades afiliadas ou parceiras dessas institui&ccedil;&otilde;es.<\/p><p class=\"wp-block-paragraph\">A sele&ccedil;&atilde;o feita &eacute; constitu&iacute;da por uma prova para o acesso direto e outra para resid&ecirc;ncias com pr&eacute;-requisitos.<\/p><p class=\"wp-block-paragraph\">O Estrat&eacute;gia MED fez uma Revis&atilde;o de V&eacute;spera no dia <strong>21 de novembro, &agrave;s 10h<\/strong>, no nosso canal do YouTube.<\/p><p class=\"wp-block-paragraph\">Abaixo, confira as <strong>informa&ccedil;&otilde;es sobre a prova da AMRIGS:<\/strong><\/p><ul class=\"wp-block-list\">\n<li>N&uacute;mero de quest&otilde;es da prova objetiva: 100;<\/li>\n\n\n\n<li>Quest&otilde;es com quatro alternativas (A, B, C e D);<\/li>\n\n\n\n<li>Hor&aacute;rio da prova: in&iacute;cio &agrave;s 9h, hor&aacute;rio de Bras&iacute;lia;<\/li>\n\n\n\n<li>Dura&ccedil;&atilde;o da prova: at&eacute; 5h;<\/li>\n\n\n\n<li>Locais de aplica&ccedil;&atilde;o da prova: Campo Grande\/MS, Caxias do Sul\/RS, Chapec&oacute;\/SC, Crici&uacute;ma\/SC, Cuiab&aacute;\/MT, Florian&oacute;polis\/SC, Joinville\/SC, Lages\/SC, Passo Fundo\/RS, Pelotas\/RS, Porto Alegre\/RS, Porto Velho\/RO, Rio Grande\/RS e Santa Maria\/RS;<\/li>\n\n\n\n<li>Divulga&ccedil;&atilde;o do caderno de prova e do gabarito preliminar:&nbsp; 23\/11\/2020; e<\/li>\n\n\n\n<li>Prazo para recursos: dias 24 e 25\/11\/2020.<\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"h-correcao-de-prova-ao-vivo-amrigs\"><span class=\"ez-toc-section\" id=\"Correcao-de-prova-Ao-Vivo-%E2%80%93-AMRIGS\"><\/span>Corre&ccedil;&atilde;o de prova Ao Vivo &ndash; AMRIGS<span class=\"ez-toc-section-end\"><\/span><\/h2><p class=\"wp-block-paragraph\">Ap&oacute;s<strong> realizar a sua prova da AMRIGS<\/strong>, o Estrat&eacute;gia MED fez a corre&ccedil;&atilde;o da <a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/programa-de-residencia-medica\/exame-amrigs\/\" target=\"_blank\">prova da AMRIGS<\/a>. <\/p><p class=\"wp-block-paragraph\">Isso mesmo, n&oacute;s compreendemos a jornada dos alunos e estaremos firmes ao lado de voc&ecirc;s ao longo dela. Por isso, para ajudar nesse momento de ansiedade e conhecimento do desempenho na prova, resolvemos a <strong>prova Ao Vivo e fizemos o nosso gabarito preliminar<\/strong>. Caso haja quest&otilde;es pass&iacute;veis de recurso, o nosso time de professores auxilia com os fundamentos para a impugna&ccedil;&atilde;o.<\/p><p class=\"wp-block-paragraph\">Portanto, todo os candidatos puderam tirar as suas d&uacute;vidas e ter uma no&ccedil;&atilde;o de seus acertos e erros.<\/p><p class=\"wp-block-paragraph\">O evento come&ccedil;ou<strong> &agrave;s 15h, no dia 22 de novembro, no canal do YouTube do Estrat&eacute;gia MED!<\/strong>&nbsp;<\/p><h2 class=\"wp-block-heading\" id=\"h-1&ordm;-simulado-geral-do-emed\"><span class=\"ez-toc-section\" id=\"1o-Simulado-Geral-do-EMED\"><\/span>1&ordm; Simulado Geral do EMED<span class=\"ez-toc-section-end\"><\/span><\/h2><p class=\"wp-block-paragraph\">Para terminar essa semana de eventos da melhor maneira poss&iacute;vel, o Estrat&eacute;gia MED preparou um <a href=\"https:\/\/med.estrategia.com\/portal\/simulados\/simulado-geral-residencia-medica\/\" target=\"_blank\">simulado geral<\/a> para que os alunos treinem seus conhecimentos e vejam seu desempenho. Foram 50 quest&otilde;es in&eacute;ditas, criadas por nossos pr&oacute;prios professores, e 2 horas e 30 minutos para a realiza&ccedil;&atilde;o do simulado.<\/p><p class=\"wp-block-paragraph\">Al&eacute;m de ter essa oportunidade de treino, o Estrat&eacute;gia MED ainda distribuiu <strong>pr&ecirc;mios para os 10 primeiros colocados!<\/strong>&nbsp;<\/p><p class=\"wp-block-paragraph\">O primeiro colocado do Simulado EMED ganhou um <strong>iPhone 11<\/strong>, al&eacute;m de um ano de acesso gratuito ao BQMED &ndash; o <a href=\"https:\/\/med.estrategia.com\/portal\/evento-emed\/sistemas-de-questoes-estrategia-med\/\" target=\"_blank\">Banco de Quest&otilde;es do Estrat&eacute;gia MED<\/a>.&nbsp;<\/p><p class=\"wp-block-paragraph\">Os outros 9 classificados entre as 10 primeiras posi&ccedil;&otilde;es do ranking tamb&eacute;m ganharam <strong>1 ano de acesso ao BQMED<\/strong>.<\/p><p class=\"wp-block-paragraph\"><strong>Aten&ccedil;&atilde;o!<\/strong> S&oacute; concorreram aos pr&ecirc;mios aqueles que preencherem o gabarito durante o per&iacute;odo de aplica&ccedil;&atilde;o da prova!<\/p><p class=\"wp-block-paragraph\">Para ficar por dentro de tudo o que envolve esse evento, confira abaixo o cronograma:<\/p><ul class=\"wp-block-list\">\n<li><strong>Hor&aacute;rio de aplica&ccedil;&atilde;o:<\/strong> das 19h &agrave;s 21:30h;<\/li>\n\n\n\n<li><strong>T&eacute;rmino do preenchimento do gabarito:<\/strong> 21:30h;<\/li>\n\n\n\n<li><strong>Libera&ccedil;&atilde;o do gabarito:<\/strong> a partir das 22h;<\/li>\n\n\n\n<li><strong>Libera&ccedil;&atilde;o do ranking:<\/strong> a partir das 22h;<\/li>\n\n\n\n<li><strong>Libera&ccedil;&atilde;o da corre&ccedil;&atilde;o em PDF:<\/strong> at&eacute; ter&ccedil;a-feira, dia 24\/11\/2020; e&nbsp;<\/li>\n\n\n\n<li><strong>Libera&ccedil;&atilde;o da premia&ccedil;&atilde;o:<\/strong> at&eacute; 30\/11.&nbsp;<\/li>\n<\/ul><p class=\"wp-block-paragraph\">O Simulado aconteceu no dia <strong>23 de novembro, &agrave;s 19h!<\/strong><\/p><p class=\"wp-block-paragraph\"><\/p><p class=\"wp-block-paragraph\"><strong><a id=\"cta\" class=\"cta-imagem\" href=\"https:\/\/med.estrategia.com\/cursos\/extensivo-de-residncia-mdica\/\" target=\"blank\">\n                <img decoding=\"async\" width=\"100%\" src=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2025\/08\/extensivo_rm.jpg\" alt=\"Extensivo RM\" title=\"extensivo_rm\">\n        <\/a><\/strong><\/p><p class=\"has-text-align-center wp-block-paragraph\"><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"Se voc&ecirc; est&aacute; procurando informa&ccedil;&otilde;es, defini&ccedil;&otilde;es e dados sobre a Resid&ecirc;ncia M&eacute;dica, o Estrat&eacute;gia MED &eacute; o lugar&hellip;\n","protected":false},"author":29,"featured_media":2614,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wl_entities_gutenberg":"","footnotes":""},"categories":[35],"tags":[],"wl_entity_type":[199],"class_list":["post-2547","post","type-post","status-publish","format-standard","has-post-thumbnail","category-eventos","wl_entity_type-article"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>1\u00aa Jornada Nacional para a Resid\u00eancia M\u00e9dica: tudo sobre o evento!<\/title>\n<meta name=\"description\" content=\"A 1\u00aa Jornada Nacional para a Resid\u00eancia M\u00e9dica \u00e9 o evento do exclusivo Estrat\u00e9gia MED para suas provas de RM! Veja a programa\u00e7\u00e3o:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1\u00aa Jornada Nacional para a Resid\u00eancia M\u00e9dica: confira como foi o evento!\" \/>\n<meta property=\"og:description\" content=\"A 1\u00aa Jornada Nacional para a Resid\u00eancia M\u00e9dica \u00e9 o evento do exclusivo Estrat\u00e9gia MED para suas provas de RM! Veja a programa\u00e7\u00e3o:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia MED\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/estrategiamed1\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-15T20:56:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-24T20:24:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/national-cancer-institute-L8tWZT4CcVQ-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o - Estrat\u00e9gia MED\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@estrategiamed_\" \/>\n<meta name=\"twitter:site\" content=\"@estrategiamed_\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o - Estrat\u00e9gia MED\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/\",\"url\":\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/\",\"name\":\"1\u00aa Jornada Nacional para a Resid\u00eancia M\u00e9dica: tudo sobre o evento!\",\"isPartOf\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/national-cancer-institute-L8tWZT4CcVQ-unsplash-scaled.jpg\",\"datePublished\":\"2020-11-15T20:56:33+00:00\",\"dateModified\":\"2023-07-24T20:24:52+00:00\",\"author\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/08697bdf5b568f54e7cb36a85b30bfb3\"},\"description\":\"A 1\u00aa Jornada Nacional para a Resid\u00eancia M\u00e9dica \u00e9 o evento do exclusivo Estrat\u00e9gia MED para suas provas de RM! Veja a programa\u00e7\u00e3o:\",\"breadcrumb\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#primaryimage\",\"url\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/national-cancer-institute-L8tWZT4CcVQ-unsplash-scaled.jpg\",\"contentUrl\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/national-cancer-institute-L8tWZT4CcVQ-unsplash-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"1\u00aa Jornada Nacional para Resid\u00eancia M\u00e9dica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/med.estrategia.com\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\/\/med.estrategia.com\/portal\/eventos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1\u00aa Jornada Nacional para a Resid\u00eancia M\u00e9dica: confira como foi o evento!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#website\",\"url\":\"https:\/\/med.estrategia.com\/portal\/\",\"name\":\"Estrat\u00e9gia MED\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/med.estrategia.com\/portal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/08697bdf5b568f54e7cb36a85b30bfb3\",\"name\":\"Reda\u00e7\u00e3o - Estrat\u00e9gia MED\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-05-at-22.32.07-1-150x150.webp\",\"contentUrl\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-05-at-22.32.07-1-150x150.webp\",\"caption\":\"Reda\u00e7\u00e3o - Estrat\u00e9gia MED\"},\"url\":\"https:\/\/med.estrategia.com\/portal\/author\/redacaoemed\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"1\u00aa Jornada Nacional para a Resid\u00eancia M\u00e9dica: tudo sobre o evento!","description":"A 1\u00aa Jornada Nacional para a Resid\u00eancia M\u00e9dica \u00e9 o evento do exclusivo Estrat\u00e9gia MED para suas provas de RM! Veja a programa\u00e7\u00e3o:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/","og_locale":"pt_BR","og_type":"article","og_title":"1\u00aa Jornada Nacional para a Resid\u00eancia M\u00e9dica: confira como foi o evento!","og_description":"A 1\u00aa Jornada Nacional para a Resid\u00eancia M\u00e9dica \u00e9 o evento do exclusivo Estrat\u00e9gia MED para suas provas de RM! Veja a programa\u00e7\u00e3o:","og_url":"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/","og_site_name":"Estrat\u00e9gia MED","article_publisher":"https:\/\/www.facebook.com\/estrategiamed1","article_published_time":"2020-11-15T20:56:33+00:00","article_modified_time":"2023-07-24T20:24:52+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/national-cancer-institute-L8tWZT4CcVQ-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o - Estrat\u00e9gia MED","twitter_card":"summary_large_image","twitter_creator":"@estrategiamed_","twitter_site":"@estrategiamed_","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o - Estrat\u00e9gia MED","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/","url":"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/","name":"1\u00aa Jornada Nacional para a Resid\u00eancia M\u00e9dica: tudo sobre o evento!","isPartOf":{"@id":"https:\/\/med.estrategia.com\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#primaryimage"},"image":{"@id":"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#primaryimage"},"thumbnailUrl":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/national-cancer-institute-L8tWZT4CcVQ-unsplash-scaled.jpg","datePublished":"2020-11-15T20:56:33+00:00","dateModified":"2023-07-24T20:24:52+00:00","author":{"@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/08697bdf5b568f54e7cb36a85b30bfb3"},"description":"A 1\u00aa Jornada Nacional para a Resid\u00eancia M\u00e9dica \u00e9 o evento do exclusivo Estrat\u00e9gia MED para suas provas de RM! Veja a programa\u00e7\u00e3o:","breadcrumb":{"@id":"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#primaryimage","url":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/national-cancer-institute-L8tWZT4CcVQ-unsplash-scaled.jpg","contentUrl":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/national-cancer-institute-L8tWZT4CcVQ-unsplash-scaled.jpg","width":2560,"height":1707,"caption":"1\u00aa Jornada Nacional para Resid\u00eancia M\u00e9dica"},{"@type":"BreadcrumbList","@id":"https:\/\/med.estrategia.com\/portal\/eventos\/jornada-nacional-para-residencia-medica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/med.estrategia.com\/portal\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/med.estrategia.com\/portal\/eventos\/"},{"@type":"ListItem","position":3,"name":"1\u00aa Jornada Nacional para a Resid\u00eancia M\u00e9dica: confira como foi o evento!"}]},{"@type":"WebSite","@id":"https:\/\/med.estrategia.com\/portal\/#website","url":"https:\/\/med.estrategia.com\/portal\/","name":"Estrat\u00e9gia MED","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/med.estrategia.com\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/08697bdf5b568f54e7cb36a85b30bfb3","name":"Reda\u00e7\u00e3o - Estrat\u00e9gia MED","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/image\/","url":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-05-at-22.32.07-1-150x150.webp","contentUrl":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-05-at-22.32.07-1-150x150.webp","caption":"Reda\u00e7\u00e3o - Estrat\u00e9gia MED"},"url":"https:\/\/med.estrategia.com\/portal\/author\/redacaoemed\/"}]}},"_wl_alt_label":[],"wl:entity_url":"\/post\/jornada-nacional-para-residencia-medica","_links":{"self":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/2547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/comments?post=2547"}],"version-history":[{"count":14,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/2547\/revisions"}],"predecessor-version":[{"id":43310,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/2547\/revisions\/43310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/media\/2614"}],"wp:attachment":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/media?parent=2547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/categories?post=2547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/tags?post=2547"},{"taxonomy":"wl_entity_type","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/wl_entity_type?post=2547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}