{"id":26166,"date":"2022-10-19T15:13:26","date_gmt":"2022-10-19T18:13:26","guid":{"rendered":"https:\/\/med.estrategia.com\/portal\/?p=26166"},"modified":"2022-10-28T09:28:05","modified_gmt":"2022-10-28T12:28:05","slug":"residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais","status":"publish","type":"post","link":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/","title":{"rendered":"Resid\u00eancia M\u00e9dica PSU-MG 2022: tudo sobre a \u00faltima edi\u00e7\u00e3o!"},"content":{"rendered":"<p>Tem interesse na prova do para <a class=\"wl-entity-page-link\" title=\"Resid&ecirc;ncia M&eacute;dica ou Re\" href=\"https:\/\/med.estrategia.com\/portal\/entidade\/residencia-medica\/\" data-id=\"\/entity\/residencia-medica;http:\/\/dbpedia.org\/resource\/Residency_(medicine);http:\/\/en.dbpedia.org\/resource\/Residency_(medicine);http:\/\/nl.dbpedia.org\/resource\/Arts-assistent;http:\/\/de.dbpedia.org\/resource\/&Auml;rztliche_Weiterbildung;http:\/\/fr.dbpedia.org\/resource\/R&eacute;sidence_(m&eacute;decine);http:\/\/lt.dbpedia.org\/resource\/Rezident&#363;ra_(studijos);http:\/\/pt.dbpedia.org\/resource\/Resid&ecirc;ncia_m&eacute;dica;http:\/\/ru.dbpedia.org\/resource\/&#1050;&#1083;&#1080;&#1085;&#1080;&#1095;&#1077;&#1089;&#1082;&#1072;&#1103;_&#1086;&#1088;&#1076;&#1080;&#1085;&#1072;&#1090;&#1091;&#1088;&#1072;;http:\/\/uk.dbpedia.org\/resource\/&#1054;&#1088;&#1076;&#1080;&#1085;&#1072;&#1090;&#1091;&#1088;&#1072;_&#1082;&#1083;&#1110;&#1085;&#1110;&#1095;&#1085;&#1072;;https:\/\/data.wordlift.io\/wl106637\/entity\/residencia-medica\">Resid&ecirc;ncia M&eacute;dica<\/a> do PSU-MG e quer conferir como foi a &uacute;ltima edi&ccedil;&atilde;o? Ent&atilde;o, n&atilde;o perca as informa&ccedil;&otilde;es que o <a class=\"wl-entity-page-link\" href=\"https:\/\/med.estrategia.com\/portal\/entidade\/estrategia-med-2\/\" data-id=\"\/entity\/estrategia-med-2;https:\/\/data.wordlift.io\/wl106637\/entity\/estrategia_med\">Estrat&eacute;gia MED<\/a> trouxe nesse post!<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_79_2 counter-hierarchy ez-toc-counter ez-toc-transparent ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Navegue pelo conte\u00fado<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#O-que-e-PSU-MG\" >O que &eacute; PSU-MG?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#Edital-PSU-MG-2022\" >Edital PSU-MG 2022<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#Cronograma-PSU-MG-2022\" >Cronograma PSU-MG 2022<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#Vagas-PSU-MG-2022\" >Vagas PSU-MG 2022<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#Instituicoes-Participantes-do-PSU-MG-2022\" >Institui&ccedil;&otilde;es Participantes do PSU-MG 2022<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#Inscricoes-PSU-MG-2022\" >Inscri&ccedil;&otilde;es PSU-MG 2022<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#Relacao-candidatovaga-PSU-MG-2022\" >Rela&ccedil;&atilde;o candidato\/vaga PSU-MG 2022<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#Processo-Seletivo-PSU-MG-2022\" >Processo Seletivo PSU-MG 2022<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#Resultado-Final-e-Desempate\" >Resultado Final e Desempate<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#PSU-MG-2022-Complementar\" >PSU-MG 2022 Complementar<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#Veja-tambem\" >Veja tamb&eacute;m:<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-o-que-e-psu-mg\"><span class=\"ez-toc-section\" id=\"O-que-e-PSU-MG\"><\/span><strong>O que &eacute; PSU-MG?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2><p>O Processo Seletivo Unificado de Minas Gerais (PSU-MG) &eacute; o maior processo seletivo de resid&ecirc;ncia m&eacute;dica do Estado. Com cerca de 80 institui&ccedil;&otilde;es participando do processo, incluindo Universidades Federais e mais de mil vagas ofertadas, &eacute; tamb&eacute;m um dos maiores processos seletivos do Brasil. <\/p><p>O PSU-MG &eacute; <strong>promovido pela<\/strong><a href=\"http:\/\/www.aremg.org.br\/\" target=\"_blank\"><strong> AREMG<\/strong><\/a><strong>, a Associa&ccedil;&atilde;o de Apoio &agrave; Resid&ecirc;ncia M&eacute;dica de Minas Gerais<\/strong>. &Eacute; ela que realiza o processo seletivo unificado, d&aacute; apoio a novas institui&ccedil;&otilde;es que queiram se credenciar e tamb&eacute;m ajuda aquelas que j&aacute; s&atilde;o credenciadas.<\/p><p><\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/psu-mgg.jpg\" alt=\"PSU-MG\" class=\"wp-image-8938\" width=\"-743\" height=\"-495\" srcset=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/psu-mgg.jpg 750w, https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/psu-mgg-300x200.png 300w, https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/psu-mgg-380x253.png 380w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><figcaption>Universidade Federal do Tri&acirc;ngulo Mineiro (UFTM), uma das institui&ccedil;&otilde;es participantes do PSU-MG. Foto: <a href=\"http:\/\/www.uftm.edu.br\/institucional\/conheca-a-uftm\" target=\"_blank\">Divulga&ccedil;&atilde;o UFTM<\/a><\/figcaption><\/figure><\/div><p><\/p><p>\n\n\n<div id=\"new-form\">\n\t<form id=\"forms_layout\">\n\t<input type=\"hidden\" id=\"chave_de\" name=\"chave_de\" value=\"01_EMED_LEADS_TOTAIS\" \/>\n\t\t<input type=\"hidden\" id=\"mid\" name=\"mid\" value=\"515009018\" \/>\n\t\t<input type=\"hidden\" id=\"Objetivo\" name=\"Objetivo\" value=\"Medicina\" \/>\n\t\t<input type=\"hidden\" id=\"Estado_de_Origem_do_IP\" name=\"Estado_de_Origem_do_IP\"  value=\"\" \/>\n\t\t<input type=\"hidden\" id=\"Cidade_de_Origem_do_IP\" name=\"Cidade_de_Origem_do_IP\" value=\"\" \/>\n\t\t<input type=\"hidden\" id=\"Modo_de_entrada\" name=\"Modo_de_entrada\" value=\"Portal\" \/>\n\t\t<input type=\"hidden\" id=\"Pagina_Origem\" name=\"Pagina_Origem\" value=\"\" \/>\n\n\t\t<div class=\"texto\">\n\t\t\t<h3 class=\"news\">Inscreva-se em nossa newsletter!<\/h3>\n\t\t\t<p>Receba not\u00edcias sobre resid\u00eancia m\u00e9dica, revalida\u00e7\u00e3o de diplomas e concursos m\u00e9dicos, al\u00e9m de materiais de estudo gratuitos e informa\u00e7\u00f5es relevantes do mundo da Medicina.<\/p>\n\t\t<\/div>\n\t\t<div class=\"campos\">\n\t\t\t<div class=\"first_name labels\">\n\t\t\t\t<input type=\"text\" class=\"input_labels\" id=\"first_name\" name=\"Nome_Completo\" placeholder=\"Nome\" required \/>\n\t\t\t<\/div>\n\t\t\t<div class=\"email labels\">\n\t\t\t\t<input type=\"email\" class=\"input_labels\" id=\"email\" name=\"Email\" placeholder=\"E-mail\" required \/>\n\t\t\t<\/div>\n\t\t\t<button type=\"submit\" class=\"button_layout\">\n\t\t\t\t<div id=\"lblBotao\">Inscreva-se<\/div>\n\t\t\t\t<span id=\"divSpiner\" class=\"loader\" role=\"status\" style=\"display: none;\"><\/span>\t\n\t\t\t<\/button>\n\t\t<\/div><!-- \/campos -->\n\t\t\n\t\t<label class=\"container_checkbox\">Voc\u00ea concorda com a nossa\n\t\t\t<a class=\"politics_privacy_ahref\" target=\"_blank\" href=\"https:\/\/gratis.estrategiaconcursos.com.br\/politica-de-privacidade\/\">Pol\u00edtica de Privacidade<\/a> e aceita receber informa\u00e7\u00f5es adicionais do Estrat\u00e9gia Educacional.\n\t\t\t<input id=\"checkbox_layout\" type=\"checkbox\" checked=\"checked\" required \/>\n\t\t\t<span class=\"checkbox\"><\/span>\n\t\t<\/label>\n\t\t<div id=\"msg\"><\/div>\n\t\t<div id=\"error\" class=\"error\">\n\t\t<\/div>\n\t<\/form>\n<\/div><!-- \/new-form -->\n\n\n\n<\/p><h2 class=\"wp-block-heading\" id=\"h-edital-psu-mg-2022\"><span class=\"ez-toc-section\" id=\"Edital-PSU-MG-2022\"><\/span><strong>Edital PSU-MG 2022<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2><p>No dia 17 de setembro, a AREMG divulgou os editais do PSU-MG 2022, que ocorreu ao final do ano de 2021 para ingresso em mar&ccedil;o de 2022. Baixe o edital completo no bot&atilde;o abaixo:&nbsp;<\/p><p><\/p><div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-light-green-cyan-to-vivid-green-cyan-gradient-background has-background\" href=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/09\/ApresentacaoPSU2022-20210927105652.pdf\" target=\"_blank\"><strong>Edital PSU-MG 2022<\/strong><\/a><\/div>\n<\/div><p>Voc&ecirc; tamb&eacute;m pode acessar a <strong>lista completa de editais no <a href=\"http:\/\/www.aremg.org.br\/processos-atuais\" target=\"_blank\" rel=\"noopener noreferrer\">site da AREMG<\/a><\/strong>!<\/p><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"cs-embed cs-embed-responsive\"><iframe title=\"Saiu Edital PSU-MG 2022: Saiba tudo! - CorujaMED News - Resid&ecirc;ncia M&eacute;dica\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/c4n00WPdq74?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure><h2 class=\"wp-block-heading\" id=\"h-cronograma-psu-mg-2022\"><span class=\"ez-toc-section\" id=\"Cronograma-PSU-MG-2022\"><\/span>Cronograma PSU-MG 2022<span class=\"ez-toc-section-end\"><\/span><\/h2><ul class=\"wp-block-list\"><li><strong>Per&iacute;odo de inscri&ccedil;&otilde;es:<\/strong> 05\/10 a 20\/10\/2021;<\/li><li><strong>Taxa de inscri&ccedil;&atilde;o: <\/strong>R$ 180,00;<\/li><li><strong>Per&iacute;odo de isen&ccedil;&atilde;o: <\/strong>28\/09\/2021 a 30\/09\/2021;<\/li><li><strong>Envio de Documentos do Curr&iacute;culo:&nbsp; <\/strong>05\/10\/2021 a 20\/10\/2021;<\/li><li><strong>Comprovante de Inscri&ccedil;&atilde;o: <\/strong>03\/11\/2021 a 10\/11\/2021;<\/li><li><strong>Prova escrita: <\/strong>05\/12\/2021;<\/li><li><strong>Divulga&ccedil;&atilde;o do gabarito:<\/strong> 05\/12\/2021;<\/li><li><strong>Divulga&ccedil;&atilde;o do resultado da prova: <\/strong>22\/12\/2021 (previs&atilde;o);<\/li><li><strong>Resultado da Avalia&ccedil;&atilde;o curricular: <\/strong>19\/01\/2022 (previs&atilde;o);<\/li><li><strong>Resultado final e convoca&ccedil;&atilde;o: <\/strong>27\/01\/2022 (previs&atilde;o);<\/li><li><strong>Matr&iacute;culas: <\/strong>28\/01\/2022 a 02\/02\/2022; e<\/li><li><strong>In&iacute;cio dos Programas de Resid&ecirc;ncia:<\/strong> 01\/03\/2022.<\/li><\/ul><h2 class=\"wp-block-heading\" id=\"h-vagas-psu-mg-2022\"><span class=\"ez-toc-section\" id=\"Vagas-PSU-MG-2022\"><\/span>Vagas PSU-MG 2022<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Para o processo seletivo de 2022, a PSU-MG ofereceu <strong><strong>mais de 1.300<\/strong> vagas<\/strong> entre as especialidades de Acesso Direto, com Pr&eacute;-Requisito e &Aacute;rea de Atua&ccedil;&atilde;o. Confira, abaixo, a quantidade de vagas das institui&ccedil;&otilde;es que foram liberadas!<\/p><h3 class=\"wp-block-heading\" id=\"h-vagas-por-instituicao\">Vagas por institui&ccedil;&atilde;o<\/h3><figure class=\"wp-block-table is-style-stripes\"><table class=\"has-light-green-cyan-to-vivid-green-cyan-gradient-background has-background has-fixed-layout\"><thead><tr><th>Institui&ccedil;&otilde;es<\/th><th class=\"has-text-align-center\" data-align=\"center\">Vagas<\/th><\/tr><\/thead><tbody><tr><td>1. Associa&ccedil;&atilde;o Beneficente Cat&oacute;lica \/ Hospital Santa Isabel &ndash; Ub&aacute;<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><\/tr><tr><td>2. Associa&ccedil;&atilde;o de Combate ao C&acirc;ncer do Brasil Hospital H&eacute;lio Angotti<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>3. Associa&ccedil;&atilde;o Hospitalar Santa Ros&aacute;lia<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><\/tr><tr><td>4. Casa de Caridade de Alfenas Nossa Senhora do Perp&eacute;tuo Socorro<\/td><td class=\"has-text-align-center\" data-align=\"center\">15<\/td><\/tr><tr><td>5. Casa de Caridade de Carangola<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><\/tr><tr><td>6. Casa de Caridade de Muria&eacute; &ndash; Hospital S&atilde;o Paulo<\/td><td class=\"has-text-align-center\" data-align=\"center\">8<\/td><\/tr><tr><td>7. Complexo de Sa&uacute;de S&atilde;o Jo&atilde;o de Deus<\/td><td class=\"has-text-align-center\" data-align=\"center\">27<\/td><\/tr><tr><td>8. Faculdade de Medicina da Universidade Federal de Uberl&acirc;ndia<\/td><td class=\"has-text-align-center\" data-align=\"center\">117<\/td><\/tr><tr><td>9. Funda&ccedil;&atilde;o Benjamin Guimar&atilde;es Hospital da Baleia<\/td><td class=\"has-text-align-center\" data-align=\"center\">15<\/td><\/tr><tr><td>10. Funda&ccedil;&atilde;o Cristiano Varella &ndash; Hospital do C&acirc;ncer de Muria&eacute;<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><\/tr><tr><td>11. Funda&ccedil;&atilde;o Hospitalar S&atilde;o Francisco de Assis<\/td><td class=\"has-text-align-center\" data-align=\"center\">9<\/td><\/tr><tr><td>12. Funda&ccedil;&atilde;o Instituto Clinico Juiz de Fora<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><\/tr><tr><td>13. Funda&ccedil;&atilde;o Jose Bonif&aacute;cio Lafayette de Andrada &ndash; Faculdade de Medicina de Barbacena<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>14. Funda&ccedil;&atilde;o S&atilde;o Francisco Xavier\/ Hospital Municipal Carlos Chagas<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>15. Fundo Municipal de Sa&uacute;de de Manhua&ccedil;u<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>16. Hospital Arnaldo Gavazza &ndash; Ponte Nova<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><\/tr><tr><td>17. Hospital Aroldo Tourinho &ndash; Montes Claros<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><\/tr><tr><td>18. Hospital Belo Horizonte<\/td><td class=\"has-text-align-center\" data-align=\"center\">10<\/td><\/tr><tr><td>19. Hospital Bom Samaritano &ndash; Governador Valadares<\/td><td class=\"has-text-align-center\" data-align=\"center\">8<\/td><\/tr><tr><td>20. Hospital Cesar Leite &ndash; Manhua&ccedil;u<\/td><td class=\"has-text-align-center\" data-align=\"center\">10<\/td><\/tr><tr><td>21. Hospital das Cl&iacute;nicas Samuel Lib&acirc;nio &ndash; Pouso Alegre<\/td><td class=\"has-text-align-center\" data-align=\"center\">47<\/td><\/tr><tr><td>22. Hospital Deraldo Guimar&atilde;es &ndash; Almenara<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>23. Hospital de Cl&iacute;nicas de Itajub&aacute; da Associa&ccedil;&atilde;o de Integra&ccedil;&atilde;o Social de Itajub&aacute;<\/td><td class=\"has-text-align-center\" data-align=\"center\">18<\/td><\/tr><tr><td>24. Hospital de Olhos do Sul de Minas Gerais<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>25. Hospital e Cl&iacute;nicas Santa Paula Ltda &ndash; Pouso Alegre<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><\/tr><tr><td>26. Hospital e Maternidade Santa Rita<\/td><td class=\"has-text-align-center\" data-align=\"center\">8<\/td><\/tr><tr><td>27. Hospital e Maternidade S&atilde;o Jos&eacute; &ndash; Conselheiro Lafaiete<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><\/tr><tr><td>28. Hospital e Maternidade Therezinha de Jesus &ndash; HMTJ<\/td><td class=\"has-text-align-center\" data-align=\"center\">44<\/td><\/tr><tr><td>29. Hospital Evang&eacute;lico de Belo Horizonte<\/td><td class=\"has-text-align-center\" data-align=\"center\">19<\/td><\/tr><tr><td>30. Hospital Ibiapaba-CEBAMS (Centro Barbacenense de Assist&ecirc;ncia M&eacute;dica e Social)<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><\/tr><tr><td>31. Hospital Infantil S&atilde;o Camilo &ndash; UNIMED<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><\/tr><tr><td>32. Hospital Madre Teresa &ndash; BH<\/td><td class=\"has-text-align-center\" data-align=\"center\">34<\/td><\/tr><tr><td>33. Hospital Marcio Cunha &ndash; FSFX &ndash; Ipatinga<\/td><td class=\"has-text-align-center\" data-align=\"center\">39<\/td><\/tr><tr><td>34. Hospital Mater Dei &ndash; Unidade Contorno<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>35. Hospital Mater Dei &ndash; Unidade Santo Agostinho<\/td><td class=\"has-text-align-center\" data-align=\"center\">44<\/td><\/tr><tr><td>36. Hospital Maternidade e Pronto Socorro Santa L&uacute;cia LTDA &ndash; Po&ccedil;os de Caldas<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>37. Hospital Metropolitano Doutor C&eacute;lio de Castro<\/td><td class=\"has-text-align-center\" data-align=\"center\">11<\/td><\/tr><tr><td>38. Hospital Metropolitano Odilon Behrens<\/td><td class=\"has-text-align-center\" data-align=\"center\">80<\/td><\/tr><tr><td>39. Hospital Municipal Jos&eacute; Lucas Filho<\/td><td class=\"has-text-align-center\" data-align=\"center\">17<\/td><\/tr><tr><td>40. Hospital Otorrino Center LTDA<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>41. Hospital P&uacute;blico Regional de Betim<\/td><td class=\"has-text-align-center\" data-align=\"center\">25<\/td><\/tr><tr><td>42. Hospital Risoleta Tolentino Neves\/FUNDEP<\/td><td class=\"has-text-align-center\" data-align=\"center\">27<\/td><\/tr><tr><td>43. Hospital Santa Casa de Patroc&iacute;nio<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><\/tr><tr><td>44. Hospital Semper<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><\/tr><tr><td>45. Hospital Socor<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>46. Hospital Sofia Feldman<\/td><td class=\"has-text-align-center\" data-align=\"center\">13<\/td><\/tr><tr><td>47. Hospital Unimed &ndash; Unidade Betim<\/td><td class=\"has-text-align-center\" data-align=\"center\">8<\/td><\/tr><tr><td>48. Hospital Unimed &ndash; Unidade Contorno<\/td><td class=\"has-text-align-center\" data-align=\"center\">10<\/td><\/tr><tr><td>49. Sociedade Mineira de Cultura &ndash; PUC Minas Po&ccedil;os de Caldas<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>50. Hospital Unimed &ndash; Unidade Contorno<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><\/tr><tr><td>51. Hospital Unimed Vit&oacute;ria<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>52. Hospital Universit&aacute;rio Alzira Velano<\/td><td class=\"has-text-align-center\" data-align=\"center\">25<\/td><\/tr><tr><td>53. Hospital Universit&aacute;rio M&aacute;rio Palm&eacute;rio da Universidade de Uberaba &ndash; UNIUBE<\/td><td class=\"has-text-align-center\" data-align=\"center\">22<\/td><\/tr><tr><td>54. Hospital Vila da Serra &ndash; BH &ndash; Instituto Materno Infantil de Minas Gerais<\/td><td class=\"has-text-align-center\" data-align=\"center\">15<\/td><\/tr><tr><td>55. Instituto de Previd&ecirc;ncia dos Servidores do Estado de Minas Gerais-IPSEMG<\/td><td class=\"has-text-align-center\" data-align=\"center\">88<\/td><\/tr><tr><td>56. Instituto Mario Penna &ndash; unidades Hospital Luxemburgo e Mario Penna<\/td><td class=\"has-text-align-center\" data-align=\"center\">34<\/td><\/tr><tr><td>57. <a href=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2022\/01\/ComunicadoCancelamentoEditalResidenciaMedica-IrmandadeNossaSenhoradaSaude-20220110172448.pdf\" target=\"_blank\">Irmandade de Nossa Senhora da Sa&uacute;de &ndash; Hospital S&atilde;o Vicente de Paulo &ndash; Ub&aacute;<\/a><br> <strong>(edital cancelado)<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><\/tr><tr><td>58. Irmandade de Nossa Senhora das Gra&ccedil;as &ndash; Sete Lagoas<\/td><td class=\"has-text-align-center\" data-align=\"center\">9<\/td><\/tr><tr><td>59. Irmandade do Hospital da Santa Casa de Po&ccedil;os de Caldas<\/td><td class=\"has-text-align-center\" data-align=\"center\">16<\/td><\/tr><tr><td>60. Irmandade do Hospital De Nossa Senhora Das Dores &ndash; Ponte Nova<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><\/tr><tr><td>61. Irmandade N Sra das Merces S Casa de Caridade Montes Claros MG<\/td><td class=\"has-text-align-center\" data-align=\"center\">34<\/td><\/tr><tr><td>62. ISO Olhos &ndash; Instituto de Sa&uacute;de Ocular<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>63. Lifecenter Sistema de Sa&uacute;de S\/A<\/td><td class=\"has-text-align-center\" data-align=\"center\">11<\/td><\/tr><tr><td>65. Maternidade Unimed &ndash; Unidade Graja&uacute;<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><\/tr><tr><td>66. Maternidade Unimed Vit&oacute;ria<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>67. Prefeitura de Juiz de Fora<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>68. Santa Casa de Miseric&oacute;rdia de Araguari<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><\/tr><tr><td>69. Santa Casa de Miseric&oacute;rdia de Barbacena<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>70. Santa Casa de Miseric&oacute;rdia de Juiz de Fora MG<\/td><td class=\"has-text-align-center\" data-align=\"center\">26<\/td><\/tr><tr><td>71. Santa Casa de Miseric&oacute;rdia de Passos<\/td><td class=\"has-text-align-center\" data-align=\"center\">30<\/td><\/tr><tr><td>72. Santa Casa de Miseric&oacute;rdia de S&atilde;o Sebasti&atilde;o do Para&iacute;so<\/td><td class=\"has-text-align-center\" data-align=\"center\">10<\/td><\/tr><tr><td>73. Secretaria Municipal de Sa&uacute;de de Belo Horizonte<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><\/tr><tr><td>74. Secretaria Municipal de Sa&uacute;de de Governador Valadares<\/td><td class=\"has-text-align-center\" data-align=\"center\">31<\/td><\/tr><tr><td>75. Secretaria Municipal de Sa&uacute;de de Sete Lagoas<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><\/tr><tr><td>76. Universidade Federal de Ouro Preto<\/td><td class=\"has-text-align-center\" data-align=\"center\">12<\/td><\/tr><tr><td>77. Universidade Federal de S&atilde;o Jo&atilde;o Del Rei<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>78. Universidade Federal de Vi&ccedil;osa<\/td><td class=\"has-text-align-center\" data-align=\"center\">14<\/td><\/tr><tr><td>79. Universidade Federal do Triangulo Mineiro &ndash; Uberaba<\/td><td class=\"has-text-align-center\" data-align=\"center\">98<\/td><\/tr><tr><td>80. Universidade Federal dos Vales do Jequitinhonha e Mucuri<\/td><td class=\"has-text-align-center\" data-align=\"center\">11<\/td><\/tr><tr><td>81. Vila Verde Sa&uacute;de Mental<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td><strong>TOTAL<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>1.315<\/strong><\/td><\/tr><\/tbody><\/table><\/figure><h3 class=\"wp-block-heading\" id=\"h-vagas-de-acesso-direto\">Vagas de Acesso Direto<\/h3><figure class=\"wp-block-table is-style-stripes\"><table class=\"has-light-green-cyan-to-vivid-green-cyan-gradient-background has-background has-fixed-layout\"><thead><tr><th>Especialidade<\/th><th class=\"has-text-align-center\" data-align=\"center\">Vagas<\/th><\/tr><\/thead><tbody><tr><td>Anestesiologia*<\/td><td class=\"has-text-align-center\" data-align=\"center\">82<\/td><\/tr><tr><td>Cirurgia Cardiovascular<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Cirurgia Geral<\/td><td class=\"has-text-align-center\" data-align=\"center\">117<\/td><\/tr><tr><td>Cl&iacute;nica M&eacute;dica*<\/td><td class=\"has-text-align-center\" data-align=\"center\">235<\/td><\/tr><tr><td>Dermatologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>Infectologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>Ginecologia e Obstetr&iacute;cia*<\/td><td class=\"has-text-align-center\" data-align=\"center\">116<\/td><\/tr><tr><td>Homeopatia<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>Medicina da Fam&iacute;lia e Comunidade<\/td><td class=\"has-text-align-center\" data-align=\"center\">102<\/td><\/tr><tr><td>Medicina de Emerg&ecirc;ncia<\/td><td class=\"has-text-align-center\" data-align=\"center\">14<\/td><\/tr><tr><td>Medicina Intensiva<\/td><td class=\"has-text-align-center\" data-align=\"center\">38<\/td><\/tr><tr><td>Neurocirurgia<\/td><td class=\"has-text-align-center\" data-align=\"center\">13<\/td><\/tr><tr><td>Neurologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">26<\/td><\/tr><tr><td>Oftalmologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">14<\/td><\/tr><tr><td>Ortopedia e Traumatologia*<\/td><td class=\"has-text-align-center\" data-align=\"center\">68<\/td><\/tr><tr><td>Otorrinolaringologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><\/tr><tr><td>Patologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>Pediatria<\/td><td class=\"has-text-align-center\" data-align=\"center\">117<\/td><\/tr><tr><td>Psiquiatria<\/td><td class=\"has-text-align-center\" data-align=\"center\">25<\/td><\/tr><tr><td>Radiologia e Diagn&oacute;stico por Imagem*<\/td><td class=\"has-text-align-center\" data-align=\"center\">27<\/td><\/tr><tr><td>Radioterapia<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><\/tr><tr><td><strong>TOTAL<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>1030<\/strong><\/td><\/tr><\/tbody><\/table><\/figure><h3 class=\"wp-block-heading\" id=\"h-vagas-com-pre-requisito-e-area-de-atuacao\">Vagas com Pr&eacute;-Requisito e &Aacute;rea de Atua&ccedil;&atilde;o<\/h3><figure class=\"wp-block-table is-style-stripes\"><table class=\"has-light-green-cyan-to-vivid-green-cyan-gradient-background has-background has-fixed-layout\"><thead><tr><th>Especialidade<\/th><th class=\"has-text-align-center\" data-align=\"center\">Vagas<\/th><\/tr><\/thead><tbody><tr><td>Alergia e Imunologia Pedi&aacute;trica<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Cancerologia Cl&iacute;nica<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Cardiologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">52<\/td><\/tr><tr><td>Cardiologia Pedi&aacute;trica<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Cirurgia Aparelho Digestivo<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><\/tr><tr><td>Cirurgia Cr&acirc;nio-Maxilo-Facial<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Cirurgia de M&atilde;o<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Cirurgia de Cabe&ccedil;a e Pesco&ccedil;o<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Cirurgia do Trauma &ndash; &Aacute;rea de atua&ccedil;&atilde;o<\/td><td class=\"has-text-align-center\" data-align=\"center\">10<\/td><\/tr><tr><td>Cirurgia Oncol&oacute;gica<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><\/tr><tr><td>Cirurgia Pedi&aacute;trica<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Cirurgia Pl&aacute;stica<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><\/tr><tr><td>Cirurgia Tor&aacute;cica<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Cirurgia Vascular<\/td><td class=\"has-text-align-center\" data-align=\"center\">15<\/td><\/tr><tr><td>Cl&iacute;nica M&eacute;dica &ndash; R3<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Coloproctologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Ecocardiografia<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Emerg&ecirc;ncia Pedi&aacute;trica<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Endocrinologia Pedi&aacute;trica &ndash; &Aacute;rea de atua&ccedil;&atilde;o<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Endocrinologia e Metabologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">10<\/td><\/tr><tr><td>Endoscopia Respirat&oacute;ria<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Gastroenterologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">8<\/td><\/tr><tr><td>Geriatria<\/td><td class=\"has-text-align-center\" data-align=\"center\">13<\/td><\/tr><tr><td>Hematologia e Hemoterapia<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>Hematologia e Hemoterapia Pedi&aacute;trica<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Mastologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">13<\/td><\/tr><tr><td>Medicina Fetal &ndash; &Aacute;rea de atua&ccedil;&atilde;o<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><\/tr><tr><td>Medicina Intensiva Pedi&aacute;trica &ndash; &Aacute;rea de atua&ccedil;&atilde;o<\/td><td class=\"has-text-align-center\" data-align=\"center\">8<\/td><\/tr><tr><td>Medicina Paliativa<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><\/tr><tr><td>Nefrologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">20<\/td><\/tr><tr><td>Neonatologia &ndash; &Aacute;rea de atua&ccedil;&atilde;o<\/td><td class=\"has-text-align-center\" data-align=\"center\">26<\/td><\/tr><tr><td>Neurologia Pedi&aacute;trica<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Nutrologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Oncologia Cl&iacute;nica<\/td><td class=\"has-text-align-center\" data-align=\"center\">30<\/td><\/tr><tr><td>Oncologia Pedi&aacute;trica<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Radiologia Intervencionista e Angiorradiologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Reprodu&ccedil;&atilde;o Assistida<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Reumatologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><\/tr><tr><td>Ultrassonografia em<br>Ginecologia e obstetr&iacute;cia<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><\/tr><tr><td>Urologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">13<\/td><\/tr><tr><td><strong>TOTAL<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>287<\/strong><\/td><\/tr><\/tbody><\/table><\/figure><h2 class=\"wp-block-heading\" id=\"h-instituicoes-participantes-do-psu-mg-2022\"><span class=\"ez-toc-section\" id=\"Instituicoes-Participantes-do-PSU-MG-2022\"><\/span>Institui&ccedil;&otilde;es Participantes do PSU-MG 2022<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Confira, abaixo, as <strong>80 institui&ccedil;&otilde;es participantes do processo seletivo:<\/strong><\/p><p>1. Associa&ccedil;&atilde;o Beneficente Cat&oacute;lica \/ Hospital Santa Isabel &ndash; Ub&aacute;<br>2. Associa&ccedil;&atilde;o de Combate ao C&acirc;ncer do Brasil Hospital H&eacute;lio Angotti<br>3. Associa&ccedil;&atilde;o Hospitalar Santa Ros&aacute;lia<br>4. Casa de Caridade de Alfenas Nossa Senhora do Perp&eacute;tuo Socorro<br>5. Casa de Caridade de Carangola<br>6. Casa de Caridade de Muria&eacute; &ndash; Hospital S&atilde;o Paulo<br>7. Complexo de Sa&uacute;de S&atilde;o Jo&atilde;o de Deus<br>8. Faculdade de Medicina da Universidade Federal de Uberl&acirc;ndia<br>9. Funda&ccedil;&atilde;o Benjamin Guimar&atilde;es Hospital da Baleia<br>10. Funda&ccedil;&atilde;o Cristiano Varella &ndash; Hospital do C&acirc;ncer de Muria&eacute;<br>11. Funda&ccedil;&atilde;o Hospitalar S&atilde;o Francisco de Assis<br>12. Funda&ccedil;&atilde;o Instituto Clinico Juiz de Fora<br>13. Funda&ccedil;&atilde;o Jose Bonif&aacute;cio Lafayette de Andrada &ndash; Faculdade de Medicina de Barbacena<br>14. Funda&ccedil;&atilde;o S&atilde;o Francisco Xavier\/ Hospital Municipal Carlos Chagas<br>15. Fundo Municipal de Sa&uacute;de de Manhua&ccedil;u<br>16. Hospital Arnaldo Gavazza &ndash; Ponte Nova<br>17. Hospital Aroldo Tourinho &ndash; Montes Claros<br>18. Hospital Belo Horizonte<br>19. Hospital Bom Samaritano &ndash; Governador Valadares<br>20. Hospital Cesar Leite &ndash; Manhua&ccedil;u<br>21. Hospital das Cl&iacute;nicas Samuel Lib&acirc;nio &ndash; Pouso Alegre<br>22. Hospital Deraldo Guimar&atilde;es &ndash; Almenara<br>23. Hospital de Cl&iacute;nicas de Itajub&aacute; da Associa&ccedil;&atilde;o de Integra&ccedil;&atilde;o Social de Itajub&aacute;<br>24. Hospital de Olhos do Sul de Minas Gerais<br>25. Hospital e Cl&iacute;nicas Santa Paula Ltda &ndash; Pouso Alegre<br>26. Hospital e Maternidade Santa Rita<br>27. Hospital e Maternidade S&atilde;o Jos&eacute; &ndash; Conselheiro Lafaiete<br>28. Hospital e Maternidade Therezinha de Jesus &ndash; HMTJ<br>29. Hospital Evang&eacute;lico de Belo Horizonte<br>30. Hospital Ibiapaba-CEBAMS (Centro Barbacenense de Assist&ecirc;ncia M&eacute;dica e Social)<br>31. Hospital Infantil S&atilde;o Camilo &ndash; UNIMED<br>32. Hospital Madre Teresa &ndash; BH<br>33. Hospital Marcio Cunha &ndash; FSFX &ndash; Ipatinga<br>34. Hospital Mater Dei &ndash; Unidade Contorno<br>35. Hospital Mater Dei &ndash; Unidade Santo Agostinho<br>36. Hospital Maternidade e Pronto Socorro Santa L&uacute;cia LTDA &ndash; Po&ccedil;os de Caldas<br>37. Hospital Metropolitano Doutor C&eacute;lio de Castro<br>38. Hospital Metropolitano Odilon Behrens<br>39. Hospital Municipal Jos&eacute; Lucas Filho<br>40. Hospital Otorrino Center LTDA<br>41. Hospital P&uacute;blico Regional de Betim<br>42. Hospital Risoleta Tolentino Neves\/FUNDEP<br>43. Hospital Santa Casa de Patroc&iacute;nio<br>44. Hospital Semper<br>45. Hospital Socor<br>46. Hospital Sofia Feldman<br>47. Hospital Unimed &ndash; Unidade Betim<br>48. Hospital Unimed &ndash; Unidade Contorno<br>49. Sociedade Mineira de Cultura &ndash; PUC Minas Po&ccedil;os de Caldas<br>50. Hospital Unimed &ndash; Unidade Contorno<br>51. Hospital Unimed Vit&oacute;ria<br>52. Hospital Universit&aacute;rio Alzira Velano<br>53. Hospital Universit&aacute;rio M&aacute;rio Palm&eacute;rio da Universidade de Uberaba &ndash; UNIUBE<br>54. Hospital Vila da Serra &ndash; BH &ndash; Instituto Materno Infantil de Minas Gerais<br>55. Instituto de Previd&ecirc;ncia dos Servidores do Estado de Minas Gerais-IPSEMG<br>56. Instituto Mario Penna &ndash; unidades Hospital Luxemburgo e Mario Penna<br>57. Irmandade de Nossa Senhora da Sa&uacute;de &ndash; Hospital S&atilde;o Vicente de Paulo &ndash; Ub&aacute;<br>58. Irmandade de Nossa Senhora das Gra&ccedil;as &ndash; Sete Lagoas<br>59. Irmandade do Hospital da Santa Casa de Po&ccedil;os de Caldas<br>60. Irmandade do Hospital De Nossa Senhora Das Dores &ndash; Ponte Nova<br>61. Irmandade N Sra das Merces S Casa de Caridade Montes Claros MG<br>62. ISO Olhos &ndash; Instituto de Sa&uacute;de Ocular<br>63. Lifecenter Sistema de Sa&uacute;de S\/A<br>64. Maternidade Unimed &ndash; Unidade Graja&uacute;<br>65. Maternidade Unimed Vit&oacute;ria<br>66. Prefeitura de Juiz de Fora<br>67. Santa Casa de Miseric&oacute;rdia de Araguari<br>68. Santa Casa de Miseric&oacute;rdia de Barbacena<br>69. Santa Casa de Miseric&oacute;rdia de Juiz de Fora MG<br>70. Santa Casa de Miseric&oacute;rdia de Passos<br>71. Santa Casa de Miseric&oacute;rdia de S&atilde;o Sebasti&atilde;o do Para&iacute;so<br>72. Secretaria Municipal de Sa&uacute;de de Belo Horizonte<br>73. Secretaria Municipal de Sa&uacute;de de Governador Valadares<br>74. Secretaria Municipal de Sa&uacute;de de Sete Lagoas<br>75. Universidade Federal de Ouro Preto<br>76. Universidade Federal de S&atilde;o Jo&atilde;o Del Rei<br>77. Universidade Federal de Vi&ccedil;osa<br>78. Universidade Federal do Triangulo Mineiro &ndash; Uberaba<br>79. Universidade Federal dos Vales do Jequitinhonha e Mucuri<br>80. Vila Verde Sa&uacute;de Mental<\/p><h2 class=\"wp-block-heading\" id=\"h-inscricoes-psu-mg-2022\"><span class=\"ez-toc-section\" id=\"Inscricoes-PSU-MG-2022\"><\/span>Inscri&ccedil;&otilde;es PSU-MG 2022<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Todo <strong>processo de inscri&ccedil;&atilde;o para o PSU-MG foi feito pela internet, por meio do <\/strong><a href=\"http:\/\/www.aremg.org.br\/\" target=\"_blank\"><strong>site da AREMG<\/strong><\/a><strong> ou dos sites das institui&ccedil;&otilde;es participantes.<\/strong> As p&aacute;ginas ser&atilde;o disponibilizadas nos diferentes editais. O candidato realizou sua <strong>inscri&ccedil;&atilde;o entre os dias 5 e 20 de outubro de 2021.<\/strong><\/p><h2 class=\"wp-block-heading\" id=\"h-relacao-candidato-vaga-psu-mg-2022\"><span class=\"ez-toc-section\" id=\"Relacao-candidatovaga-PSU-MG-2022\"><\/span><strong>Rela&ccedil;&atilde;o candidato\/vaga PSU-MG 2022<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2><p>O seletivo do PSU-MG 2022 contou com&nbsp;<strong>1.293 vagas<\/strong> e <strong>27.976 inscritos<\/strong>. Para conferir a rela&ccedil;&atilde;o candidato por vaga de cada especialidade presente na institui&ccedil;&atilde;o, clique no bot&atilde;o abaixo!<\/p><p><\/p><div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-light-green-cyan-background-color has-background\" href=\"https:\/\/www.galaxcms.com.br\/up_crud_comum\/601\/RelatorioCandatoporvaga-PSU2022-20211029113622.pdf\" target=\"_blank\">Concorr&ecirc;ncia PSU-MG 2022<\/a><\/div>\n<\/div><h2 class=\"wp-block-heading\" id=\"h-processo-seletivo-psu-mg-2022\"><span class=\"ez-toc-section\" id=\"Processo-Seletivo-PSU-MG-2022\"><\/span><strong>Processo Seletivo PSU-MG 2022<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2><p>O seletivo do PSU-MG envolveu duas fases: Prova Objetiva, com peso 9,0 e An&aacute;lise Curricular, com peso 1,0.<\/p><h3 class=\"wp-block-heading\" id=\"h-prova-objetiva-1&ordf;-fase\"><strong>Prova Objetiva (1&ordf; fase)<\/strong><\/h3><p>A prova objetiva foi a<strong> 1&ordf; fase do PSU-MG 2022, que equivale a 90% da nota final.&nbsp;<\/strong><\/p><h4 class=\"wp-block-heading\" id=\"h-no-dia-da-prova-objetiva\"><strong>No dia da prova objetiva<\/strong><\/h4><ul class=\"wp-block-list\"><li>Os port&otilde;es foram fechados &agrave;s 8h45;<\/li><li>Foi necess&aacute;rio levar um <strong>documento de identidade e o comprovante de inscri&ccedil;&atilde;o quitado;<\/strong><\/li><li>O gabarito deveria ser preenchido por <strong>caneta esferogr&aacute;fica transparente de tinta azul ou preta;&nbsp;<\/strong><\/li><li>O candidato <strong>s&oacute; p&ocirc;de sair da sala de prova ap&oacute;s passada 1 hora desde o in&iacute;cio do exame.<\/strong><\/li><\/ul><p>As <strong>provas foram<\/strong> <strong>diferentes para as especialidades de acesso direto e para as especialidades com pr&eacute;-requisito.<\/strong> Confira, abaixo, os detalhes de cada uma delas.<\/p><h4 class=\"wp-block-heading\" id=\"h-acesso-direto\"><strong>Acesso Direto:<\/strong><\/h4><p>Foram <strong>100 quest&otilde;es de m&uacute;ltipla escolha<\/strong>, com apenas uma alternativa correta, divididas entre as seguintes especialidades:<\/p><ul class=\"wp-block-list\"><li>Cirurgia Geral;<\/li><li>Cl&iacute;nica M&eacute;dica;<\/li><li>Obstetr&iacute;cia e Ginecologia;<\/li><li>Medicina Preventiva e Social; e<\/li><li>Pediatria.<\/li><\/ul><p>A prova de acesso direto do PSU-MG 2022 teve <strong>in&iacute;cio &agrave;s 9h do dia 5 de dezembro de 2021<\/strong> e o candidato teve <strong>4 horas para realiz&aacute;-la.<\/strong><\/p><h4 class=\"wp-block-heading\" id=\"h-pre-requisito\"><strong>Pr&eacute;-Requisito:<\/strong><\/h4><p>A prova para especialidades com pr&eacute;-requisito teve at&eacute; <strong>50 quest&otilde;es<\/strong> de m&uacute;ltipla escolha ou at&eacute; <strong>10 quest&otilde;es abertas<\/strong> envolvendo o conte&uacute;do das &aacute;reas que s&atilde;o pr&eacute;-requisitos para entrada no Programa de Resid&ecirc;ncia M&eacute;dica.<\/p><p>A prova tamb&eacute;m teve <strong>in&iacute;cio &agrave;s 9h<\/strong>, por&eacute;m os candidatos tiveram apenas <strong>2 horas para realiz&aacute;-la.<\/strong><\/p><div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/12\/GabaritoprovisorioPSU2022-20211205151729.zip\" target=\"_blank\">Confira o gabarito final!<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/12\/Resultadoprova-PSU2022-20211222103052.pdf\" target=\"_blank\">Veja o resultado da prova e os classificados para 2&ordf; etapa!<\/a><\/div>\n<\/div><h3 class=\"wp-block-heading\" id=\"h-analise-curricular-2&ordf;-fase\"><strong>An&aacute;lise Curricular (2&ordf; fase)<\/strong><\/h3><p><strong>Para passar para a segunda fase<\/strong> do PSU-MG 2022, que consiste na an&aacute;lise curricular, os <strong>candidatos deveriam acertar, pelo menos, 50% da prova objetiva.<\/strong><\/p><p>Os <strong>curr&iacute;culos <\/strong>analisados, assim como os <strong>documentos anexos, precisaram ser enviados no momento da inscri&ccedil;&atilde;o, entre os dias 5 e 20 de outubro de 2021.<\/strong><\/p><p>Os <strong>curr&iacute;culos deveriam estar padronizados, seguindo o que est&aacute; expl&iacute;cito no <\/strong><a href=\"http:\/\/www.aremg.org.br\/detalhes-do-processo\/anexos-aos-editais-do-processo-seletivo-unificado-para-residencia-medica-de-minas-gerais--psu-2022\/1120\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>anexo I<\/strong><\/a><a href=\"http:\/\/www.aremg.org.br\/detalhes-do-processo\/anexos-aos-editais-do-processo-seletivo-unificado-para-residencia-medica-de-minas-gerais--psu-2022\/1120\" target=\"_blank\"><strong> e II<\/strong><\/a> do edital do PSU-MG 2022. Al&eacute;m disso, a <strong>AREMG tamb&eacute;m disponibilizou os crit&eacute;rios que ser&atilde;o aplicados na avalia&ccedil;&atilde;o de <\/strong>cada curr&iacute;culo. <\/p><figure class=\"wp-block-table is-style-stripes\"><table class=\"has-background has-fixed-layout\" style=\"background-color:#e7f5fe\"><thead><tr><th><strong>Crit&eacute;rios<\/strong><\/th><th class=\"has-text-align-center\" data-align=\"center\"><strong>Pontua&ccedil;&atilde;o<\/strong><\/th><\/tr><\/thead><tbody><tr><td>Avalia&ccedil;&atilde;o durante a resid&ecirc;ncia m&eacute;dica de pr&eacute;-requisito<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Conhecimento em ingl&ecirc;s ou outra l&iacute;ngua estrangeira<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Resid&ecirc;ncia m&eacute;dica, resid&ecirc;ncia multiprofissional em sa&uacute;de, mestrado\/doutorado em &aacute;rea da sa&uacute;de, especializa&ccedil;&atilde;o m&eacute;dica ou t&iacute;tulo de especialista<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Representa&ccedil;&atilde;o de m&eacute;dicos residentes<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Apresenta&ccedil;&atilde;o ou publica&ccedil;&atilde;o de trabalhos cient&iacute;ficos nos &uacute;ltimos 3 anos<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Publica&ccedil;&atilde;o de artigo cient&iacute;fico em revista indexada<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Publica&ccedil;&atilde;o de livros ou cap&iacute;tulo de livros em formato f&iacute;sico ou eletr&ocirc;nico nos &uacute;ltimos 3 anos<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Cursos de suporte &agrave; vida realizados nos &uacute;ltimos 5 anos<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Cursos relacionados a &eacute;tica m&eacute;dica<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Cursos relacionados &agrave; medicina baseada em evid&ecirc;ncias, com dura&ccedil;&atilde;o m&iacute;nima de 8 horas, realizados durante nos &uacute;ltimos 03 anos<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><\/tbody><\/table><\/figure><p><strong><strong>Aten&ccedil;&atilde;o!<\/strong><\/strong> Todos os curr&iacute;culos deveriam ser digitalizados para serem enviados para o PSU-MG.<\/p><h2 class=\"wp-block-heading\" id=\"h-resultado-final-e-desempate\"><span class=\"ez-toc-section\" id=\"Resultado-Final-e-Desempate\"><\/span>Resultado Final e Desempate<span class=\"ez-toc-section-end\"><\/span><\/h2><p>O resultado final do PSU-MG 2021 foi divulgado no <a href=\"http:\/\/www.aremg.org.br.\/\" target=\"_blank\">site da AREMG<\/a><strong> no dia 27 de janeiro de 2022.&nbsp;<\/strong>A lista ser&aacute; organizada <strong>em ordem decrescente de classifica&ccedil;&atilde;o<\/strong>, de acordo com as notas finais (soma das notas da 1&ordf; e 2&ordf; fases). Confira:<\/p><div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2022\/01\/resultado-final-psu-mg.pdf\" target=\"_blank\">Resultado Final<\/a><\/div>\n<\/div><p><strong>Aten&ccedil;&atilde;o! <\/strong>Os candidatos convocados deveriam acessar sua p&aacute;gina no <a href=\"http:\/\/www.aremg.org.br\/\" target=\"_blank\">site<\/a> para confirmar interesse ou desist&ecirc;ncia da vaga, levando em conta o prazo especificado em cada convoca&ccedil;&atilde;o. Para a 1&ordf; convoca&ccedil;&atilde;o, o prazo &eacute; de <strong>27\/01 a 02\/02\/2022<\/strong>. <\/p><p>Em <strong>caso de empate, foram considerados os seguintes crit&eacute;rios:<\/strong><\/p><ol class=\"wp-block-list\"><li>Candidato que obtiver maior nota na 1&ordf; fase; e<\/li><li>Candidato mais velho.<\/li><\/ol><div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2022\/02\/convocacao2psu2022public-20220202233637.pdf\" target=\"_blank\">Confira tamb&eacute;m a 2&ordf; chamada!<\/a><\/div>\n<\/div><h2 class=\"wp-block-heading\" id=\"h-psu-mg-2022-complementar\"><span class=\"ez-toc-section\" id=\"PSU-MG-2022-Complementar\"><\/span>PSU-MG 2022 Complementar<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Al&eacute;m do seletivo principal, a AREMG divulgou uma s&eacute;rie de editais extras para Resid&ecirc;ncia M&eacute;dica, com ingresso ainda em 2022. Confira as principais informa&ccedil;&otilde;es abaixo:<\/p><div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2022\/01\/psu-mg-2022-extra.zip\" target=\"_blank\">Editais PSU-MG 2022 complementar<\/a><\/div>\n<\/div><h3 class=\"wp-block-heading\">Cronograma<\/h3><ul class=\"wp-block-list\"><li><strong>Solicita&ccedil;&atilde;o de isen&ccedil;&atilde;o da taxa de inscri&ccedil;&atilde;o:<\/strong> 01 e 02\/02\/2022;<\/li><li><strong>Inscri&ccedil;&otilde;es e envio do curr&iacute;culo: <\/strong>04 a 08\/02\/2022;<\/li><li><strong>Prova escrita e divulga&ccedil;&atilde;o do gabarito: <\/strong>17\/02\/2022; e<\/li><li><strong>Resultado final: <\/strong>24\/02\/2022.<\/li><\/ul><h3 class=\"wp-block-heading\">Processo Seletivo<\/h3><p>Os candidatos passaram por uma prova geral, valendo 90 pontos, e uma an&aacute;lise curricular, de 10 pontos. Para os programas de acesso direto,  foram at&eacute; 75 quest&otilde;es objetivas que versaram entre os conte&uacute;dos de Cirurgia Geral, Cl&iacute;nica M&eacute;dica, Obstetr&iacute;cia e Ginecologia, Medicina Preventiva e Social (Sa&uacute;de Coletiva e Medicina Geral de Fam&iacute;lia e Comunidade) e Pediatria.<\/p><p>Est&aacute; interessado pela Resid&ecirc;ncia M&eacute;dica do PSU-MG? Ent&atilde;o, n&atilde;o deixe de acompanhar as novidades que o Estrat&eacute;gia MED preparou para voc&ecirc;, acompanhe o nosso Portal!<\/p><p><\/p><p><strong><a id=\"cta\" class=\"cta-imagem\" href=\"https:\/\/med.estrategia.com\/cursos\/extensivo-de-residncia-mdica\/\" target=\"blank\">\n                <img decoding=\"async\" width=\"100%\" src=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2025\/08\/extensivo_rm.jpg\" alt=\"Extensivo RM\" title=\"extensivo_rm\">\n        <\/a><\/strong><\/p><h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Veja-tambem\"><\/span>Veja tamb&eacute;m:<span class=\"ez-toc-section-end\"><\/span><\/h2><ul class=\"wp-block-list\"><li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/provas\/psu-mg-2021-provas-e-editais\/\">Prova de Resid&ecirc;ncia M&eacute;dica PSU-MG 2021<\/a><\/li><li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-ufrj\/\">Resid&ecirc;ncia M&eacute;dica UFRJ<\/a><\/li><li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/uff-residencia-medic\/\">Resid&ecirc;ncia M&eacute;dica UFF<\/a><\/li><li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/uerj-residencia-medica\/\">Resid&ecirc;ncia M&eacute;dica UERJ<\/a><\/li><li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/ufes-residencia-medica\/\">Resid&ecirc;ncia M&eacute;dica UFES<\/a><\/li><li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/ses-rj-residencia-medica\/\">Resid&ecirc;ncia M&eacute;dica SES-RJ<\/a><\/li><li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/sms-rj-residencia-medica\/\">Resid&ecirc;ncia M&eacute;dica SMS-RJ<\/a><\/li><li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/especialidades\/10-residencias-medicas-menos-concorridas\/\">10 resid&ecirc;ncias m&eacute;dicas menos concorridas&nbsp;<\/a><\/li><li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/especialidades\/10-residencias-medicas-com-mais-vagas-por-especialidade\/\">10 Resid&ecirc;ncias M&eacute;dicas com mais vagas por especialidade<\/a><\/li><li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencias-medicas-mais-concorridos\/\">10 Resid&ecirc;ncias M&eacute;dicas mais concorridas<\/a><\/li><li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/usp-sp-residencia-medica\/\">Resid&ecirc;ncia M&eacute;dica USP SP<\/a><\/li><li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/enare-vagas-cronograma-provas-edital\/\">Resid&ecirc;ncia M&eacute;dica ENARE<\/a><\/li><\/ul><\/p>\n","protected":false},"excerpt":{"rendered":"Tem interesse na prova do para Resid&ecirc;ncia M&eacute;dica do PSU-MG e quer conferir como foi a &uacute;ltima edi&ccedil;&atilde;o?&hellip;\n","protected":false},"author":10,"featured_media":6733,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wl_entities_gutenberg":"","footnotes":""},"categories":[24],"tags":[160],"wl_entity_type":[199],"class_list":{"0":"post-26166","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-residencia-medica","8":"tag-psu-mg","9":"wl_entity_type-article"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Resid\u00eancia M\u00e9dica PSU-MG 2022 - Estrat\u00e9gia MED!<\/title>\n<meta name=\"description\" content=\"Foram divulgados os editais da Resid\u00eancia M\u00e9dica do PSU-MG , que ter\u00e1 mais de 1300 vagas. Confira mais informa\u00e7\u00f5es sobre o processo seletivo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resid\u00eancia M\u00e9dica PSU-MG 2022: tudo sobre a \u00faltima edi\u00e7\u00e3o!\" \/>\n<meta property=\"og:description\" content=\"Foram divulgados os editais da Resid\u00eancia M\u00e9dica do PSU-MG , que ter\u00e1 mais de 1300 vagas. Confira mais informa\u00e7\u00f5es sobre o processo seletivo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia MED\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/estrategiamed1\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-19T18:13:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-28T12:28:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.medblog.estrategiaeducacional.com.br\/wp-content\/uploads\/2020\/11\/23090433\/PSU-MG.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Beatriz Testa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@estrategiamed_\" \/>\n<meta name=\"twitter:site\" content=\"@estrategiamed_\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Beatriz Testa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/\",\"url\":\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/\",\"name\":\"Resid\u00eancia M\u00e9dica PSU-MG 2022 - Estrat\u00e9gia MED!\",\"isPartOf\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/PSU-MG.jpg\",\"datePublished\":\"2022-10-19T18:13:26+00:00\",\"dateModified\":\"2022-10-28T12:28:05+00:00\",\"author\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/b7dbcd5a280cfd98cc9f95fb82338fe3\"},\"description\":\"Foram divulgados os editais da Resid\u00eancia M\u00e9dica do PSU-MG , que ter\u00e1 mais de 1300 vagas. Confira mais informa\u00e7\u00f5es sobre o processo seletivo!\",\"breadcrumb\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#primaryimage\",\"url\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/PSU-MG.jpg\",\"contentUrl\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/PSU-MG.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"PSU-MG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/med.estrategia.com\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resid\u00eancia M\u00e9dica\",\"item\":\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Resid\u00eancia M\u00e9dica PSU-MG 2022: tudo sobre a \u00faltima edi\u00e7\u00e3o!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#website\",\"url\":\"https:\/\/med.estrategia.com\/portal\/\",\"name\":\"Estrat\u00e9gia MED\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/med.estrategia.com\/portal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/b7dbcd5a280cfd98cc9f95fb82338fe3\",\"name\":\"Beatriz Testa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e87f00de46242bcd24922a3678dae2b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e87f00de46242bcd24922a3678dae2b5?s=96&d=mm&r=g\",\"caption\":\"Beatriz Testa\"},\"description\":\"Beatriz, a santista que cursa jornalismo na grande S\u00e3o Paulo. Amo dan\u00e7ar e ler, mas minha grande paix\u00e3o \u00e9 a escrita. Quando n\u00e3o consigo me expressar na fala, \u00e9 a\u00ed escrita entra em cena.\",\"url\":\"https:\/\/med.estrategia.com\/portal\/author\/beatriz-testa\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resid\u00eancia M\u00e9dica PSU-MG 2022 - Estrat\u00e9gia MED!","description":"Foram divulgados os editais da Resid\u00eancia M\u00e9dica do PSU-MG , que ter\u00e1 mais de 1300 vagas. Confira mais informa\u00e7\u00f5es sobre o processo seletivo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/","og_locale":"pt_BR","og_type":"article","og_title":"Resid\u00eancia M\u00e9dica PSU-MG 2022: tudo sobre a \u00faltima edi\u00e7\u00e3o!","og_description":"Foram divulgados os editais da Resid\u00eancia M\u00e9dica do PSU-MG , que ter\u00e1 mais de 1300 vagas. Confira mais informa\u00e7\u00f5es sobre o processo seletivo!","og_url":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/","og_site_name":"Estrat\u00e9gia MED","article_publisher":"https:\/\/www.facebook.com\/estrategiamed1","article_published_time":"2022-10-19T18:13:26+00:00","article_modified_time":"2022-10-28T12:28:05+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/cdn.medblog.estrategiaeducacional.com.br\/wp-content\/uploads\/2020\/11\/23090433\/PSU-MG.jpg","type":"image\/jpeg"}],"author":"Beatriz Testa","twitter_card":"summary_large_image","twitter_creator":"@estrategiamed_","twitter_site":"@estrategiamed_","twitter_misc":{"Escrito por":"Beatriz Testa","Est. tempo de leitura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/","url":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/","name":"Resid\u00eancia M\u00e9dica PSU-MG 2022 - Estrat\u00e9gia MED!","isPartOf":{"@id":"https:\/\/med.estrategia.com\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#primaryimage"},"image":{"@id":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#primaryimage"},"thumbnailUrl":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/PSU-MG.jpg","datePublished":"2022-10-19T18:13:26+00:00","dateModified":"2022-10-28T12:28:05+00:00","author":{"@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/b7dbcd5a280cfd98cc9f95fb82338fe3"},"description":"Foram divulgados os editais da Resid\u00eancia M\u00e9dica do PSU-MG , que ter\u00e1 mais de 1300 vagas. Confira mais informa\u00e7\u00f5es sobre o processo seletivo!","breadcrumb":{"@id":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#primaryimage","url":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/PSU-MG.jpg","contentUrl":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2020\/11\/PSU-MG.jpg","width":1920,"height":1080,"caption":"PSU-MG"},{"@type":"BreadcrumbList","@id":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/med.estrategia.com\/portal\/"},{"@type":"ListItem","position":2,"name":"Resid\u00eancia M\u00e9dica","item":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/"},{"@type":"ListItem","position":3,"name":"Resid\u00eancia M\u00e9dica PSU-MG 2022: tudo sobre a \u00faltima edi\u00e7\u00e3o!"}]},{"@type":"WebSite","@id":"https:\/\/med.estrategia.com\/portal\/#website","url":"https:\/\/med.estrategia.com\/portal\/","name":"Estrat\u00e9gia MED","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/med.estrategia.com\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/b7dbcd5a280cfd98cc9f95fb82338fe3","name":"Beatriz Testa","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e87f00de46242bcd24922a3678dae2b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e87f00de46242bcd24922a3678dae2b5?s=96&d=mm&r=g","caption":"Beatriz Testa"},"description":"Beatriz, a santista que cursa jornalismo na grande S\u00e3o Paulo. Amo dan\u00e7ar e ler, mas minha grande paix\u00e3o \u00e9 a escrita. Quando n\u00e3o consigo me expressar na fala, \u00e9 a\u00ed escrita entra em cena.","url":"https:\/\/med.estrategia.com\/portal\/author\/beatriz-testa\/"}]}},"_wl_alt_label":[],"wl:entity_url":"\/post\/residencia-medica-psu-mg-inscricoes-edital-vagas-e-mais","_links":{"self":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/26166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/comments?post=26166"}],"version-history":[{"count":2,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/26166\/revisions"}],"predecessor-version":[{"id":28763,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/26166\/revisions\/28763"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/media\/6733"}],"wp:attachment":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/media?parent=26166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/categories?post=26166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/tags?post=26166"},{"taxonomy":"wl_entity_type","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/wl_entity_type?post=26166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}