{"id":3154,"date":"2024-01-08T11:43:00","date_gmt":"2024-01-08T14:43:00","guid":{"rendered":"https:\/\/med.estrategiaeducacional.com.br\/blog\/?p=3154"},"modified":"2026-06-03T13:40:30","modified_gmt":"2026-06-03T16:40:30","slug":"unesp-residencia-medica","status":"publish","type":"post","link":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/","title":{"rendered":"Resid\u00eancia M\u00e9dica Unesp: edital, vagas, cronograma e mais"},"content":{"rendered":"<p>Quer saber tudo sobre o processo seletivo para <a class=\"wl-entity-page-link\" title=\"resid&ecirc;ncia  m&eacute;dica\" href=\"https:\/\/med.estrategia.com\/portal\/entidade\/residencia-medica\/\" data-id=\"\/entity\/residencia-medica;http:\/\/dbpedia.org\/resource\/Residency_(medicine);http:\/\/en.dbpedia.org\/resource\/Residency_(medicine);http:\/\/nl.dbpedia.org\/resource\/Arts-assistent;http:\/\/de.dbpedia.org\/resource\/&Auml;rztliche_Weiterbildung;http:\/\/fr.dbpedia.org\/resource\/R&eacute;sidence_(m&eacute;decine);http:\/\/lt.dbpedia.org\/resource\/Rezident&#363;ra_(studijos);http:\/\/pt.dbpedia.org\/resource\/Resid&ecirc;ncia_m&eacute;dica;http:\/\/ru.dbpedia.org\/resource\/&#1050;&#1083;&#1080;&#1085;&#1080;&#1095;&#1077;&#1089;&#1082;&#1072;&#1103;_&#1086;&#1088;&#1076;&#1080;&#1085;&#1072;&#1090;&#1091;&#1088;&#1072;;http:\/\/uk.dbpedia.org\/resource\/&#1054;&#1088;&#1076;&#1080;&#1085;&#1072;&#1090;&#1091;&#1088;&#1072;_&#1082;&#1083;&#1110;&#1085;&#1110;&#1095;&#1085;&#1072;;https:\/\/data.wordlift.io\/wl106637\/entity\/residencia-medica\">Resid&ecirc;ncia M&eacute;dica<\/a> da <a class=\"wl-entity-page-link\" href=\"https:\/\/med.estrategia.com\/portal\/entidade\/unesp\/\" data-id=\"\/entity\/unesp;http:\/\/de.dbpedia.org\/resource\/Universidade_Estadual_Paulista;http:\/\/pt.dbpedia.org\/resource\/Universidade_Estadual_Paulista;http:\/\/it.dbpedia.org\/resource\/Universidade_Estadual_Paulista;http:\/\/es.dbpedia.org\/resource\/Universidad_Estatal_Paulista;https:\/\/data.wordlift.io\/wl106637\/entity\/unesp\">Unesp<\/a>? Se voc&ecirc; est&aacute; interessado na sele&ccedil;&atilde;o, confira as informa&ccedil;&otilde;es e conte&uacute;dos que o <a class=\"wl-entity-page-link\" href=\"https:\/\/med.estrategia.com\/portal\/entidade\/estrategia-med-2\/\" data-id=\"\/entity\/estrategia-med-2;https:\/\/data.wordlift.io\/wl106637\/entity\/estrategia_med\">Estrat&eacute;gia MED<\/a> preparou para voc&ecirc;!<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_79_2 counter-hierarchy ez-toc-counter ez-toc-transparent ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Navegue pelo conte\u00fado<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#O-que-e-a-Unesp\" >O que &eacute; a Unesp?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#Inscricoes-Unesp-Residencia-Medica\" >Inscri&ccedil;&otilde;es Unesp Resid&ecirc;ncia M&eacute;dica<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#Como-funciona-o-processo-seletivo-da-Unesp\" >Como funciona o processo seletivo da Unesp?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#Saiba-como-foi-a-edicao-para-ingresso-em-2026-da-UNESP\" >Saiba como foi a edi&ccedil;&atilde;o para ingresso em 2026 da UNESP<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#Concorrencia-Unesp-2026\" >Concorr&ecirc;ncia Unesp 2026<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#Estudando-para-a-prova-da-Unesp-2027\" >Estudando para a prova da Unesp 2027?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#Veja-tambem\" >Veja tamb&eacute;m:<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O-que-e-a-Unesp\"><\/span>O que &eacute; a Unesp?<span class=\"ez-toc-section-end\"><\/span><\/h2><p>A <strong>Universidade Estadual Paulista<\/strong> <strong>(Unesp)<\/strong> &eacute; uma <strong>institui&ccedil;&atilde;o p&uacute;blica<\/strong>, voltada para o ensino superior. Criada em <strong>1976<\/strong>, a Unesp &eacute; resultado da jun&ccedil;&atilde;o dos<strong> Institutos Isolados de Ensino Superior<\/strong> do Estado de S&atilde;o Paulo. <\/p><div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/med.estrategia.com\/cursos\/\" style=\"background-color:#0ba4ae\" target=\"_blank\">Conhe&ccedil;a os cursos do Estrat&eacute;gia MED!<\/a><\/div>\n<\/div><div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"699\" src=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/07\/Unesp-1024x699-1.jpg\" alt=\"\" class=\"wp-image-7533\" srcset=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/07\/Unesp-1024x699-1.jpg 1024w, https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/07\/Unesp-1024x699-1-300x205.jpg 300w, https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/07\/Unesp-1024x699-1-768x524.jpg 768w, https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/07\/Unesp-1024x699-1-380x259.jpg 380w, https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/07\/Unesp-1024x699-1-800x546.jpg 800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/www2.unesp.br\/portal#!\/unesp-40-anos\/faculdades-e-institutos\/botucatu---fmb\/\" target=\"_blank\">Foto: Arquivo Unesp<\/a><\/figcaption><\/figure><\/div><h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Inscricoes-Unesp-Residencia-Medica\"><\/span>Inscri&ccedil;&otilde;es Unesp Resid&ecirc;ncia M&eacute;dica<span class=\"ez-toc-section-end\"><\/span><\/h2><p>O processo de inscri&ccedil;&atilde;o da Unesp &eacute; realizado de forma<strong> on-line<\/strong> no m&ecirc;s de outubro, por meio do<a href=\"https:\/\/www.vunesp.com.br\/\" target=\"_blank\"> site da Funda&ccedil;&atilde;o VUNESP<\/a>. Al&eacute;m de preencher a ficha de inscri&ccedil;&atilde;o e efetuar o pagamento da <strong>taxa vigente de R$ 618,00<\/strong>, os candidatos tamb&eacute;m podem <strong>selecionar a cidade em que desejam realizar a prova, sendo S&atilde;o Paulo\/SP, Botucatu\/SP e Bras&iacute;lia\/DF<\/strong> <strong>as op&ccedil;&otilde;es<\/strong>.<\/p><p>Aqueles que desejam solicitar a <strong>redu&ccedil;&atilde;o de 50% no valor da taxa de inscri&ccedil;&atilde;o<\/strong> podem faz&ecirc;-lo nos primeiros dias de inscri&ccedil;&atilde;o, sendo necess&aacute;rio comprovar ser estudantes regularmente matriculados em cursos superiores &mdash; em n&iacute;vel de gradua&ccedil;&atilde;o ou de p&oacute;s-gradua&ccedil;&atilde;o, que recebam remunera&ccedil;&atilde;o mensal inferior a dois sal&aacute;rios m&iacute;nimos, ou desempregados, respeitando as disposi&ccedil;&otilde;es dos itens 18 a 29 do edital. <\/p><p>\n\n\n<div id=\"new-form\">\n\t<form id=\"forms_layout\">\n\t<input type=\"hidden\" id=\"chave_de\" name=\"chave_de\" value=\"01_EMED_LEADS_TOTAIS\" \/>\n\t\t<input type=\"hidden\" id=\"mid\" name=\"mid\" value=\"515009018\" \/>\n\t\t<input type=\"hidden\" id=\"Objetivo\" name=\"Objetivo\" value=\"Medicina\" \/>\n\t\t<input type=\"hidden\" id=\"Estado_de_Origem_do_IP\" name=\"Estado_de_Origem_do_IP\"  value=\"\" \/>\n\t\t<input type=\"hidden\" id=\"Cidade_de_Origem_do_IP\" name=\"Cidade_de_Origem_do_IP\" value=\"\" \/>\n\t\t<input type=\"hidden\" id=\"Modo_de_entrada\" name=\"Modo_de_entrada\" value=\"Portal\" \/>\n\t\t<input type=\"hidden\" id=\"Pagina_Origem\" name=\"Pagina_Origem\" value=\"\" \/>\n\n\t\t<div class=\"texto\">\n\t\t\t<h3 class=\"news\">Inscreva-se em nossa newsletter!<\/h3>\n\t\t\t<p>Receba not\u00edcias sobre resid\u00eancia m\u00e9dica, revalida\u00e7\u00e3o de diplomas e concursos m\u00e9dicos, al\u00e9m de materiais de estudo gratuitos e informa\u00e7\u00f5es relevantes do mundo da Medicina.<\/p>\n\t\t<\/div>\n\t\t<div class=\"campos\">\n\t\t\t<div class=\"first_name labels\">\n\t\t\t\t<input type=\"text\" class=\"input_labels\" id=\"first_name\" name=\"Nome_Completo\" placeholder=\"Nome\" required \/>\n\t\t\t<\/div>\n\t\t\t<div class=\"email labels\">\n\t\t\t\t<input type=\"email\" class=\"input_labels\" id=\"email\" name=\"Email\" placeholder=\"E-mail\" required \/>\n\t\t\t<\/div>\n\t\t\t<button type=\"submit\" class=\"button_layout\">\n\t\t\t\t<div id=\"lblBotao\">Inscreva-se<\/div>\n\t\t\t\t<span id=\"divSpiner\" class=\"loader\" role=\"status\" style=\"display: none;\"><\/span>\t\n\t\t\t<\/button>\n\t\t<\/div><!-- \/campos -->\n\t\t\n\t\t<label class=\"container_checkbox\">Voc\u00ea concorda com a nossa\n\t\t\t<a class=\"politics_privacy_ahref\" target=\"_blank\" href=\"https:\/\/gratis.estrategiaconcursos.com.br\/politica-de-privacidade\/\">Pol\u00edtica de Privacidade<\/a> e aceita receber informa\u00e7\u00f5es adicionais do Estrat\u00e9gia Educacional.\n\t\t\t<input id=\"checkbox_layout\" type=\"checkbox\" checked=\"checked\" required \/>\n\t\t\t<span class=\"checkbox\"><\/span>\n\t\t<\/label>\n\t\t<div id=\"msg\"><\/div>\n\t\t<div id=\"error\" class=\"error\">\n\t\t<\/div>\n\t<\/form>\n<\/div><!-- \/new-form -->\n\n\n\n<\/p><h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como-funciona-o-processo-seletivo-da-Unesp\"><\/span>Como funciona o processo seletivo da Unesp?<span class=\"ez-toc-section-end\"><\/span><\/h2><p>O processo seletivo &eacute; composto por Prova Objetiva e An&aacute;lise Curricular, com exce&ccedil;&atilde;o dos programas de Ortopedia e Traumatologia, Cirurgia da M&atilde;o, Cirurgia Oncol&oacute;gica e Cirurgia Pl&aacute;stica, que contam somente com a etapa da prova escrita objetiva. Saiba mais abaixo!<\/p><h3 class=\"wp-block-heading\">Primeira fase: Prova Objetiva<\/h3><p>A prova objetiva &eacute; a <strong>primeira fase<\/strong> do processo seletivo da Unesp. Ela tem car&aacute;ter <strong>classificat&oacute;rio e eliminat&oacute;rio e corresponde a 90% da nota final<\/strong> para todas as especialidades.<\/p><p>Voc&ecirc; pode conferir abaixo as caracter&iacute;sticas de cada prova de acordo com suas especialidades:<\/p><figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Especialidades<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>N&uacute;mero de Quest&otilde;es<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Tipo de Quest&atilde;o<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Dura&ccedil;&atilde;o<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Acesso Direto<\/td><td class=\"has-text-align-center\" data-align=\"center\">100<\/td><td class=\"has-text-align-center\" data-align=\"center\">M&uacute;ltipla escolha<\/td><td class=\"has-text-align-center\" data-align=\"center\">4 horas<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Pr&eacute;-Requisito (Grupo 1 e 2)<\/td><td class=\"has-text-align-center\" data-align=\"center\">100<\/td><td class=\"has-text-align-center\" data-align=\"center\">M&uacute;ltipla escolha<\/td><td class=\"has-text-align-center\" data-align=\"center\">4 horas<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Pr&eacute;-Requisito (Grupo 3 e 4)<\/td><td class=\"has-text-align-center\" data-align=\"center\">60<\/td><td class=\"has-text-align-center\" data-align=\"center\">M&uacute;ltipla escolha<\/td><td class=\"has-text-align-center\" data-align=\"center\">3 horas<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Pr&eacute;-Requisito (Grupo 5)<\/td><td class=\"has-text-align-center\" data-align=\"center\">25 + 1<\/td><td class=\"has-text-align-center\" data-align=\"center\">M&uacute;ltipla escolha e Quest&atilde;o dissertativa<\/td><td class=\"has-text-align-center\" data-align=\"center\">3 horas<\/td><\/tr><\/tbody><\/table><\/figure><h3 class=\"wp-block-heading\">Segunda fase: An&aacute;lise Curricular<\/h3><p>A<a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/analise-curricular\/analise-curricular-residencia-medica\/\" target=\"_blank\"> an&aacute;lise curricular<\/a> corresponde &agrave; <strong>segunda e &uacute;ltima fase<\/strong> do processo seletivo da Unesp. Ela tem <strong>car&aacute;ter apenas classificat&oacute;rio e peso de 10%<\/strong> na nota final.&nbsp;<\/p><p>Para participar, o candidato precisa fazer o <strong>upload de seu curr&iacute;culo na<\/strong><a href=\"http:\/\/www.avaliacao.fmb.unesp.br\" target=\"_blank\"><strong> p&aacute;gina espec&iacute;fica da Unesp<\/strong><\/a> em per&iacute;odo especificado em edital. Os itens avaliados mudam de acordo com a especialidade a qual o candidato concorre, mas, em geral, s&atilde;o<strong> avaliados os seguintes itens:<\/strong><\/p><ul class=\"wp-block-list\">\n<li>&Iacute;ndice geral de cursos da Institui&ccedil;&atilde;o;<\/li>\n\n\n\n<li>Dura&ccedil;&atilde;o do internato;<\/li>\n\n\n\n<li>Coeficiente de rendimento do aluno;<\/li>\n\n\n\n<li>Participa&ccedil;&atilde;o em cons&oacute;rcio de Teste do Progresso;<\/li>\n\n\n\n<li>Plant&otilde;es de internato na institui&ccedil;&atilde;o de ensino respons&aacute;vel pela gradua&ccedil;&atilde;o, com mais de 750 horas, comprovados pela institui&ccedil;&atilde;o;<\/li>\n\n\n\n<li>Inicia&ccedil;&atilde;o cient&iacute;fica com ou sem bolsa;<\/li>\n\n\n\n<li>Monitoria acad&ecirc;mica;<\/li>\n\n\n\n<li>Participa&ccedil;&atilde;o em ligas acad&ecirc;micas ou atl&eacute;ticas;<\/li>\n\n\n\n<li>Trabalho apresentado em congresso de sociedades;<\/li>\n\n\n\n<li>Atividades extracurriculares e certificados;<\/li>\n\n\n\n<li>Monitorias;<\/li>\n\n\n\n<li>Trabalhos ou artigos publicados;<\/li>\n\n\n\n<li>Entre outros.<\/li>\n<\/ul><p>Todos os candidatos convocados para a 2&ordf; etapa dever&atilde;o encaminhar o curriculum vitae, a c&oacute;pia de todos os certificados &ndash; incluindo Hist&oacute;rico Escolar do Curso de Medicina &ndash; e foto colorida. <\/p><p>A an&aacute;lise do curriculum vitae &eacute; realizada por Banca Examinadora composta para cada uma das especialidades e, determina uma pontua&ccedil;&atilde;o de 0 a 10. Os <strong>documentos devem ser organizados e enviados de acordo com a ordem abaixo<\/strong>: <\/p><ul class=\"wp-block-list\">\n<li>1. Capa com identifica&ccedil;&atilde;o; <\/li>\n\n\n\n<li>2. Texto descritivo do curriculum vitae;<\/li>\n\n\n\n<li>3. Respectivos documentos comprobat&oacute;rios;<\/li>\n\n\n\n<li>4. C&oacute;pia do diploma de gradua&ccedil;&atilde;o ou declara&ccedil;&atilde;o de conclus&atilde;o do curso; e <\/li>\n\n\n\n<li>5. C&oacute;pia do hist&oacute;rico escolar do curso de gradua&ccedil;&atilde;o.<\/li>\n<\/ul><p>Para os documentos comprobat&oacute;rios, a ordem de envio de cada documento deve ser:<\/p><ol class=\"wp-block-list\">\n<li>Forma&ccedil;&atilde;o acad&ecirc;mica: nome da institui&ccedil;&atilde;o, curr&iacute;culo e hist&oacute;rico escolar &ldquo;sujo&rdquo; com rendimento do aluno, tempo de internato, participa&ccedil;&atilde;o em teste do Progresso e documento comprobat&oacute;rio do n&uacute;mero de horas de plant&otilde;es realizados na gradua&ccedil;&atilde;o;<\/li>\n\n\n\n<li>Participa&ccedil;&atilde;o em atividades extracurriculares relacionadas ao ensino, assist&ecirc;ncia, extens&atilde;o e pesquisa;<\/li>\n\n\n\n<li>Participa&ccedil;&atilde;o em Eventos (congressos\/cursos\/jornadas) cient&iacute;ficas, de extens&atilde;o ou de ensino &ndash; comprovando se houver apresenta&ccedil;&atilde;o de trabalhos;<\/li>\n\n\n\n<li>Publica&ccedil;&atilde;o de artigos e de outras produ&ccedil;&otilde;es (autoria e coautoria);<\/li>\n\n\n\n<li>Outras atividades extracurriculares: no &acirc;mbito da gradua&ccedil;&atilde;o na institui&ccedil;&atilde;o, ou n&atilde;o relacionadas diretamente &agrave; profiss&atilde;o, l&iacute;nguas estrangeiras e outras atividades apresentadas de organiza&ccedil;&atilde;o em ensino, pesquisa ou extens&atilde;o.<\/li>\n<\/ol><h2 class=\"wp-block-heading\" id=\"h-saiba-como-foi-a-edicao-para-ingresso-em-2026-da-unesp\"><span class=\"ez-toc-section\" id=\"Saiba-como-foi-a-edicao-para-ingresso-em-2026-da-UNESP\"><\/span>Saiba como foi a edi&ccedil;&atilde;o para ingresso em 2026 da UNESP<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Confira os editais divulgados para o processo seletivo para Resid&ecirc;ncia M&eacute;dica da UNESP 2026:<\/p><div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-2 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/cdn.medblog.estrategiaeducacional.com.br\/wp-content\/uploads\/2025\/09\/unesp_editalAD_2026.pdf\" target=\"_blank\">EDITAL UNESP 2025 &ndash; ACESSO DIRETO (VERS&Atilde;O DOE)<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/cdn.medblog.estrategiaeducacional.com.br\/wp-content\/uploads\/2025\/09\/FMHO2501_224_20250929115659.pdf.pdf\" target=\"_blank\">EDITAL UNESP 2025 &ndash; ACESSO DIRETO<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/cdn.medblog.estrategiaeducacional.com.br\/wp-content\/uploads\/2025\/09\/unesp_editalPR_2026.pdf\" target=\"_blank\">EDITAL UNESP 2025 &ndash; PR&Eacute;-REQUISITO (VERS&Atilde;O DOE)<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/cdn.medblog.estrategiaeducacional.com.br\/wp-content\/uploads\/2025\/09\/FMHO2501_224_20250929115815.pdf.pdf\" target=\"_blank\">EDITAL UNESP 2025 &ndash; PR&Eacute;-REQUISITO<\/a><\/div>\n<\/div><h3 class=\"wp-block-heading\" id=\"h-cronograma-unesp-2026\">Cronograma Unesp 2026<\/h3><ul class=\"wp-block-list\">\n<li><strong style=\"color: initial;\">Per&iacute;odo de Inscri&ccedil;&otilde;es:<\/strong><span style=\"color: initial;\"> 09 a 20\/10\/2025;<\/span><\/li>\n\n\n\n<li><strong>Taxa de inscri&ccedil;&atilde;o:<\/strong> R$618,00;<\/li>\n\n\n\n<li><strong>Prova Objetiva:<\/strong> 29\/11\/2025;<\/li>\n\n\n\n<li><strong>Divulga&ccedil;&atilde;o do Gabarito Preliminar:<\/strong> 01\/12\/2025;<\/li>\n\n\n\n<li><strong>Recurso contra o Gabarito:<\/strong> 02 e 03\/12\/2025;<\/li>\n\n\n\n<li><strong>Convoca&ccedil;&atilde;o para a 2&ordf; fase: <\/strong>05\/12\/2025;<\/li>\n\n\n\n<li><strong>Envio dos documentos para An&aacute;lise Curricular:<\/strong> 06 a 09\/12\/2025;<\/li>\n\n\n\n<li><strong>An&aacute;lise Curricular: <\/strong>10 a 15\/12\/2025;<\/li>\n\n\n\n<li><strong>Resultado Preliminar Ampla Concorr&ecirc;ncia:<\/strong> 16\/01\/2026;<\/li>\n\n\n\n<li><strong>Resultado Preliminar PPI:<\/strong> 23\/01\/2026;<\/li>\n\n\n\n<li><strong>Resultado Final:<\/strong> at&eacute; 30\/01\/2026.<\/li>\n<\/ul><h3 class=\"wp-block-heading\" id=\"h-vagas-e-especialidades-residencia-medica-unesp-2026\">Vagas e especialidades Resid&ecirc;ncia M&eacute;dica Unesp 2026<\/h3><p>O <strong>processo seletivo para Resid&ecirc;ncia M&eacute;dica da Unesp 2026 ofereceu 196 vagas para especialidades de Acesso Direto<\/strong> e com<strong> Pr&eacute;-Requisito<\/strong>. Confira a distribui&ccedil;&atilde;o:<\/p><h3 class=\"wp-block-heading\" id=\"h-acesso-direto\">Acesso Direto<\/h3><figure class=\"wp-block-table\"><table><thead><tr><th>PROGRAMA<\/th><th class=\"has-text-align-center\" data-align=\"center\">Vagas Previstas<\/th><th class=\"has-text-align-center\" data-align=\"center\">Servi&ccedil;o Militar<\/th><th class=\"has-text-align-center\" data-align=\"center\">Reserva de Vagas PPI<\/th><\/tr><\/thead><tbody><tr><td>Anestesiologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">8<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Cirurgia Cardiovascular<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Cirurgia Geral<\/td><td class=\"has-text-align-center\" data-align=\"center\">13<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><\/tr><tr><td>Cl&iacute;nica M&eacute;dica<\/td><td class=\"has-text-align-center\" data-align=\"center\">30<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><\/tr><tr><td>Dermatologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Ginecologia e Obstetr&iacute;cia<\/td><td class=\"has-text-align-center\" data-align=\"center\">10<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Infectologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Medicina de Emerg&ecirc;ncia<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Medicina de Fam&iacute;lia e Comunidade<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Medicina Intensiva<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Medicina Nuclear<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Neurocirurgia<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Neurologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Oftalmologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Ortopedia e Traumatologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Otorrinolaringologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Patologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Pediatria<\/td><td class=\"has-text-align-center\" data-align=\"center\">17<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><\/tr><tr><td>Psiquiatria<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Radiologia e Diagn&oacute;stico por Imagem<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><\/tbody><\/table><\/figure><h3 class=\"wp-block-heading\" id=\"h-pre-requisito\">Pr&eacute;-Requisito<\/h3><figure class=\"wp-block-table\"><table><thead><tr><th>PROGRAMA<\/th><th class=\"has-text-align-center\" data-align=\"center\">Vagas Previstas<\/th><th class=\"has-text-align-center\" data-align=\"center\">Reserva de Vagas PPI<\/th><\/tr><\/thead><tbody><tr><td>Cardiologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Cirurgia da M&atilde;o<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Cirurgia do Aparelho Digestivo<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Cirurgia Oncol&oacute;gica<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Cirurgia Pedi&aacute;trica<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Cirurgia Pl&aacute;stica<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Cirurgia Tor&aacute;cica<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Cirurgia Vascular<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Endocrinologia e Metabologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Endoscopia<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Gastroenterologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Geriatria<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Hematologia e Hemoterapia<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Mastologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Nefrologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">8<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Oncologia Cl&iacute;nica<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Pneumologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Reumatologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><tr><td>Urologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">&ndash;<\/td><\/tr><\/tbody><\/table><\/figure><h2 class=\"wp-block-heading\" id=\"h-concorrencia-unesp-2026\"><span class=\"ez-toc-section\" id=\"Concorrencia-Unesp-2026\"><\/span>Concorr&ecirc;ncia Unesp 2026<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Foram, ao todo, <strong>4.557 candidatos inscritos<\/strong> no processo seletivo para <strong>196 vagas ofertadas<\/strong>, o que acarreta em uma rela&ccedil;&atilde;o geral de <strong>23,25 candidatos por vaga<\/strong>. Agora, confira como ficou a concorr&ecirc;ncia entre as especialidades:<\/p><figure class=\"wp-block-table\"><table><thead><tr><th>Especialidade<\/th><th class=\"has-text-align-center\" data-align=\"center\">Inscritos<\/th><th class=\"has-text-align-center\" data-align=\"center\">Vagas<\/th><th class=\"has-text-align-center\" data-align=\"center\">Concorr&ecirc;ncia<\/th><\/tr><\/thead><tbody><tr><td>Anestesiologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">299<\/td><td class=\"has-text-align-center\" data-align=\"center\">8<\/td><td class=\"has-text-align-center\" data-align=\"center\">37.38<\/td><\/tr><tr><td>Cardiologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">40<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><td class=\"has-text-align-center\" data-align=\"center\">5.71<\/td><\/tr><tr><td>Cirurgia Cardiovascular<\/td><td class=\"has-text-align-center\" data-align=\"center\">31<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">15.50<\/td><\/tr><tr><td>Cirurgia da M&atilde;o<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">4.00<\/td><\/tr><tr><td>Cirurgia do Aparelho Digestivo<\/td><td class=\"has-text-align-center\" data-align=\"center\">11<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">2.75<\/td><\/tr><tr><td>Cirurgia Geral<\/td><td class=\"has-text-align-center\" data-align=\"center\">498<\/td><td class=\"has-text-align-center\" data-align=\"center\">13<\/td><td class=\"has-text-align-center\" data-align=\"center\">38.31<\/td><\/tr><tr><td>Cirurgia Oncol&oacute;gica<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">1.00<\/td><\/tr><tr><td>Cirurgia Pedi&aacute;trica<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">7.00<\/td><\/tr><tr><td>Cirurgia Pl&aacute;stica<\/td><td class=\"has-text-align-center\" data-align=\"center\">80<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">40.00<\/td><\/tr><tr><td>Cirurgia Tor&aacute;cica<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">3.00<\/td><\/tr><tr><td>Cirurgia Vascular<\/td><td class=\"has-text-align-center\" data-align=\"center\">11<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><td class=\"has-text-align-center\" data-align=\"center\">3.67<\/td><\/tr><tr><td>Cl&iacute;nica M&eacute;dica<\/td><td class=\"has-text-align-center\" data-align=\"center\">663<\/td><td class=\"has-text-align-center\" data-align=\"center\">30<\/td><td class=\"has-text-align-center\" data-align=\"center\">22.10<\/td><\/tr><tr><td>Dermatologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">350<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><td class=\"has-text-align-center\" data-align=\"center\">58.33<\/td><\/tr><tr><td>Endocrinologia e Metabologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">55<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><td class=\"has-text-align-center\" data-align=\"center\">18.33<\/td><\/tr><tr><td>Endoscopia<\/td><td class=\"has-text-align-center\" data-align=\"center\">14<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">7.00<\/td><\/tr><tr><td>Gastroenterologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">39<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">9.75<\/td><\/tr><tr><td>Geriatria<\/td><td class=\"has-text-align-center\" data-align=\"center\">28<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">7.00<\/td><\/tr><tr><td>Ginecologia e Obstetr&iacute;cia<\/td><td class=\"has-text-align-center\" data-align=\"center\">352<\/td><td class=\"has-text-align-center\" data-align=\"center\">10<\/td><td class=\"has-text-align-center\" data-align=\"center\">35.20<\/td><\/tr><tr><td>Hematologia e Hemoterapia<\/td><td class=\"has-text-align-center\" data-align=\"center\">22<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">5.50<\/td><\/tr><tr><td>Infectologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">33<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">8.25<\/td><\/tr><tr><td>Mastologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">3.00<\/td><\/tr><tr><td>Medicina de Emerg&ecirc;ncia<\/td><td class=\"has-text-align-center\" data-align=\"center\">29<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">7.25<\/td><\/tr><tr><td>Medicina de Fam&iacute;lia e Comunidade<\/td><td class=\"has-text-align-center\" data-align=\"center\">29<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">7.25<\/td><\/tr><tr><td>Medicina Intensiva<\/td><td class=\"has-text-align-center\" data-align=\"center\">23<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">11.50<\/td><\/tr><tr><td>Medicina Nuclear<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">7.00<\/td><\/tr><tr><td>Nefrologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">21<\/td><td class=\"has-text-align-center\" data-align=\"center\">8<\/td><td class=\"has-text-align-center\" data-align=\"center\">2.63<\/td><\/tr><tr><td>Neurocirurgia<\/td><td class=\"has-text-align-center\" data-align=\"center\">112<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">56.00<\/td><\/tr><tr><td>Neurologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">150<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><td class=\"has-text-align-center\" data-align=\"center\">30.00<\/td><\/tr><tr><td>Oftalmologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">279<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><td class=\"has-text-align-center\" data-align=\"center\">39.86<\/td><\/tr><tr><td>Oncologia Cl&iacute;nica<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">7.00<\/td><\/tr><tr><td>Ortopedia e Traumatologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">203<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><td class=\"has-text-align-center\" data-align=\"center\">33.83<\/td><\/tr><tr><td>Otorrinolaringologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">211<\/td><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">52.75<\/td><\/tr><tr><td>Patologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">51<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><td class=\"has-text-align-center\" data-align=\"center\">17.00<\/td><\/tr><tr><td>Pediatria<\/td><td class=\"has-text-align-center\" data-align=\"center\">318<\/td><td class=\"has-text-align-center\" data-align=\"center\">17<\/td><td class=\"has-text-align-center\" data-align=\"center\">18.71<\/td><\/tr><tr><td>Pneumologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">18<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><td class=\"has-text-align-center\" data-align=\"center\">6.00<\/td><\/tr><tr><td>Psiquiatria<\/td><td class=\"has-text-align-center\" data-align=\"center\">341<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><td class=\"has-text-align-center\" data-align=\"center\">56.83<\/td><\/tr><tr><td>Radiologia e Diagn&oacute;stico por Imagem<\/td><td class=\"has-text-align-center\" data-align=\"center\">175<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><td class=\"has-text-align-center\" data-align=\"center\">25.00<\/td><\/tr><tr><td>Reumatologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">16<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">8.00<\/td><\/tr><tr><td>Urologia<\/td><td class=\"has-text-align-center\" data-align=\"center\">20<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">10.00<\/td><\/tr><\/tbody><\/table><\/figure><h2 class=\"wp-block-heading\" id=\"h-estudando-para-a-prova-da-unesp-2027\"><span class=\"ez-toc-section\" id=\"Estudando-para-a-prova-da-Unesp-2027\"><\/span>Estudando para a prova da Unesp 2027?<span class=\"ez-toc-section-end\"><\/span><\/h2><p>O aluno que est&aacute; interessado nas provas para Resid&ecirc;ncia M&eacute;dica deve sempre escolher um <strong>m&eacute;todo de estudo que seja eficaz<\/strong> e &eacute; por isso que <strong>a resolu&ccedil;&atilde;o de quest&otilde;es &eacute; uma pr&aacute;tica essencial<\/strong>.<\/p><p>Ao estudar por quest&otilde;es, os candidatos se familiarizam com o estilo da prova, calculam seu tempo de resolu&ccedil;&atilde;o e tamb&eacute;m identificam as mat&eacute;rias que mais exigem sua aten&ccedil;&atilde;o.&nbsp;<\/p><p>Por isso, se voc&ecirc; est&aacute; se <strong>preparando para um concurso de resid&ecirc;ncia m&eacute;dica<\/strong>, confira o <a href=\"https:\/\/med.estrategia.com\/portal\/evento-emed\/sistemas-de-questoes-estrategia-med\/\" target=\"_blank\"><strong>Banco de Quest&otilde;es MED<\/strong><\/a>! No <a href=\"https:\/\/med.estrategiaeducacional.com.br\/\" target=\"_blank\">BQMED<\/a>, os alunos montam seus pr&oacute;prios simulados e organizam sua rotina de estudos de acordo com suas necessidades. Venha estudar de maneira inovadora com o Estrat&eacute;gia MED!&nbsp;&nbsp;<\/p><p>\n\n\n\n<a id=\"cta\" class=\"cta-imagem\" href=\"https:\/\/med.estrategia.com\/curso\/banco-de-questes-resumos-estrategicos-anual\/\" target=\"blank\">\n                <img decoding=\"async\" width=\"100%\" src=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2025\/08\/banco_questoes.png\" alt=\"banco_questoes\" title=\"banco_questoes\">\n        <\/a>\n\n\n\n<\/p><h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Veja-tambem\"><\/span>Veja tamb&eacute;m:<span class=\"ez-toc-section-end\"><\/span><\/h2><ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/usp-sp-residencia-medica\/\">Resid&ecirc;ncia M&eacute;dica USP SP&nbsp;<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/usp-rp-residencia-medica\/\">Resid&ecirc;ncia M&eacute;dica USP RP<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/sus-sp-residencia-medica\/\">Resid&ecirc;ncia M&eacute;dica SUS SP<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/sms-sp-residencia-medica\/\">Resid&ecirc;ncia M&eacute;dica SMS SP (Susinho)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/iamspe-residencia-medica\/\">Resid&ecirc;ncia M&eacute;dica IAMSPE<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencia-medica-unicamp\/\">Resid&ecirc;ncia M&eacute;dica Unicamp<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unifesp-residencia-medica\/\">Resid&ecirc;ncia M&eacute;dica Unifesp<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/especialidades\/10-residencias-medicas-com-mais-vagas-por-especialidade\/\">10 Resid&ecirc;ncias M&eacute;dicas com mais vagas por especialidade<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/residencias-medicas-mais-concorridos\/\">10 Resid&ecirc;ncias M&eacute;dicas mais concorridas<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/enare-vagas-cronograma-provas-edital\/\">Resid&ecirc;ncia M&eacute;dica ENARE<\/a><\/li>\n<\/ul><\/p>\n","protected":false},"excerpt":{"rendered":"Quer saber tudo sobre o processo seletivo para Resid&ecirc;ncia M&eacute;dica da Unesp? Se voc&ecirc; est&aacute; interessado na sele&ccedil;&atilde;o,&hellip;\n","protected":false},"author":22,"featured_media":39316,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wl_entities_gutenberg":"","footnotes":""},"categories":[24],"tags":[],"wl_entity_type":[199],"class_list":{"0":"post-3154","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-residencia-medica","8":"wl_entity_type-article"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Resid\u00eancia M\u00e9dica Unesp: edital, vagas, cronograma e mais<\/title>\n<meta name=\"description\" content=\"Confira todas as informa\u00e7\u00f5es sobre a prova de Resid\u00eancia M\u00e9dica da Unesp aqui! Tire as suas d\u00favidas sobre esse exame!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resid\u00eancia M\u00e9dica Unesp: edital, vagas, cronograma e mais\" \/>\n<meta property=\"og:description\" content=\"Confira todas as informa\u00e7\u00f5es sobre a prova de Resid\u00eancia M\u00e9dica da Unesp aqui! Tire as suas d\u00favidas sobre esse exame!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia MED\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/estrategiamed1\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-08T14:43:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-03T16:40:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/01\/coverWP_publica_bgfoto_logo-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erika Coelho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@estrategiamed_\" \/>\n<meta name=\"twitter:site\" content=\"@estrategiamed_\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erika Coelho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/\",\"url\":\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/\",\"name\":\"Resid\u00eancia M\u00e9dica Unesp: edital, vagas, cronograma e mais\",\"isPartOf\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/01\/coverWP_publica_bgfoto_logo-11.jpg\",\"datePublished\":\"2024-01-08T14:43:00+00:00\",\"dateModified\":\"2026-06-03T16:40:30+00:00\",\"author\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/8e7c9b2f53f2eede3b8880ad86ff20a3\"},\"description\":\"Confira todas as informa\u00e7\u00f5es sobre a prova de Resid\u00eancia M\u00e9dica da Unesp aqui! Tire as suas d\u00favidas sobre esse exame!\",\"breadcrumb\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#primaryimage\",\"url\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/01\/coverWP_publica_bgfoto_logo-11.jpg\",\"contentUrl\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/01\/coverWP_publica_bgfoto_logo-11.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Cr\u00e9ditos: Estrat\u00e9gia MED e FMB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/med.estrategia.com\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resid\u00eancia M\u00e9dica\",\"item\":\"https:\/\/med.estrategia.com\/portal\/residencia-medica\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Resid\u00eancia M\u00e9dica Unesp: edital, vagas, cronograma e mais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#website\",\"url\":\"https:\/\/med.estrategia.com\/portal\/\",\"name\":\"Estrat\u00e9gia MED\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/med.estrategia.com\/portal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/8e7c9b2f53f2eede3b8880ad86ff20a3\",\"name\":\"Erika Coelho\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8ef9ff2e2fa53829c640cca8d1a45178?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8ef9ff2e2fa53829c640cca8d1a45178?s=96&d=mm&r=g\",\"caption\":\"Erika Coelho\"},\"description\":\"Jornalista pela Universidade Presbiteriana Mackenzie, escrevo sobre educa\u00e7\u00e3o, sa\u00fade e pol\u00edticas p\u00fablicas\",\"url\":\"https:\/\/med.estrategia.com\/portal\/author\/erika\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resid\u00eancia M\u00e9dica Unesp: edital, vagas, cronograma e mais","description":"Confira todas as informa\u00e7\u00f5es sobre a prova de Resid\u00eancia M\u00e9dica da Unesp aqui! Tire as suas d\u00favidas sobre esse exame!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/","og_locale":"pt_BR","og_type":"article","og_title":"Resid\u00eancia M\u00e9dica Unesp: edital, vagas, cronograma e mais","og_description":"Confira todas as informa\u00e7\u00f5es sobre a prova de Resid\u00eancia M\u00e9dica da Unesp aqui! Tire as suas d\u00favidas sobre esse exame!","og_url":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/","og_site_name":"Estrat\u00e9gia MED","article_publisher":"https:\/\/www.facebook.com\/estrategiamed1","article_published_time":"2024-01-08T14:43:00+00:00","article_modified_time":"2026-06-03T16:40:30+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/01\/coverWP_publica_bgfoto_logo-11.jpg","type":"image\/jpeg"}],"author":"Erika Coelho","twitter_card":"summary_large_image","twitter_creator":"@estrategiamed_","twitter_site":"@estrategiamed_","twitter_misc":{"Escrito por":"Erika Coelho","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/","url":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/","name":"Resid\u00eancia M\u00e9dica Unesp: edital, vagas, cronograma e mais","isPartOf":{"@id":"https:\/\/med.estrategia.com\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#primaryimage"},"image":{"@id":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#primaryimage"},"thumbnailUrl":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/01\/coverWP_publica_bgfoto_logo-11.jpg","datePublished":"2024-01-08T14:43:00+00:00","dateModified":"2026-06-03T16:40:30+00:00","author":{"@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/8e7c9b2f53f2eede3b8880ad86ff20a3"},"description":"Confira todas as informa\u00e7\u00f5es sobre a prova de Resid\u00eancia M\u00e9dica da Unesp aqui! Tire as suas d\u00favidas sobre esse exame!","breadcrumb":{"@id":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#primaryimage","url":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/01\/coverWP_publica_bgfoto_logo-11.jpg","contentUrl":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2021\/01\/coverWP_publica_bgfoto_logo-11.jpg","width":1200,"height":800,"caption":"Cr\u00e9ditos: Estrat\u00e9gia MED e FMB"},{"@type":"BreadcrumbList","@id":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/unesp-residencia-medica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/med.estrategia.com\/portal\/"},{"@type":"ListItem","position":2,"name":"Resid\u00eancia M\u00e9dica","item":"https:\/\/med.estrategia.com\/portal\/residencia-medica\/"},{"@type":"ListItem","position":3,"name":"Resid\u00eancia M\u00e9dica Unesp: edital, vagas, cronograma e mais"}]},{"@type":"WebSite","@id":"https:\/\/med.estrategia.com\/portal\/#website","url":"https:\/\/med.estrategia.com\/portal\/","name":"Estrat\u00e9gia MED","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/med.estrategia.com\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/8e7c9b2f53f2eede3b8880ad86ff20a3","name":"Erika Coelho","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8ef9ff2e2fa53829c640cca8d1a45178?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ef9ff2e2fa53829c640cca8d1a45178?s=96&d=mm&r=g","caption":"Erika Coelho"},"description":"Jornalista pela Universidade Presbiteriana Mackenzie, escrevo sobre educa\u00e7\u00e3o, sa\u00fade e pol\u00edticas p\u00fablicas","url":"https:\/\/med.estrategia.com\/portal\/author\/erika\/"}]}},"_wl_alt_label":[],"wl:entity_url":"\/post\/unesp-residencia-medica","_links":{"self":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/3154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/comments?post=3154"}],"version-history":[{"count":118,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/3154\/revisions"}],"predecessor-version":[{"id":110910,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/3154\/revisions\/110910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/media\/39316"}],"wp:attachment":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/media?parent=3154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/categories?post=3154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/tags?post=3154"},{"taxonomy":"wl_entity_type","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/wl_entity_type?post=3154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}