{"id":61185,"date":"2024-04-08T16:50:14","date_gmt":"2024-04-08T19:50:14","guid":{"rendered":"https:\/\/med.estrategia.com\/portal\/?p=61185"},"modified":"2024-04-08T16:51:55","modified_gmt":"2024-04-08T19:51:55","slug":"governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa","status":"publish","type":"post","link":"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/","title":{"rendered":"Governo lan\u00e7a 6\u00aa edi\u00e7\u00e3o da Caderneta de Sa\u00fade da Crian\u00e7a ap\u00f3s tr\u00eas anos suspensa"},"content":{"rendered":"<p>O <strong>Minist&eacute;rio da Sa&uacute;de<\/strong> lan&ccedil;ou a <strong>6&ordf; edi&ccedil;&atilde;o da Caderneta de Sa&uacute;de da Crian&ccedil;a<\/strong> na &uacute;ltima sexta-feira (5), documento vital para o <strong>acompanhamento da sa&uacute;de infantil<\/strong> no Brasil. <strong>Ap&oacute;s um hiato de tr&ecirc;s anos<\/strong> sem sua distribui&ccedil;&atilde;o, a caderneta retorna com importantes <strong>atualiza&ccedil;&otilde;es e recursos<\/strong>, fornecendo suporte essencial para profissionais da sa&uacute;de e cuidadores.<p>Esta nova vers&atilde;o da Caderneta de Sa&uacute;de da Crian&ccedil;a apresenta atualiza&ccedil;&otilde;es, com destaque para o <strong>calend&aacute;rio do Programa Nacional de Imuniza&ccedil;&otilde;es (PNI)<\/strong>, agora <strong>incorporando doses contra a COVID-19<\/strong>, dispon&iacute;veis para crian&ccedil;as a partir dos seis meses de idade. Al&eacute;m disso, o Minist&eacute;rio da Sa&uacute;de planeja <strong>integrar o documento com o aplicativo Meu SUS Digital<\/strong>.<\/p><p>Al&eacute;m de servir como um guia abrangente para fam&iacute;lias e profissionais da sa&uacute;de acompanharem o <strong>ciclo vacinal das crian&ccedil;as<\/strong>, a caderneta, tamb&eacute;m conhecida como &ldquo;Passaporte da Cidadania&rdquo;, oferece <strong>orienta&ccedil;&otilde;es para reduzir a mortalidade infantil<\/strong> e promover um desenvolvimento saud&aacute;vel.<\/p><p>Durante a pandemia de COVID-19, a <strong>impress&atilde;o e distribui&ccedil;&atilde;o da Caderneta foram suspensas<\/strong>. A empresa contratada pelo Minist&eacute;rio enfrentou dificuldades na obten&ccedil;&atilde;o de mat&eacute;ria-prima e, eventualmente, encerrou suas opera&ccedil;&otilde;es, resultando no rompimento do contrato.<\/p><p>\n\n\n<div id=\"new-form\">\n\t<form id=\"forms_layout\">\n\t<input type=\"hidden\" id=\"chave_de\" name=\"chave_de\" value=\"01_EMED_LEADS_TOTAIS\" \/>\n\t\t<input type=\"hidden\" id=\"mid\" name=\"mid\" value=\"515009018\" \/>\n\t\t<input type=\"hidden\" id=\"Objetivo\" name=\"Objetivo\" value=\"Medicina\" \/>\n\t\t<input type=\"hidden\" id=\"Estado_de_Origem_do_IP\" name=\"Estado_de_Origem_do_IP\"  value=\"\" \/>\n\t\t<input type=\"hidden\" id=\"Cidade_de_Origem_do_IP\" name=\"Cidade_de_Origem_do_IP\" value=\"\" \/>\n\t\t<input type=\"hidden\" id=\"Modo_de_entrada\" name=\"Modo_de_entrada\" value=\"Portal\" \/>\n\t\t<input type=\"hidden\" id=\"Pagina_Origem\" name=\"Pagina_Origem\" value=\"\" \/>\n\n\t\t<div class=\"texto\">\n\t\t\t<h3 class=\"news\">Inscreva-se em nossa newsletter!<\/h3>\n\t\t\t<p>Receba not\u00edcias sobre resid\u00eancia m\u00e9dica, revalida\u00e7\u00e3o de diplomas e concursos m\u00e9dicos, al\u00e9m de materiais de estudo gratuitos e informa\u00e7\u00f5es relevantes do mundo da Medicina.<\/p>\n\t\t<\/div>\n\t\t<div class=\"campos\">\n\t\t\t<div class=\"first_name labels\">\n\t\t\t\t<input type=\"text\" class=\"input_labels\" id=\"first_name\" name=\"Nome_Completo\" placeholder=\"Nome\" required \/>\n\t\t\t<\/div>\n\t\t\t<div class=\"email labels\">\n\t\t\t\t<input type=\"email\" class=\"input_labels\" id=\"email\" name=\"Email\" placeholder=\"E-mail\" required \/>\n\t\t\t<\/div>\n\t\t\t<button type=\"submit\" class=\"button_layout\">\n\t\t\t\t<div id=\"lblBotao\">Inscreva-se<\/div>\n\t\t\t\t<span id=\"divSpiner\" class=\"loader\" role=\"status\" style=\"display: none;\"><\/span>\t\n\t\t\t<\/button>\n\t\t<\/div><!-- \/campos -->\n\t\t\n\t\t<label class=\"container_checkbox\">Voc\u00ea concorda com a nossa\n\t\t\t<a class=\"politics_privacy_ahref\" target=\"_blank\" href=\"https:\/\/gratis.estrategiaconcursos.com.br\/politica-de-privacidade\/\">Pol\u00edtica de Privacidade<\/a> e aceita receber informa\u00e7\u00f5es adicionais do Estrat\u00e9gia Educacional.\n\t\t\t<input id=\"checkbox_layout\" type=\"checkbox\" checked=\"checked\" required \/>\n\t\t\t<span class=\"checkbox\"><\/span>\n\t\t<\/label>\n\t\t<div id=\"msg\"><\/div>\n\t\t<div id=\"error\" class=\"error\">\n\t\t<\/div>\n\t<\/form>\n<\/div><!-- \/new-form -->\n\n\n\n<\/p><h2 class=\"wp-block-heading\" id=\"h-conheca-a-caderneta\">Conhe&ccedil;a a Caderneta<\/h2><p>A Caderneta funciona como um <strong>registro de sa&uacute;de para crian&ccedil;as at&eacute; 9 anos<\/strong>, documentando o <strong>hist&oacute;rico de vacina&ccedil;&atilde;o<\/strong> e fornecendo <strong>orienta&ccedil;&otilde;es<\/strong> sobre <strong>desenvolvimento f&iacute;sico e mental<\/strong>, <strong>educa&ccedil;&atilde;o<\/strong>, <strong>direitos infantis<\/strong> e <strong>preven&ccedil;&atilde;o de viol&ecirc;ncias<\/strong>.<\/p><p>Dividido em <strong>duas partes<\/strong>, o livreto destina-se tanto aos respons&aacute;veis pelas crian&ccedil;as quanto aos <strong>profissionais de sa&uacute;de<\/strong>. A <strong>primeira se&ccedil;&atilde;o<\/strong> oferece informa&ccedil;&otilde;es essenciais sobre <strong>amamenta&ccedil;&atilde;o<\/strong>, <strong>preven&ccedil;&atilde;o de acidentes<\/strong> e a <strong>import&acirc;ncia do afeto<\/strong>. J&aacute; a <strong>segunda parte<\/strong> &eacute; <strong>direcionada aos profissionais de sa&uacute;de<\/strong>, servindo como um <strong>instrumento de apoio<\/strong> ao trabalho das equipes de <strong>aten&ccedil;&atilde;o prim&aacute;ria<\/strong>, permitindo o <strong>registro de consultas<\/strong> e o <strong>acompanhamento do desenvolvimento das crian&ccedil;as<\/strong>.<\/p><p>O Minist&eacute;rio da Sa&uacute;de<strong> investiu 17,9 milh&otilde;es<\/strong> de reais na <strong>produ&ccedil;&atilde;o de 6,5 milh&otilde;es de exemplares da Caderneta<\/strong>, suficientes para <strong>cobrir todos os beb&ecirc;s nascidos no pa&iacute;s ao longo de dois anos<\/strong>. Metade desses exemplares ser&aacute; distribu&iacute;da no primeiro semestre de 2024, com prioridade para os <strong>Distritos Sanit&aacute;rios Especiais Ind&iacute;genas (DSEIs)<\/strong>, unidades de responsabilidade sanit&aacute;ria federal que abrangem terras ind&iacute;genas.<\/p><p>A <strong>distribui&ccedil;&atilde;o<\/strong> da Caderneta ocorre atrav&eacute;s das <strong>secretarias de Sa&uacute;de das capitais<\/strong> e das <strong>secretarias estaduais de Sa&uacute;de<\/strong>, que as redistribuem para os munic&iacute;pios. A entrega foi priorizada nas regi&otilde;es Norte e Nordeste, que apresentam os piores &iacute;ndices de sa&uacute;de infantil.<\/p><p>Al&eacute;m da vers&atilde;o f&iacute;sica, a Caderneta tamb&eacute;m estar&aacute; dispon&iacute;vel em <strong>formato digital<\/strong>, adaptada para meninas e meninos. A nova edi&ccedil;&atilde;o tamb&eacute;m apresenta uma mudan&ccedil;a visual, com capas de cores distintas: verde para os meninos e roxo para as meninas.<\/p><div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/bvsms.saude.gov.br\/bvs\/publicacoes\/caderneta_crianca_menino_6ed.pdf\" target=\"_blank\">Caderneta menino<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/bvsms.saude.gov.br\/bvs\/publicacoes\/caderneta_crianca_menina_6ed.pdf\" target=\"_blank\">caderneta menina<\/a><\/div>\n<\/div><p>Para n&atilde;o perder nenhuma atualiza&ccedil;&atilde;o no universo da medicina e ficar por dentro dos seletivos de Resid&ecirc;ncia M&eacute;dica, de revalida&ccedil;&atilde;o de diplomas e conte&uacute;dos t&eacute;cnicos, continue acessando o&nbsp;<a href=\"https:\/\/med.estrategia.com\/portal\/\" target=\"_blank\">Portal do Estrat&eacute;gia MED<\/a>!<\/p><figure class=\"wp-block-image size-large\"><a href=\"https:\/\/med.estrategia.com\/curso\/curso-prova-pratica-para-residencia-medica-e-revalida-on-line\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"498\" src=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2022\/09\/prova_pratica-1024x498.jpg\" alt=\"\" class=\"wp-image-110851\" srcset=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2022\/09\/prova_pratica-1024x498.jpg 1024w, https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2022\/09\/prova_pratica-768x373.jpg 768w, https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2022\/09\/prova_pratica-800x389.jpg 800w, https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2022\/09\/prova_pratica-1160x564.jpg 1160w, https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2022\/09\/prova_pratica.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/p>\n","protected":false},"excerpt":{"rendered":"O Minist\u00e9rio da Sa\u00fade investiu 17,9 milh\u00f5es de reais na produ\u00e7\u00e3o de 6,5 milh\u00f5es de exemplares da Caderneta, suficientes para cobrir todos os beb\u00eas nascidos no pa\u00eds ao longo de dois anos\n","protected":false},"author":52,"featured_media":61187,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wl_entities_gutenberg":"","footnotes":""},"categories":[300],"tags":[],"wl_entity_type":[199],"class_list":{"0":"post-61185","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias","8":"wl_entity_type-article"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Governo lan\u00e7a 6\u00aa edi\u00e7\u00e3o da Caderneta de Sa\u00fade da Crian\u00e7a ap\u00f3s tr\u00eas anos suspensa<\/title>\n<meta name=\"description\" content=\"O Minist\u00e9rio da Sa\u00fade lan\u00e7ou a 6\u00aa edi\u00e7\u00e3o da Caderneta de Sa\u00fade da Crian\u00e7a na \u00faltima sexta-feira (5), documento vital para o acompanhamento da sa\u00fade infantil no Brasil. Ap\u00f3s um hiato de tr\u00eas anos sem sua distribui\u00e7\u00e3o, a caderneta retorna com importantes atualiza\u00e7\u00f5es e recursos, fornecendo suporte essencial para profissionais da sa\u00fade e cuidadores.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo lan\u00e7a 6\u00aa edi\u00e7\u00e3o da Caderneta de Sa\u00fade da Crian\u00e7a ap\u00f3s tr\u00eas anos suspensa\" \/>\n<meta property=\"og:description\" content=\"O Minist\u00e9rio da Sa\u00fade lan\u00e7ou a 6\u00aa edi\u00e7\u00e3o da Caderneta de Sa\u00fade da Crian\u00e7a na \u00faltima sexta-feira (5), documento vital para o acompanhamento da sa\u00fade infantil no Brasil. Ap\u00f3s um hiato de tr\u00eas anos sem sua distribui\u00e7\u00e3o, a caderneta retorna com importantes atualiza\u00e7\u00f5es e recursos, fornecendo suporte essencial para profissionais da sa\u00fade e cuidadores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia MED\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/estrategiamed1\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-08T19:50:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-08T19:51:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2024\/04\/caderneta-vacicacao-infantil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arion Wolff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@estrategiamed_\" \/>\n<meta name=\"twitter:site\" content=\"@estrategiamed_\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arion Wolff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/\",\"url\":\"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/\",\"name\":\"Governo lan\u00e7a 6\u00aa edi\u00e7\u00e3o da Caderneta de Sa\u00fade da Crian\u00e7a ap\u00f3s tr\u00eas anos suspensa\",\"isPartOf\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2024\/04\/caderneta-vacicacao-infantil.jpg\",\"datePublished\":\"2024-04-08T19:50:14+00:00\",\"dateModified\":\"2024-04-08T19:51:55+00:00\",\"author\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/b6aba49604868a427dd15c3b1fc6a8bc\"},\"description\":\"O Minist\u00e9rio da Sa\u00fade lan\u00e7ou a 6\u00aa edi\u00e7\u00e3o da Caderneta de Sa\u00fade da Crian\u00e7a na \u00faltima sexta-feira (5), documento vital para o acompanhamento da sa\u00fade infantil no Brasil. Ap\u00f3s um hiato de tr\u00eas anos sem sua distribui\u00e7\u00e3o, a caderneta retorna com importantes atualiza\u00e7\u00f5es e recursos, fornecendo suporte essencial para profissionais da sa\u00fade e cuidadores.\",\"breadcrumb\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/#primaryimage\",\"url\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2024\/04\/caderneta-vacicacao-infantil.jpg\",\"contentUrl\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2024\/04\/caderneta-vacicacao-infantil.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Estrat\u00e9gia Med | Imagem: Minist\u00e9rio da Sa\u00fade\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/med.estrategia.com\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/med.estrategia.com\/portal\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Governo lan\u00e7a 6\u00aa edi\u00e7\u00e3o da Caderneta de Sa\u00fade da Crian\u00e7a ap\u00f3s tr\u00eas anos suspensa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#website\",\"url\":\"https:\/\/med.estrategia.com\/portal\/\",\"name\":\"Estrat\u00e9gia MED\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/med.estrategia.com\/portal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/b6aba49604868a427dd15c3b1fc6a8bc\",\"name\":\"Arion Wolff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2023\/12\/arion-wolff-estrategia-med-150x150.jpg\",\"contentUrl\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2023\/12\/arion-wolff-estrategia-med-150x150.jpg\",\"caption\":\"Arion Wolff\"},\"description\":\"Jornalista formado pela UNIFATEC e p\u00f3s-graduado em Jornalismo Digital pela UNINTER. Escrevo sobre medicina, resid\u00eancia m\u00e9dica e sa\u00fade. Entusiasta de filmes, livros, bons dramas e romances gen\u00e9ricos.\",\"sameAs\":[\"http:\/\/med.estrategia.com\"],\"url\":\"https:\/\/med.estrategia.com\/portal\/author\/arion-santos\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Governo lan\u00e7a 6\u00aa edi\u00e7\u00e3o da Caderneta de Sa\u00fade da Crian\u00e7a ap\u00f3s tr\u00eas anos suspensa","description":"O Minist\u00e9rio da Sa\u00fade lan\u00e7ou a 6\u00aa edi\u00e7\u00e3o da Caderneta de Sa\u00fade da Crian\u00e7a na \u00faltima sexta-feira (5), documento vital para o acompanhamento da sa\u00fade infantil no Brasil. Ap\u00f3s um hiato de tr\u00eas anos sem sua distribui\u00e7\u00e3o, a caderneta retorna com importantes atualiza\u00e7\u00f5es e recursos, fornecendo suporte essencial para profissionais da sa\u00fade e cuidadores.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo lan\u00e7a 6\u00aa edi\u00e7\u00e3o da Caderneta de Sa\u00fade da Crian\u00e7a ap\u00f3s tr\u00eas anos suspensa","og_description":"O Minist\u00e9rio da Sa\u00fade lan\u00e7ou a 6\u00aa edi\u00e7\u00e3o da Caderneta de Sa\u00fade da Crian\u00e7a na \u00faltima sexta-feira (5), documento vital para o acompanhamento da sa\u00fade infantil no Brasil. Ap\u00f3s um hiato de tr\u00eas anos sem sua distribui\u00e7\u00e3o, a caderneta retorna com importantes atualiza\u00e7\u00f5es e recursos, fornecendo suporte essencial para profissionais da sa\u00fade e cuidadores.","og_url":"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/","og_site_name":"Estrat\u00e9gia MED","article_publisher":"https:\/\/www.facebook.com\/estrategiamed1","article_published_time":"2024-04-08T19:50:14+00:00","article_modified_time":"2024-04-08T19:51:55+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2024\/04\/caderneta-vacicacao-infantil.jpg","type":"image\/jpeg"}],"author":"Arion Wolff","twitter_card":"summary_large_image","twitter_creator":"@estrategiamed_","twitter_site":"@estrategiamed_","twitter_misc":{"Escrito por":"Arion Wolff","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/","url":"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/","name":"Governo lan\u00e7a 6\u00aa edi\u00e7\u00e3o da Caderneta de Sa\u00fade da Crian\u00e7a ap\u00f3s tr\u00eas anos suspensa","isPartOf":{"@id":"https:\/\/med.estrategia.com\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/#primaryimage"},"image":{"@id":"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/#primaryimage"},"thumbnailUrl":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2024\/04\/caderneta-vacicacao-infantil.jpg","datePublished":"2024-04-08T19:50:14+00:00","dateModified":"2024-04-08T19:51:55+00:00","author":{"@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/b6aba49604868a427dd15c3b1fc6a8bc"},"description":"O Minist\u00e9rio da Sa\u00fade lan\u00e7ou a 6\u00aa edi\u00e7\u00e3o da Caderneta de Sa\u00fade da Crian\u00e7a na \u00faltima sexta-feira (5), documento vital para o acompanhamento da sa\u00fade infantil no Brasil. Ap\u00f3s um hiato de tr\u00eas anos sem sua distribui\u00e7\u00e3o, a caderneta retorna com importantes atualiza\u00e7\u00f5es e recursos, fornecendo suporte essencial para profissionais da sa\u00fade e cuidadores.","breadcrumb":{"@id":"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/#primaryimage","url":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2024\/04\/caderneta-vacicacao-infantil.jpg","contentUrl":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2024\/04\/caderneta-vacicacao-infantil.jpg","width":1920,"height":1080,"caption":"Estrat\u00e9gia Med | Imagem: Minist\u00e9rio da Sa\u00fade"},{"@type":"BreadcrumbList","@id":"https:\/\/med.estrategia.com\/portal\/noticias\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/med.estrategia.com\/portal\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/med.estrategia.com\/portal\/noticias\/"},{"@type":"ListItem","position":3,"name":"Governo lan\u00e7a 6\u00aa edi\u00e7\u00e3o da Caderneta de Sa\u00fade da Crian\u00e7a ap\u00f3s tr\u00eas anos suspensa"}]},{"@type":"WebSite","@id":"https:\/\/med.estrategia.com\/portal\/#website","url":"https:\/\/med.estrategia.com\/portal\/","name":"Estrat\u00e9gia MED","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/med.estrategia.com\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/b6aba49604868a427dd15c3b1fc6a8bc","name":"Arion Wolff","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/image\/","url":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2023\/12\/arion-wolff-estrategia-med-150x150.jpg","contentUrl":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2023\/12\/arion-wolff-estrategia-med-150x150.jpg","caption":"Arion Wolff"},"description":"Jornalista formado pela UNIFATEC e p\u00f3s-graduado em Jornalismo Digital pela UNINTER. Escrevo sobre medicina, resid\u00eancia m\u00e9dica e sa\u00fade. Entusiasta de filmes, livros, bons dramas e romances gen\u00e9ricos.","sameAs":["http:\/\/med.estrategia.com"],"url":"https:\/\/med.estrategia.com\/portal\/author\/arion-santos\/"}]}},"_wl_alt_label":[],"wl:entity_url":"\/post\/governo-lanca-6a-edicao-da-caderneta-de-saude-da-crianca-apos-tres-anos-suspensa","_links":{"self":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/61185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/comments?post=61185"}],"version-history":[{"count":3,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/61185\/revisions"}],"predecessor-version":[{"id":61189,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/61185\/revisions\/61189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/media\/61187"}],"wp:attachment":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/media?parent=61185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/categories?post=61185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/tags?post=61185"},{"taxonomy":"wl_entity_type","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/wl_entity_type?post=61185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}