{"id":64792,"date":"2024-06-12T09:11:06","date_gmt":"2024-06-12T12:11:06","guid":{"rendered":"https:\/\/med.estrategia.com\/portal\/?p=64792"},"modified":"2024-06-12T09:19:02","modified_gmt":"2024-06-12T12:19:02","slug":"5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas","status":"publish","type":"post","link":"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/","title":{"rendered":"5 quest\u00f5es sobre Doen\u00e7as Exantem\u00e1ticas que j\u00e1 ca\u00edram nas provas"},"content":{"rendered":"<p class=\"wp-block-paragraph\">As <strong>doen&ccedil;as exantem&aacute;ticas <\/strong>s&atilde;o um tema de grande relev&acirc;ncia entre quest&otilde;es de Infectologia no bloco de Pediatria em provas de resid&ecirc;ncia m&eacute;dica e revalida&ccedil;&atilde;o, exigindo que os candidatos tenham uma compreens&atilde;o s&oacute;lida do assunto. Ter familiaridade com a <strong>defini&ccedil;&atilde;o<\/strong>, a <strong>etiologia das doen&ccedil;as exantem&aacute;ticas na inf&acirc;ncia<\/strong>, suas <strong>manifesta&ccedil;&otilde;es cl&iacute;nicas<\/strong>, entre outros t&oacute;picos &eacute; fundamental para alcan&ccedil;ar um bom desempenho. Ent&atilde;o, para aqueles que querem mandar bem na prova, veja abaixo 5 quest&otilde;es resolvidas para praticar e revisar o tema!<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-transparent ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">Navegue pelo conte\u00fado<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#O-que-sao-as-doencas-exantematicas\" >O que s&atilde;o as doen&ccedil;as exantem&aacute;ticas?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#Etiologia-das-doencas-exantematicas-na-infancia\" >Etiologia das doen&ccedil;as exantem&aacute;ticas na inf&acirc;ncia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#Inscreva-se-em-nossa-newsletter\" >Inscreva-se em nossa newsletter!<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#PROCESSO-SELETIVO-UNIFICADO-%E2%80%93-PSU-MG-2024\" >PROCESSO SELETIVO UNIFICADO &ndash; PSU MG (2024)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#ASSOCIACAO-MEDICA-DO-RIO-GRANDE-DO-SUL-%E2%80%93-AMRIGS-2024\" >ASSOCIA&Ccedil;&Atilde;O M&Eacute;DICA DO RIO GRANDE DO SUL &ndash; AMRIGS (2024)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#SELECAO-UNIFICADA-PARA-RESIDENCIA-MEDICA-DO-ESTADO-DO-CEARA-%E2%80%93-SURCE-2024\" >SELE&Ccedil;&Atilde;O UNIFICADA PARA RESID&Ecirc;NCIA M&Eacute;DICA DO ESTADO DO CEAR&Aacute; &ndash; SURCE (2024)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#CENTRO-UNIVERSITARIO-ATENAS-%E2%80%93-UNIATENAS-2023\" >CENTRO UNIVERSIT&Aacute;RIO ATENAS &ndash; UNIATENAS (2023)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#REVALIDA-INEP-2022\" >REVALIDA INEP (2022)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#Prepare-se-para-as-provas-com-o-Estrategia-MED\" >Prepare-se para as provas com o Estrat&eacute;gia MED<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#Banco-de-Questoes\" >Banco de Quest\u00f5es<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-o-que-sao-as-doencas-exantematicas\"><span class=\"ez-toc-section\" id=\"O-que-sao-as-doencas-exantematicas\"><\/span>O que s&atilde;o as doen&ccedil;as exantem&aacute;ticas?<span class=\"ez-toc-section-end\"><\/span><\/h2><p class=\"wp-block-paragraph\">As doen&ccedil;as exantem&aacute;ticas s&atilde;o quadros comuns da pr&aacute;tica m&eacute;dica, impondo dificuldade diagn&oacute;stica frequente. <strong>O exantema &eacute; uma erup&ccedil;&atilde;o cut&acirc;nea que pode ser composta por maculopapular, papulovesicular ou formada por pet&eacute;quias e p&uacute;rpuras<\/strong>. As les&otilde;es podem apresentar aspecto irregular e edemaciado, estando ou n&atilde;o em&nbsp; associa&ccedil;&atilde;o com prurido, descama&ccedil;&atilde;o, les&otilde;es bolhosas e crostas.&nbsp;<\/p><p class=\"wp-block-paragraph\">As<strong> causas<\/strong> <strong>mais comuns s&atilde;o infecciosas<\/strong>, sendo as infec&ccedil;&otilde;es de etiologia viral as mais relacionadas com a doen&ccedil;a exantem&aacute;tica da inf&acirc;ncia. No entanto, podem ser causadas por bact&eacute;rias, fungos e protozo&aacute;rios, at&eacute; causas n&atilde;o infecciosas, tais como rea&ccedil;&otilde;es medicamentosas, doen&ccedil;as autoimunes e neoplasias.&nbsp;&nbsp;<\/p><h3 class=\"wp-block-heading\" id=\"h-etiologia-das-doencas-exantematicas-na-infancia\"><span class=\"ez-toc-section\" id=\"Etiologia-das-doencas-exantematicas-na-infancia\"><\/span>Etiologia das doen&ccedil;as exantem&aacute;ticas na inf&acirc;ncia<span class=\"ez-toc-section-end\"><\/span><\/h3><p class=\"wp-block-paragraph\">O exantema maculopapular &eacute; a manifesta&ccedil;&atilde;o cut&acirc;nea mais comum nas doen&ccedil;as exantem&aacute;ticas da inf&acirc;ncia e a preval&ecirc;ncia de cada uma varia de acordo com a faixa et&aacute;ria.&nbsp;<\/p><p class=\"wp-block-verse\">Para saber mais sobre as doen&ccedil;as exantem&aacute;ticas, confira o <a href=\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/doencas\/resumo-de-doencas-exantematicas-na-infancia-diagnostico-tratamento-e-mais\/\" target=\"_blank\">resumo de doen&ccedil;as exantem&aacute;ticas na inf&acirc;ncia: diagn&oacute;stico, tratamento e mais<\/a><\/p><p>\n\n\n<div id=\"new-form\">\n\t<form id=\"forms_layout\">\n\t<input type=\"hidden\" id=\"chave_de\" name=\"chave_de\" value=\"01_EMED_LEADS_TOTAIS\" \/>\n\t\t<input type=\"hidden\" id=\"mid\" name=\"mid\" value=\"515009018\" \/>\n\t\t<input type=\"hidden\" id=\"Objetivo\" name=\"Objetivo\" value=\"Medicina\" \/>\n\t\t<input type=\"hidden\" id=\"Estado_de_Origem_do_IP\" name=\"Estado_de_Origem_do_IP\"  value=\"\" \/>\n\t\t<input type=\"hidden\" id=\"Cidade_de_Origem_do_IP\" name=\"Cidade_de_Origem_do_IP\" value=\"\" \/>\n\t\t<input type=\"hidden\" id=\"Modo_de_entrada\" name=\"Modo_de_entrada\" value=\"Portal\" \/>\n\t\t<input type=\"hidden\" id=\"Pagina_Origem\" name=\"Pagina_Origem\" value=\"\" \/>\n\n\t\t<div class=\"texto\">\n\t\t\t<h3 class=\"news\"><span class=\"ez-toc-section\" id=\"Inscreva-se-em-nossa-newsletter\"><\/span>Inscreva-se em nossa newsletter!<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\t\t\t<p>Receba not\u00edcias sobre resid\u00eancia m\u00e9dica, revalida\u00e7\u00e3o de diplomas e concursos m\u00e9dicos, al\u00e9m de materiais de estudo gratuitos e informa\u00e7\u00f5es relevantes do mundo da Medicina.<\/p>\n\t\t<\/div>\n\t\t<div class=\"campos\">\n\t\t\t<div class=\"first_name labels\">\n\t\t\t\t<input type=\"text\" class=\"input_labels\" id=\"first_name\" name=\"Nome_Completo\" placeholder=\"Nome\" required \/>\n\t\t\t<\/div>\n\t\t\t<div class=\"email labels\">\n\t\t\t\t<input type=\"email\" class=\"input_labels\" id=\"email\" name=\"Email\" placeholder=\"E-mail\" required \/>\n\t\t\t<\/div>\n\t\t\t<button type=\"submit\" class=\"button_layout\">\n\t\t\t\t<div id=\"lblBotao\">Inscreva-se<\/div>\n\t\t\t\t<span id=\"divSpiner\" class=\"loader\" role=\"status\" style=\"display: none;\"><\/span>\t\n\t\t\t<\/button>\n\t\t<\/div><!-- \/campos -->\n\t\t\n\t\t<label class=\"container_checkbox\">Voc\u00ea concorda com a nossa\n\t\t\t<a class=\"politics_privacy_ahref\" target=\"_blank\" href=\"https:\/\/gratis.estrategiaconcursos.com.br\/politica-de-privacidade\/\">Pol\u00edtica de Privacidade<\/a> e aceita receber informa\u00e7\u00f5es adicionais do Estrat\u00e9gia Educacional.\n\t\t\t<input id=\"checkbox_layout\" type=\"checkbox\" checked=\"checked\" required \/>\n\t\t\t<span class=\"checkbox\"><\/span>\n\t\t<\/label>\n\t\t<div id=\"msg\"><\/div>\n\t\t<div id=\"error\" class=\"error\">\n\t\t<\/div>\n\t<\/form>\n<\/div><!-- \/new-form -->\n\n\n\n<\/p><h2 class=\"wp-block-heading\" id=\"h-processo-seletivo-unificado-psu-mg-2024\"><span class=\"ez-toc-section\" id=\"PROCESSO-SELETIVO-UNIFICADO-%E2%80%93-PSU-MG-2024\"><\/span>PROCESSO SELETIVO UNIFICADO &ndash; PSU MG (2024)<span class=\"ez-toc-section-end\"><\/span><\/h2><p class=\"wp-block-paragraph\"><strong>Paciente de 7 anos de idade, residente na capital, procura a Unidade B&aacute;sica de Sa&uacute;de com relato de febre, cefal&eacute;ia e dor abdominal h&aacute; cinco dias sem melhora com tratamento. Ao exame f&iacute;sico, voc&ecirc; percebe a presen&ccedil;a de exantema maculopapular em tronco e membros. Assinale a alternativa que descreve UM DADO EPIDEMIOL&Oacute;GICO IMPORTANTE para o esclarecimento diagn&oacute;stico:<\/strong><\/p><p class=\"wp-block-paragraph\">A. A hist&oacute;ria de contato com cavalos nos &uacute;ltimos 30 dias &eacute; importante, pois a febre maculosa ocorre ap&oacute;s esse per&iacute;odo de incuba&ccedil;&atilde;o.<\/p><p class=\"wp-block-paragraph\">B. O hist&oacute;rico vacinal &eacute; importante, pois nessa idade o paciente j&aacute; deve ter recebido tr&ecirc;s doses da vacina contra sarampo, varicela e rub&eacute;ola.<\/p><p class=\"wp-block-paragraph\">C. O m&ecirc;s em que o paciente adoece &eacute; importante, pois, a maioria dos casos de dengue ocorre nos meses de agosto a novembro.<\/p><p class=\"wp-block-paragraph\">D. O uso recente de penicilina ou derivados &eacute; importante, pois o exantema em pacientes com mononucleose &eacute; muito frequente ap&oacute;s o uso desses medicamentos.<\/p><blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Resolu&ccedil;&atilde;o:<\/strong> Estrategista, quest&atilde;o bastante geral cobrada na prova do PSU-MG que nos descreve um paciente de 7 anos com uma s&iacute;ndrome febril bastante inespec&iacute;fica associada &agrave; um exantema maculopapular em tronco, e sobre ela s&atilde;o feitas afirmativas a respeito de dados epidemiol&oacute;gicos que poderiam nos auxiliar no diagn&oacute;stico definitivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alternativa correta D. Apesar de n&atilde;o mencionado outros aspectos cl&iacute;nicos para pensarmos em um quadro de mononucleose (faringite, adenomegalia&hellip;), o uso de penicilina nessas situa&ccedil;&otilde;es pode sim ser causa de exantema semelhante ao descrito na quest&atilde;o.&nbsp;<\/p>\n<\/blockquote><h2 class=\"wp-block-heading\" id=\"h-associacao-medica-do-rio-grande-do-sul-amrigs-2024\"><span class=\"ez-toc-section\" id=\"ASSOCIACAO-MEDICA-DO-RIO-GRANDE-DO-SUL-%E2%80%93-AMRIGS-2024\"><\/span>ASSOCIA&Ccedil;&Atilde;O M&Eacute;DICA DO RIO GRANDE DO SUL &ndash; AMRIGS (2024)<span class=\"ez-toc-section-end\"><\/span><\/h2><p class=\"wp-block-paragraph\"><strong>A insufici&ecirc;ncia respirat&oacute;ria na sepse por Epstein-Barr na inf&acirc;ncia pode se apresentar em decorr&ecirc;ncia de:<\/strong><\/p><p class=\"wp-block-paragraph\">A. Hipoxemia inicial com hipercapnia, secund&aacute;rias especialmente &agrave; obstru&ccedil;&atilde;o extr&iacute;nseca de vias a&eacute;reas por linfadenopatia cervical.<\/p><p class=\"wp-block-paragraph\">B. Hipercapnia sem hipoxemia, pois existe comprometimento parenquimatoso pulmonar, dificultando mais a difus&atilde;o de CO2 do que do O2.<\/p><p class=\"wp-block-paragraph\">C. Hipoxemia isolada sem risco de restri&ccedil;&atilde;o de caixa tor&aacute;cica, j&aacute; que essa situa&ccedil;&atilde;o n&atilde;o cursa com hepatoesplenomegalia.<\/p><p class=\"wp-block-paragraph\">D. Aumento da rela&ccedil;&atilde;o ventila&ccedil;&atilde;o\/perfus&atilde;o por obstru&ccedil;&atilde;o br&ocirc;nquica, fen&ocirc;meno conhecido por efeito espa&ccedil;o-morto.<\/p><blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Resolu&ccedil;&atilde;o:<\/strong> Ol&aacute;, Estrategista. A mononucleose infecciosa (MI) &eacute; causada pelo v&iacute;rus Epstein-Barr (EBV), da fam&iacute;lia Herpesviridae (HHV tipo 4), transmitido por secre&ccedil;&otilde;es orais. O EBV &eacute; um v&iacute;rus sabidamente oncog&ecirc;nico, por esse motivo, relaciona-se ao linfoma de Burkitt e ao carcinoma nasofar&iacute;ngeo, entre outras neoplasias malignas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adolescentes e adultos jovens apresentam mais frequentemente o quadro cl&iacute;nico completo. Os sintomas iniciam-se frequentemente de forma inespec&iacute;fica, com febre baixa, cefaleia leve e mal-estar. Em seguida, geralmente se apresentam seus sinais e sintomas mais cl&aacute;ssicos: amigdalite + linfonodomegalia generalizada (e cervical posterior) + hepatoesplenomegalia. No exame f&iacute;sico, a orofaringe apresenta-se classicamente com hipertrofia e hiperemia de tonsilas palatinas associadas a um exsudato esbranqui&ccedil;ado ou branco acinzentado. Na cavidade oral, podem ser vistas pet&eacute;quias no palato. Tamb&eacute;m podemos ter hepato e\/ou esplenomegalia e um exantema vari&aacute;vel, geralmente maculopapular.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O acometimento pulmonar n&atilde;o &eacute; nada comum, sendo assim, quando h&aacute; um quadro de insufici&ecirc;ncia respirat&oacute;ria associado &agrave; infec&ccedil;&atilde;o por EBV a principal suspeita recai sobre a compress&atilde;o extr&iacute;nseca devido &agrave; linfonodomegalia cervical.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O diagn&oacute;stico da mononucleose pode ser cl&iacute;nico, atrav&eacute;s da associa&ccedil;&atilde;o dos sinais e sintomas descritos acima. Contudo, em casos mais graves ou que necessitem de confirma&ccedil;&atilde;o diagn&oacute;stica, existem exames complementares que podem auxiliar nesse fim. A sorologia (IgM e IgG) para detec&ccedil;&atilde;o dos anticorpos espec&iacute;ficos contra o EBV d&aacute; a certeza diagn&oacute;stica. Testes r&aacute;pidos para a detec&ccedil;&atilde;o de anticorpos heter&oacute;filos e\/ou de anticorpos espec&iacute;ficos para o v&iacute;rus Epstein-Barr tamb&eacute;m s&atilde;o vi&aacute;veis para o diagn&oacute;stico e podem ser utilizados. O hemograma pode trazer leucocitose, &agrave;s custas dos linf&oacute;citos e com mais de 10% de atipias.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alternativa correta A. Esta alternativa sugere a presen&ccedil;a de hipoxemia inicial acompanhada de hipercapnia, destacando a obstru&ccedil;&atilde;o extr&iacute;nseca das vias a&eacute;reas por linfadenopatia cervical como uma causa principal. A linfadenopatia cervical pode comprometer a ventila&ccedil;&atilde;o, levando a uma inicial hipoxemia com posterior reten&ccedil;&atilde;o de CO2.&nbsp;<\/p>\n<\/blockquote><h2 class=\"wp-block-heading\" id=\"h-selecao-unificada-para-residencia-medica-do-estado-do-ceara-surce-2024\"><span class=\"ez-toc-section\" id=\"SELECAO-UNIFICADA-PARA-RESIDENCIA-MEDICA-DO-ESTADO-DO-CEARA-%E2%80%93-SURCE-2024\"><\/span>SELE&Ccedil;&Atilde;O UNIFICADA PARA RESID&Ecirc;NCIA M&Eacute;DICA DO ESTADO DO CEAR&Aacute; &ndash; SURCE (2024)<span class=\"ez-toc-section-end\"><\/span><\/h2><p class=\"wp-block-paragraph\"><strong>Paciente, 2 anos, &eacute; atendido na emerg&ecirc;ncia com quadro de febre (38&deg;C), coriza hialina, tosse e recusa alimentar h&aacute; 3 dias. Ao exame, apresenta orofaringe hiperemiada, com &uacute;lceras no palato mole e lojas amigdalianas. A conduta indicada nesse caso, al&eacute;m da orienta&ccedil;&atilde;o dos pais, consiste na prescri&ccedil;&atilde;o de:<\/strong><\/p><p class=\"wp-block-paragraph\">A. Azitromicina.<\/p><p class=\"wp-block-paragraph\">B. Sintom&aacute;ticos.<\/p><p class=\"wp-block-paragraph\">C. Amoxicilina.<\/p><p class=\"wp-block-paragraph\">D. Aciclovir.<\/p><blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Resolu&ccedil;&atilde;o:<\/strong> O quadro cl&iacute;nico apresentado &eacute; caracter&iacute;stico da herpangina que &eacute; causada por tr&ecirc;s tipos de v&iacute;rus, sendo o mais comum na pr&aacute;tica cl&iacute;nica o v&iacute;rus Coxsackie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contudo, essa infec&ccedil;&atilde;o tamb&eacute;m pode ser desencadeada pelo ecov&iacute;rus e pelos enterov&iacute;rus A71, A68 e A72.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pode apresentar-se em associa&ccedil;&atilde;o &agrave; doen&ccedil;a da m&atilde;o-p&eacute;-boca. Essa apresenta&ccedil;&atilde;o &eacute; causada pelos mesmos v&iacute;rus, mas de cepas diferentes das que causam a faringite de forma isolada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O sintoma mais comum na pr&aacute;tica cl&iacute;nica &eacute; a odinofagia. Nos beb&ecirc;s, a dor na orofaringe pode manifestar-se como choro, irritabilidade e\/ou &ldquo;baba&ccedil;&atilde;o&rdquo;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A febre &eacute; um sintoma muito comum, frequentemente com temperaturas elevadas e dura&ccedil;&atilde;o de aproximadamente tr&ecirc;s dias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao exame f&iacute;sico da orofaringe, s&atilde;o verificadas m&uacute;ltiplas &uacute;lceras razas de 4 a 8 mm nos pilares tonsilares anteriores, palato mole e tonsilas palatinas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essas manifesta&ccedil;&otilde;es apresentam-se de forma s&uacute;bita na maioria dos casos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O diagn&oacute;stico da herpangina pode ser feito clinicamente com base na apar&ecirc;ncia e localiza&ccedil;&atilde;o t&iacute;pica das &uacute;lceras e enantemas, sendo caracterizada por pelo menos 10 les&otilde;es papulovesiculosas hiperemiadas amarelo\/branco-acinzentadas nos pilares anteriores tonsilares, palato mole, am&iacute;gdalas e &uacute;vula. O tratamento deve ser feito utilizando sintom&aacute;ticos e medidas adjuvantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alternativa correta B, o tratamento da herpangina &eacute; de suporte, com sintom&aacute;ticos.<\/p>\n<\/blockquote><h2 class=\"wp-block-heading\" id=\"h-centro-universitario-atenas-uniatenas-2023\"><span class=\"ez-toc-section\" id=\"CENTRO-UNIVERSITARIO-ATENAS-%E2%80%93-UNIATENAS-2023\"><\/span>CENTRO UNIVERSIT&Aacute;RIO ATENAS &ndash; UNIATENAS (2023)<span class=\"ez-toc-section-end\"><\/span><\/h2><p class=\"wp-block-paragraph\"><strong>Paciente pr&eacute;-escolar de tr&ecirc;s anos e 6 meses, &eacute; levado ao pediatra por apresentar febre alta h&aacute; 10 dias. Exame f&iacute;sico: edema palpebral, pet&eacute;quias no palato, exsudato amigdaliano, adenomegalia cervical anterior e posterior, f&iacute;gado palp&aacute;vel a 4 cm do rebordo costal direito. O exame laboratorial indicado para a confirma&ccedil;&atilde;o do diagn&oacute;stico &eacute;:<\/strong><\/p><p class=\"wp-block-paragraph\">A. Aspirado de medula &oacute;ssea.<\/p><p class=\"wp-block-paragraph\">B. Sorologia para v&iacute;rus da dengue.<\/p><p class=\"wp-block-paragraph\">C. Bacterioscopia e cultura da secre&ccedil;&atilde;o far&iacute;ngea.<\/p><p class=\"wp-block-paragraph\">D. Teste r&aacute;pido para pesquisa de estreptococo grupo A.<\/p><p class=\"wp-block-paragraph\">E. Sorologia para v&iacute;rus de Epstein Barr.<\/p><blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Resolu&ccedil;&atilde;o:<\/strong> Ol&aacute;, Estrategista, temos aqui um caso de mononucleose, vamos aprender sobre ela.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A mononucleose &eacute; uma infec&ccedil;&atilde;o extremamente prevalente na popula&ccedil;&atilde;o mundial, sendo estimado que 90% dos adultos s&atilde;o soropositivos para o agente causador, apesar de este apresentar baixo cont&aacute;gio e pouca sobreviv&ecirc;ncia de forma isolada no meio ambiente.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O agente causador &eacute; o v&iacute;rus Epstein-Barr (EBV), da fam&iacute;lia Herpesviridae (HHV tipo 4).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os sintomas iniciam-se frequentemente de forma inespec&iacute;fica, com febre baixa, cefaleia leve e mal-estar. Em seguida, geralmente se apresentam seus sinais e sintomas mais cl&aacute;ssicos: amigdalite + linfonodomegalia generalizada (e cervical posterior) + hepatoesplenomegalia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A febre pode ser alta e prolongada. No exame f&iacute;sico, a orofaringe apresenta-se classicamente com hipertrofia e hiperemia de tonsilas palatinas (am&iacute;gdalas) associadas a um exsudato esbranqui&ccedil;ado ou branco acinzentado. Na cavidade oral, podem ser vistas pet&eacute;quias no palato, em semelhan&ccedil;a &agrave; faringite estreptoc&oacute;cica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Podemos ter tamb&eacute;m um exantema vari&aacute;vel, apresentando-se mais frequentemente como maculopapular. Muito importante para a vida de m&eacute;dico e por isso bastante cobrado em provas &eacute; o conhecimento de que, em caso de uso de antibi&oacute;ticos na mononucleose (o que &eacute; contraindicado), o exantema exacerba-se e torna-se mais frequente.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As complica&ccedil;&otilde;es s&atilde;o raras, mas devemos lembrar que o EBV &eacute; um v&iacute;rus sabidamente oncog&ecirc;nico, relacionado ao linfoma de Burkitt e ao carcinoma nasofar&iacute;ngeo, entre outras neoplasias malignas. A sorologia (IgM e IgG) para detec&ccedil;&atilde;o dos anticorpos espec&iacute;ficos contra o EBV d&aacute; a certeza diagn&oacute;stica. O tratamento &eacute; suportivo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alternativa correta E.<\/p>\n<\/blockquote><h2 class=\"wp-block-heading\" id=\"h-revalida-inep-2022\"><span class=\"ez-toc-section\" id=\"REVALIDA-INEP-2022\"><\/span>REVALIDA INEP (2022)<span class=\"ez-toc-section-end\"><\/span><\/h2><p class=\"wp-block-paragraph\"><strong>Crian&ccedil;a de 5 anos foi levada por familiar para consulta na unidade b&aacute;sica de sa&uacute;de, com quadro de febre n&atilde;o aferida havia 3 dias, odinofagia e recusa alimentar. No exame f&iacute;sico, observou-se presen&ccedil;a de les&otilde;es vesiculares na mucosa bucal e na l&iacute;ngua, al&eacute;m de erup&ccedil;&otilde;es papulovesiculares localizadas em regi&otilde;es palmares e plantares bilateralmente.<\/strong><\/p><p class=\"wp-block-paragraph\"><strong>Considerando-se como principal hip&oacute;tese diagn&oacute;stica a s&iacute;ndrome m&atilde;o-p&eacute;-boca, qual &eacute; a conduta correta?<\/strong><\/p><p class=\"wp-block-paragraph\">A. Orientar isolamento e afastar a crian&ccedil;a da creche por sete dias ou at&eacute; o desaparecimento das les&otilde;es cut&acirc;neas.<\/p><p class=\"wp-block-paragraph\">B. Notificar imediatamente o caso ao servi&ccedil;o de vigil&acirc;ncia epidemiol&oacute;gica e agendar visita &agrave; creche para busca ativa de casos.<\/p><p class=\"wp-block-paragraph\">C. Recomendar isolamento domiciliar por sete dias e instituir tratamento ambulatorial com o antiviral plenaril.<\/p><p class=\"wp-block-paragraph\">D. Encaminhar a crian&ccedil;a para interna&ccedil;&atilde;o hospitalar, para hidrata&ccedil;&atilde;o, se necess&aacute;ria, tratamento sintom&aacute;tico e aplica&ccedil;&atilde;o de imunoglobulina endovenosa.<\/p><blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Resolu&ccedil;&atilde;o:<\/strong> Ol&aacute; coruja, a crian&ccedil;a do enunciado tem diagn&oacute;stico de s&iacute;ndrome m&atilde;o-p&eacute;-boca que &eacute; uma infec&ccedil;&atilde;o viral de transmiss&atilde;o fecal-oral ocasionada pelo Coxsackie A16. &Eacute; uma doen&ccedil;a de diagn&oacute;stico cl&iacute;nico que n&atilde;o requer notifica&ccedil;&atilde;o compuls&oacute;ria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ser contagiosa, &eacute; recomend&aacute;vel que se afaste a crian&ccedil;a de suas atividades habituais at&eacute; o desaparecimento dos sintomas, que &eacute; usualmente de 5 a 7 dias. N&atilde;o h&aacute; vacina, imunoglobulina ou tratamento espec&iacute;fico. O tratamento consiste em medidas gerais e sintom&aacute;ticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alternativa correta A, porque indicou a conduta correta para o&nbsp; caso.<\/p>\n<\/blockquote><h2 class=\"wp-block-heading\" id=\"h-prepare-se-para-as-provas-com-o-estrategia-med\"><span class=\"ez-toc-section\" id=\"Prepare-se-para-as-provas-com-o-Estrategia-MED\"><\/span>Prepare-se para as provas com o Estrat&eacute;gia MED<span class=\"ez-toc-section-end\"><\/span><\/h2><p class=\"wp-block-paragraph\">O estudo pelas resolu&ccedil;&otilde;es de quest&otilde;es &eacute; a grande chave para a aprova&ccedil;&atilde;o e o <a href=\"https:\/\/med.estrategia.com\/portal\/\" target=\"_blank\">Estrat&eacute;gia MED<\/a> n&atilde;o est&aacute; de fora desse m&eacute;todo de aprendizagem. Com o Banco de Quest&otilde;es do Estrat&eacute;gia MED, voc&ecirc; poder&aacute; aproveitar todos os recursos dispon&iacute;veis, incluindo mais de 700 quest&otilde;es sobre doen&ccedil;as exantem&aacute;ticas, al&eacute;m de outras milhares de Pediatria, grande parte j&aacute; com a resolu&ccedil;&atilde;o comentada das alternativas.&nbsp;<\/p><p class=\"wp-block-paragraph\">Vem ser coruja! Clique no banner e saiba mais sobre o Banco de Quest&otilde;es do Estrat&eacute;gia MED!<\/p><p>\n\n\n<div class=\"estrategia-catalog\"><h3><span class=\"ez-toc-section\" id=\"Banco-de-Questoes\"><\/span>Banco de Quest\u00f5es<span class=\"ez-toc-section-end\"><\/span><\/h3><div class=\"carrossel-product\"><div><h4><strong>Banco de Quest\u00f5es + B\u00f4nus Resumos Estrat\u00e9gicos - Anual<\/strong><\/h4><div class=\"cat-description\">Estude com o maior Banco de Quest\u00f5es aut\u00f4nomo da \u00e1rea m\u00e9dica, com mais de 200 mil quest\u00f5es dispon\u00edveis, sendo mais de 108 mil comentadas alternativa por alternativa e mais de 75 mil resolvidas em v\u00eddeo pelos professores especialistas do Estrat\u00e9gia MED.<\/div><div class=\"cat-price\"><span>12x<\/span> R$ 416,41<\/div><div class=\"cat-sale\">No Cart\u00e3o de Cr\u00e9dito ou 10% de desconto no Boleto ou Pix \u00e0 vista: R$ 4.497,30<\/div><br><a href=\"https:\/\/med.estrategia.com\/curso\/banco-de-questes-resumos-estrategicos-anual\/?utm_source=portal&utm_medium=post&utm_campaign=med-x-vd-seo-portal-v-catalogo\" class=\"estrategia-button\" target=\"_blank\">Saiba mais<\/a><\/div><div><h4><strong>Banco de Quest\u00f5es Semestral + Sprint ENAMED \/ ENARE<\/strong><\/h4><div class=\"cat-description\">Estude com o maior Banco de Quest\u00f5es aut\u00f4nomo da \u00e1rea m\u00e9dica, com mais de 200 mil quest\u00f5es dispon\u00edveis, sendo mais de 108 mil comentadas alternativa por alternativa e mais de 75 mil resolvidas em v\u00eddeo pelos professores especialistas do Estrat\u00e9gia MED. A prepara\u00e7\u00e3o definitiva para quem quer acertar o alvo da nova banca do ENARE<\/div><div class=\"cat-price\"><span>12x<\/span> R$ 382,83<\/div><div class=\"cat-sale\">No Cart\u00e3o de Cr\u00e9dito ou 10% de desconto no Boleto ou Pix \u00e0 vista: R$ 4.134,60<\/div><br><a href=\"https:\/\/med.estrategia.com\/curso\/banco-de-questes-semestral-sprint-enamed-enare\/?utm_source=portal&utm_medium=post&utm_campaign=med-x-vd-seo-portal-v-catalogo\" class=\"estrategia-button\" target=\"_blank\">Saiba mais<\/a><\/div><div><h4><strong>Banco de Quest\u00f5es + B\u00f4nus Resumos Estrat\u00e9gicos - Anual + Sprint ENARE\/ENAMED<\/strong><\/h4><div class=\"cat-description\">Estude com o maior Banco de Quest\u00f5es aut\u00f4nomo da \u00e1rea m\u00e9dica, com mais de 200 mil quest\u00f5es dispon\u00edveis, sendo mais de 108 mil comentadas alternativa por alternativa e mais de 75 mil resolvidas em v\u00eddeo pelos professores especialistas do Estrat\u00e9gia MED.<\/div><div class=\"cat-price\"><span>12x<\/span> R$ 555,35<\/div><div class=\"cat-sale\">No Cart\u00e3o de Cr\u00e9dito ou 10% de desconto no Boleto ou Pix \u00e0 vista: R$ 5.997,87<\/div><br><a href=\"https:\/\/med.estrategia.com\/curso\/banco-de-questes-bonus-resumos-estrategicos-anual-sprint-enare-enamed\/?utm_source=portal&utm_medium=post&utm_campaign=med-x-vd-seo-portal-v-catalogo\" class=\"estrategia-button\" target=\"_blank\">Saiba mais<\/a><\/div><\/div><\/div>\n<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"As doen&ccedil;as exantem&aacute;ticas s&atilde;o um tema de grande relev&acirc;ncia entre quest&otilde;es de Infectologia no bloco de Pediatria em&hellip;\n","protected":false},"author":52,"featured_media":64795,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wl_entities_gutenberg":"","footnotes":""},"categories":[33],"tags":[51,40],"wl_entity_type":[199],"class_list":["post-64792","post","type-post","status-publish","format-standard","has-post-thumbnail","category-conteudos-gratis","tag-infectologia","tag-pediatria","wl_entity_type-article"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>5 quest\u00f5es sobre Doen\u00e7as Exantem\u00e1ticas que j\u00e1 ca\u00edram nas provas<\/title>\n<meta name=\"description\" content=\"As doen\u00e7as exantem\u00e1ticas s\u00e3o um tema de grande relev\u00e2ncia entre quest\u00f5es de Infectologia no bloco de Pediatria em provas de resid\u00eancia m\u00e9dica e revalida\u00e7\u00e3o, exigindo que os candidatos tenham uma compreens\u00e3o s\u00f3lida do assunto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 quest\u00f5es sobre Doen\u00e7as Exantem\u00e1ticas que j\u00e1 ca\u00edram nas provas\" \/>\n<meta property=\"og:description\" content=\"As doen\u00e7as exantem\u00e1ticas s\u00e3o um tema de grande relev\u00e2ncia entre quest\u00f5es de Infectologia no bloco de Pediatria em provas de resid\u00eancia m\u00e9dica e revalida\u00e7\u00e3o, exigindo que os candidatos tenham uma compreens\u00e3o s\u00f3lida do assunto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrat\u00e9gia MED\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/estrategiamed1\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-12T12:11:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-12T12:19:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2024\/06\/questoes-doenca-exantematica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1380\" \/>\n\t<meta property=\"og:image:height\" content=\"920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arion Wolff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@estrategiamed_\" \/>\n<meta name=\"twitter:site\" content=\"@estrategiamed_\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arion Wolff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/\",\"url\":\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/\",\"name\":\"5 quest\u00f5es sobre Doen\u00e7as Exantem\u00e1ticas que j\u00e1 ca\u00edram nas provas\",\"isPartOf\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2024\/06\/questoes-doenca-exantematica.jpg\",\"datePublished\":\"2024-06-12T12:11:06+00:00\",\"dateModified\":\"2024-06-12T12:19:02+00:00\",\"author\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/b6aba49604868a427dd15c3b1fc6a8bc\"},\"description\":\"As doen\u00e7as exantem\u00e1ticas s\u00e3o um tema de grande relev\u00e2ncia entre quest\u00f5es de Infectologia no bloco de Pediatria em provas de resid\u00eancia m\u00e9dica e revalida\u00e7\u00e3o, exigindo que os candidatos tenham uma compreens\u00e3o s\u00f3lida do assunto.\",\"breadcrumb\":{\"@id\":\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#primaryimage\",\"url\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2024\/06\/questoes-doenca-exantematica.jpg\",\"contentUrl\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2024\/06\/questoes-doenca-exantematica.jpg\",\"width\":1380,\"height\":920,\"caption\":\"Estrat\u00e9gia Med | Foto: Freepik\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/med.estrategia.com\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conte\u00fados Gr\u00e1tis\",\"item\":\"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"5 quest\u00f5es sobre Doen\u00e7as Exantem\u00e1ticas que j\u00e1 ca\u00edram nas provas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#website\",\"url\":\"https:\/\/med.estrategia.com\/portal\/\",\"name\":\"Estrat\u00e9gia MED\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/med.estrategia.com\/portal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/b6aba49604868a427dd15c3b1fc6a8bc\",\"name\":\"Arion Wolff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2023\/12\/arion-wolff-estrategia-med-150x150.jpg\",\"contentUrl\":\"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2023\/12\/arion-wolff-estrategia-med-150x150.jpg\",\"caption\":\"Arion Wolff\"},\"description\":\"Jornalista formado pela UNIFATEC e p\u00f3s-graduado em Jornalismo Digital pela UNINTER. Escrevo sobre medicina, resid\u00eancia m\u00e9dica e sa\u00fade. Entusiasta de filmes, livros, bons dramas e romances gen\u00e9ricos.\",\"sameAs\":[\"http:\/\/med.estrategia.com\"],\"url\":\"https:\/\/med.estrategia.com\/portal\/author\/arion-santos\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"5 quest\u00f5es sobre Doen\u00e7as Exantem\u00e1ticas que j\u00e1 ca\u00edram nas provas","description":"As doen\u00e7as exantem\u00e1ticas s\u00e3o um tema de grande relev\u00e2ncia entre quest\u00f5es de Infectologia no bloco de Pediatria em provas de resid\u00eancia m\u00e9dica e revalida\u00e7\u00e3o, exigindo que os candidatos tenham uma compreens\u00e3o s\u00f3lida do assunto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/","og_locale":"pt_BR","og_type":"article","og_title":"5 quest\u00f5es sobre Doen\u00e7as Exantem\u00e1ticas que j\u00e1 ca\u00edram nas provas","og_description":"As doen\u00e7as exantem\u00e1ticas s\u00e3o um tema de grande relev\u00e2ncia entre quest\u00f5es de Infectologia no bloco de Pediatria em provas de resid\u00eancia m\u00e9dica e revalida\u00e7\u00e3o, exigindo que os candidatos tenham uma compreens\u00e3o s\u00f3lida do assunto.","og_url":"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/","og_site_name":"Estrat\u00e9gia MED","article_publisher":"https:\/\/www.facebook.com\/estrategiamed1","article_published_time":"2024-06-12T12:11:06+00:00","article_modified_time":"2024-06-12T12:19:02+00:00","og_image":[{"width":1380,"height":920,"url":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2024\/06\/questoes-doenca-exantematica.jpg","type":"image\/jpeg"}],"author":"Arion Wolff","twitter_card":"summary_large_image","twitter_creator":"@estrategiamed_","twitter_site":"@estrategiamed_","twitter_misc":{"Escrito por":"Arion Wolff","Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/","url":"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/","name":"5 quest\u00f5es sobre Doen\u00e7as Exantem\u00e1ticas que j\u00e1 ca\u00edram nas provas","isPartOf":{"@id":"https:\/\/med.estrategia.com\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#primaryimage"},"image":{"@id":"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#primaryimage"},"thumbnailUrl":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2024\/06\/questoes-doenca-exantematica.jpg","datePublished":"2024-06-12T12:11:06+00:00","dateModified":"2024-06-12T12:19:02+00:00","author":{"@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/b6aba49604868a427dd15c3b1fc6a8bc"},"description":"As doen\u00e7as exantem\u00e1ticas s\u00e3o um tema de grande relev\u00e2ncia entre quest\u00f5es de Infectologia no bloco de Pediatria em provas de resid\u00eancia m\u00e9dica e revalida\u00e7\u00e3o, exigindo que os candidatos tenham uma compreens\u00e3o s\u00f3lida do assunto.","breadcrumb":{"@id":"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#primaryimage","url":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2024\/06\/questoes-doenca-exantematica.jpg","contentUrl":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2024\/06\/questoes-doenca-exantematica.jpg","width":1380,"height":920,"caption":"Estrat\u00e9gia Med | Foto: Freepik"},{"@type":"BreadcrumbList","@id":"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/med.estrategia.com\/portal\/"},{"@type":"ListItem","position":2,"name":"Conte\u00fados Gr\u00e1tis","item":"https:\/\/med.estrategia.com\/portal\/conteudos-gratis\/"},{"@type":"ListItem","position":3,"name":"5 quest\u00f5es sobre Doen\u00e7as Exantem\u00e1ticas que j\u00e1 ca\u00edram nas provas"}]},{"@type":"WebSite","@id":"https:\/\/med.estrategia.com\/portal\/#website","url":"https:\/\/med.estrategia.com\/portal\/","name":"Estrat\u00e9gia MED","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/med.estrategia.com\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/b6aba49604868a427dd15c3b1fc6a8bc","name":"Arion Wolff","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/med.estrategia.com\/portal\/#\/schema\/person\/image\/","url":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2023\/12\/arion-wolff-estrategia-med-150x150.jpg","contentUrl":"https:\/\/med.estrategia.com\/portal\/wp-content\/uploads\/2023\/12\/arion-wolff-estrategia-med-150x150.jpg","caption":"Arion Wolff"},"description":"Jornalista formado pela UNIFATEC e p\u00f3s-graduado em Jornalismo Digital pela UNINTER. Escrevo sobre medicina, resid\u00eancia m\u00e9dica e sa\u00fade. Entusiasta de filmes, livros, bons dramas e romances gen\u00e9ricos.","sameAs":["http:\/\/med.estrategia.com"],"url":"https:\/\/med.estrategia.com\/portal\/author\/arion-santos\/"}]}},"_wl_alt_label":[],"wl:entity_url":"\/post\/5-questoes-sobre-doencas-exantematicas-que-ja-cairam-nas-provas","_links":{"self":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/64792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/comments?post=64792"}],"version-history":[{"count":6,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/64792\/revisions"}],"predecessor-version":[{"id":64799,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/posts\/64792\/revisions\/64799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/media\/64795"}],"wp:attachment":[{"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/media?parent=64792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/categories?post=64792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/tags?post=64792"},{"taxonomy":"wl_entity_type","embeddable":true,"href":"https:\/\/med.estrategia.com\/portal\/wp-json\/wp\/v2\/wl_entity_type?post=64792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}